{"id":4360,"date":"2020-03-10T11:15:00","date_gmt":"2020-03-10T11:15:00","guid":{"rendered":"https:\/\/expleo.com\/case-studies\/norwegian-industrial-property-office-2\/"},"modified":"2023-09-21T04:17:36","modified_gmt":"2023-09-21T04:17:36","slug":"fuehrender-industriekonzern","status":"publish","type":"case-studies","link":"https:\/\/expleo.com\/global\/de\/projektbeispiele\/fuehrender-industriekonzern\/","title":{"rendered":"F\u00fchrender Industriekonzern"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4360\" class=\"elementor elementor-4360\" data-elementor-post-type=\"case-studies\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4ad0bcb gg-article-content gg-simple-text gg-container-small-ptb-96 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ad0bcb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fa01d01\" data-id=\"fa01d01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e315c5 gg-font-v5 gg-text-with-paddingbottom gg-custom-dark-purple-color  elementor-widget elementor-widget-heading\" data-id=\"9e315c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Stabilit\u00e4t und Struktur f\u00fcr einen weltweit f\u00fchrenden Automobilhersteller<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1882d3 gg-font-v8 gg-custom-dark-purple-color  elementor-widget elementor-widget-heading\" data-id=\"c1882d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inhalt &amp; Herausforderung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-814da6c gg-font-v9 gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"814da6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der Kunde, ein f\u00fchrender Automobilhersteller, musste innerhalb eines Transformationsprogramm, das seit vielen Jahren eine strategische Schl\u00fcsselrolle einnimmt, eine Grundlage f\u00fcr mehr Transparenz, Einblick und Kontrolle entwickeln.<\/p><p>Vor der Beteiligung von Expleo lief das Programm ohne ein Projektmanagement-Office (PMO), was die Kontrolle von Komplexit\u00e4t und Umfang erschwerte. Dieser Mangel an Steuerung hatte zur Folge, dass beteiligte Teams ineffizient und ineffektiv arbeiteten \u2013 oftmals isoliert in \u201eSilos\u201c.<\/p><p>Der Investitionsumfang und die Zukunftspl\u00e4ne des Kunden f\u00fcr seine Fertigungssoftware machten eine Stabilisierung durch ein PMO dringend erforderlich. Der Kunde hatte dies erkannt und sah die Notwendigkeit externer Unterst\u00fctzung, um das erforderliche Ma\u00df an Engagement und<br \/>Management f\u00fcr eine erfolgreiche Umsetzung zu gew\u00e4hrleisten.<\/p><p>So wurde die Einbindung eines externen Partners erforderlich, um diesen \u00dcbergang zu einer wesentlich strukturierteren Arbeitsweise zu erleichtern.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3785e3d gg-font-v8 gg-custom-dark-purple-color  elementor-widget elementor-widget-heading\" data-id=\"3785e3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qualit\u00e4t ist der Schl\u00fcssel<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60bf904 gg-font-v9 gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"60bf904\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Qualit\u00e4t ist ein wesentlicher Faktor f\u00fcr den Schutz jeder Investition und war in diesem Fall f\u00fcr den Kunden von ma\u00dfgeblicher Bedeutung.<\/p><p>Der Kunde ben\u00f6tigte durchgehende Qualit\u00e4tsstandards, die in allen Facetten der Programmdurchf\u00fchrung pr\u00e4sent sind. Die Implementierung und der Betrieb der PMO-Funktionen waren entscheidend, um die Komplexit\u00e4t des Projekts beherrschbar zu halten. Dazu geh\u00f6rte fachliches Coaching und Anleitung f\u00fcr die Direktions- und alle darunterliegenden Ebenen der am<br \/>Programm beteiligten Teams. Dies beinhaltete auch die Unterst\u00fctzung der F\u00fchrungskr\u00e4fte des Kunden bei der Einf\u00fchrung einer Programm-Charta. Diese bestand aus Schl\u00fcsselkomponenten wie einer klaren Roadmap, logischen Strukturen und Prozessen, einer ausf\u00fchrlichen Dokumentation und Best Practices zur \u00dcbernahme von Verantwortung, um die Durchf\u00fchrung k\u00fcnftiger Programme auf Kurs zu halten.<\/p><p>Ein weiterer Vorteil, den Expleo der Programmleitung durch die erfolgreiche Einf\u00fchrung des neuen PMO bot, war die Erstellung detaillierter Berichte zur Vorlage beim Vorstand. Dies erm\u00f6glicht nun die laufende \u00dcberpr\u00fcfung und Freigabe von zus\u00e4tzlichen finanziellen Mitteln oder neuen Technologien.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a7055ad gg-simple-cta-purple-section gg-container-small-ptb-96 gg-simple-text elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a7055ad\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-62d66ce\" data-id=\"62d66ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b706bd gg-custom-white-color  gg-font-v8 elementor-widget elementor-widget-heading\" data-id=\"2b706bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nutzen f\u00fcr den Kunden<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d71ef64 gg-custom-white-color gg-font-v9 gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"d71ef64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Expleo konnte einen fortschrittlichen, klaren und umfassenden Ansatz f\u00fcr den Aufbau eines PMO in der Organisation des Kunden einbringen.<\/p><p>Mit Fokus auf die F\u00fchrungsebene wurden Richtung und Form der langfristigen Strategie festgelegt, wobei die Risiken f\u00fcr den kontinuierlichen Betrieb des PMO minimiert und gleichzeitig dessen Potenzial maximiert wurden.<\/p><p>Expleo \u00fcbernahm \u00fcberall dort Verantwortung, wo es zuvor keine klaren Zust\u00e4ndigkeiten gegeben hatte und unterstellte alle Rollen und Verantwortlichkeiten des Transformationsprogramms einer dringend ben\u00f6tigten Projektsteuerung.<\/p><p>Expleo brachte au\u00dferdem das Know-how seiner Businessanalysten in das Projekt ein, um die klare Definition und Konsistenz der Anforderungen an die L\u00f6sung sicherzustellen, sowie um die<br \/>Bed\u00fcrfnisse der Business-Seite bei der Umsetzung des Programms zu ber\u00fccksichtigen.<\/p><p>Die F\u00e4higkeiten des Expleo-Teams kamen durch die Struktur und Qualit\u00e4t, die im Rahmen des Aufbaus und Betriebs des PMO entwickelt wurden, optimal zum Einsatz. Dies brachte mehr Transparenz, Einblick und Kontrolle in das Programm.<\/p><p>Expleo konnte dar\u00fcber hinaus breites Wissen und weitreichende Expertise im Zusammenhang mit digitalen Transformationsprozessen bereitstellen und so die bestehenden Kenntnisse des Kunden in diesem Bereich erg\u00e4nzen.<\/p><p>Damit wurde ein Fokus auf Qualit\u00e4t in das Programm eingebracht, wodurch Entwicklungsverfahren und Leistungen von Zulieferern hinterfragt und folglich die Gesamtqualit\u00e4t der zu entwickelnden Softwareanwendung verbessert werden konnte.<\/p><p>Der Kunde hat sein digitales Transformationsprogramm auf ein besser fokussiertes System mit einem gut funktionierenden PMO umgestellt, das zuk\u00fcnftig die Leitung \u00fcbernehmen und sich auf Management und Kontrolle konzentrieren kann.<\/p><p>Im Laufe des sechsmonatigen Projekts hat Expleo das Fundament geliefert und die Richtung vorgegeben, so dass der Kunde erfolgreich die n\u00e4chste Entwicklungsphase beginnen und planm\u00e4\u00dfig neue Produkte mithilfe des neuen Systems liefern kann.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-381b6bc gg-simple-cta-section-grey gg-container-small-ptb-96 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"381b6bc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a05d13\" data-id=\"3a05d13\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be66c37 elementor-widget elementor-widget-gravity-advanced-cta\" data-id=\"be66c37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"gravity-advanced-cta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"gg-advanced-cta\">\r\n            \r\n        <p class=\"gg-advanced-cta__heading gg-tagline-heading-left\">\r\n        <strong>        TRANSFORMATIONSBERATUNG        <\/strong>        <\/p>\r\n        \r\n        <h2 class=\"gg-advanced-cta__subheading gg-font-v2\">\r\n                <span>Project Management Office<\/span>                <\/h2>\r\n                <div class=\"gg-advanced-cta__description gg-font-v9\">\r\n            <span><p>Die verschiedenen Project Management Offices (PMO) von Expleo steuern und erleichtern die Konzeption und Durchf\u00fchrung von Prozessen entlang der gesamten Wertsch\u00f6pfungskette \u2013 vom Design bis zum Kundensupport.<\/p><\/span>        <\/div>\r\n        \r\n        <div class=\"gg-advanced-cta__button-first gg-advanced-cta__button gg-button-v3\">\r\n            <a href=\"https:\/\/expleo.com\/global\/de\/services\/transformation-consultancy\/\">\r\n                Mehr anzeigen            <\/a>\r\n        <\/div>\r\n\r\n                <\/div>\r\n\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Stabilit\u00e4t und Struktur f\u00fcr einen weltweit f\u00fchrenden Automobilhersteller Inhalt &#038; Herausforderung Der Kunde, ein f\u00fchrender Automobilhersteller, musste innerhalb eines Transformationsprogramm, das seit vielen Jahren eine strategische Schl\u00fcsselrolle einnimmt, eine Grundlage f\u00fcr mehr Transparenz, Einblick und Kontrolle entwickeln. Vor der Beteiligung von Expleo lief das Programm ohne ein Projektmanagement-Office (PMO), was die Kontrolle von Komplexit\u00e4t und [&hellip;]<\/p>\n","protected":false},"featured_media":1265,"template":"","meta":{"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","service-grey-banner":"false","service-grey-banner-link":"","footnotes":""},"case-study-single-templates":[],"topic":[121],"industry-taxonomy":[24,36],"country":[113],"service":[60,238],"class_list":["post-4360","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","topic-industrie-4-0","industry-taxonomy-automotive","industry-taxonomy-manufacturing-and-construction","country-global","service-enterprise-transformation","service-transformation-consultancy"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Expleo | F\u00fchrender Industriekonzern<\/title>\n<meta name=\"description\" content=\"Projektbeispiel: Stabilisierung und Strukturierung des Transformationsprogramms eines weltweit f\u00fchrenden Automobilherstellers.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expleo.com\/global\/de\/projektbeispiele\/fuehrender-industriekonzern\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00fchrender Industriekonzern\" \/>\n<meta property=\"og:description\" content=\"Projektbeispiel: Stabilisierung und Strukturierung des Transformationsprogramms eines weltweit f\u00fchrenden Automobilherstellers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expleo.com\/global\/de\/projektbeispiele\/fuehrender-industriekonzern\/\" \/>\n<meta property=\"og:site_name\" content=\"Global DE\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-21T04:17:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2020\/06\/meeting-inpage-1280x720-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/projektbeispiele\\\/fuehrender-industriekonzern\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/projektbeispiele\\\/fuehrender-industriekonzern\\\/\",\"name\":\"Expleo | F\u00fchrender Industriekonzern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/projektbeispiele\\\/fuehrender-industriekonzern\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/projektbeispiele\\\/fuehrender-industriekonzern\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/meeting-inpage-1280x720-1.jpg\",\"datePublished\":\"2020-03-10T11:15:00+00:00\",\"dateModified\":\"2023-09-21T04:17:36+00:00\",\"description\":\"Projektbeispiel: Stabilisierung und Strukturierung des Transformationsprogramms eines weltweit f\u00fchrenden Automobilherstellers.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/projektbeispiele\\\/fuehrender-industriekonzern\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/projektbeispiele\\\/fuehrender-industriekonzern\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/projektbeispiele\\\/fuehrender-industriekonzern\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/meeting-inpage-1280x720-1.jpg\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/meeting-inpage-1280x720-1.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Business meeting\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/projektbeispiele\\\/fuehrender-industriekonzern\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projektbeispiele\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/projektbeispiele\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"F\u00fchrender Industriekonzern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\",\"name\":\"Expleo | DE\",\"description\":\"Expleo\",\"publisher\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#organization\",\"name\":\"Expleo | DE\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"width\":1600,\"height\":774,\"caption\":\"Expleo | DE\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Expleo | F\u00fchrender Industriekonzern","description":"Projektbeispiel: Stabilisierung und Strukturierung des Transformationsprogramms eines weltweit f\u00fchrenden Automobilherstellers.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expleo.com\/global\/de\/projektbeispiele\/fuehrender-industriekonzern\/","og_locale":"de_DE","og_type":"article","og_title":"F\u00fchrender Industriekonzern","og_description":"Projektbeispiel: Stabilisierung und Strukturierung des Transformationsprogramms eines weltweit f\u00fchrenden Automobilherstellers.","og_url":"https:\/\/expleo.com\/global\/de\/projektbeispiele\/fuehrender-industriekonzern\/","og_site_name":"Global DE","article_modified_time":"2023-09-21T04:17:36+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2020\/06\/meeting-inpage-1280x720-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/expleo.com\/global\/de\/projektbeispiele\/fuehrender-industriekonzern\/","url":"https:\/\/expleo.com\/global\/de\/projektbeispiele\/fuehrender-industriekonzern\/","name":"Expleo | F\u00fchrender Industriekonzern","isPartOf":{"@id":"https:\/\/expleo.com\/global\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expleo.com\/global\/de\/projektbeispiele\/fuehrender-industriekonzern\/#primaryimage"},"image":{"@id":"https:\/\/expleo.com\/global\/de\/projektbeispiele\/fuehrender-industriekonzern\/#primaryimage"},"thumbnailUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2020\/06\/meeting-inpage-1280x720-1.jpg","datePublished":"2020-03-10T11:15:00+00:00","dateModified":"2023-09-21T04:17:36+00:00","description":"Projektbeispiel: Stabilisierung und Strukturierung des Transformationsprogramms eines weltweit f\u00fchrenden Automobilherstellers.","breadcrumb":{"@id":"https:\/\/expleo.com\/global\/de\/projektbeispiele\/fuehrender-industriekonzern\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expleo.com\/global\/de\/projektbeispiele\/fuehrender-industriekonzern\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/expleo.com\/global\/de\/projektbeispiele\/fuehrender-industriekonzern\/#primaryimage","url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2020\/06\/meeting-inpage-1280x720-1.jpg","contentUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2020\/06\/meeting-inpage-1280x720-1.jpg","width":1280,"height":720,"caption":"Business meeting"},{"@type":"BreadcrumbList","@id":"https:\/\/expleo.com\/global\/de\/projektbeispiele\/fuehrender-industriekonzern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expleo.com\/global\/de\/"},{"@type":"ListItem","position":2,"name":"Projektbeispiele","item":"https:\/\/expleo.com\/global\/de\/projektbeispiele\/"},{"@type":"ListItem","position":3,"name":"F\u00fchrender Industriekonzern"}]},{"@type":"WebSite","@id":"https:\/\/expleo.com\/global\/de\/#website","url":"https:\/\/expleo.com\/global\/de\/","name":"Expleo | DE","description":"Expleo","publisher":{"@id":"https:\/\/expleo.com\/global\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expleo.com\/global\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/expleo.com\/global\/de\/#organization","name":"Expleo | DE","url":"https:\/\/expleo.com\/global\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/expleo.com\/global\/de\/#\/schema\/logo\/image\/","url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","contentUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","width":1600,"height":774,"caption":"Expleo | DE"},"image":{"@id":"https:\/\/expleo.com\/global\/de\/#\/schema\/logo\/image\/"}}]}},"hreflang":{"rendered":"<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/projektbeispiele\/leading-manufacturing-organisation\/\" hreflang=\"x-default\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/projektbeispiele\/leading-manufacturing-organisation\/\" hreflang=\"en\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/de\/projektbeispiele\/fuehrender-industriekonzern\/\" hreflang=\"de\"\/>\n","structure":[{"blogId":4,"blogIsHidden":false,"postId":7357,"url":"https:\/\/expleo.com\/global\/en\/projektbeispiele\/leading-manufacturing-organisation\/","language":"en","default":true},{"blogId":6,"blogIsHidden":false,"postId":4360,"url":"https:\/\/expleo.com\/global\/de\/projektbeispiele\/fuehrender-industriekonzern\/","language":"de","default":false}]},"_links":{"self":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/case-studies\/4360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/types\/case-studies"}],"version-history":[{"count":0,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/case-studies\/4360\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/media\/1265"}],"wp:attachment":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/media?parent=4360"}],"wp:term":[{"taxonomy":"case-study-single-templates","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/case-study-single-templates?post=4360"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/topic?post=4360"},{"taxonomy":"industry-taxonomy","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/industry-taxonomy?post=4360"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/country?post=4360"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/service?post=4360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}