{"id":1178,"date":"2018-07-23T10:59:00","date_gmt":"2018-07-23T10:59:00","guid":{"rendered":"https:\/\/expleo.com\/global\/en\/?post_type=insight&#038;p=1547"},"modified":"2024-02-14T16:55:13","modified_gmt":"2024-02-14T16:55:13","slug":"unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner","status":"publish","type":"insights","link":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\/","title":{"rendered":"Unternehmerisch handeln: Maximieren Sie die Wirkung Ihrer Product Owner"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1178\" class=\"elementor elementor-1178\" data-elementor-post-type=\"insights\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f934ada gg-article-content  gg-standard-article-template gg-simple-text gg-container-small-ptb-72 gg-print-ptb-null elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f934ada\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b5ec139 gg-tablet-view\" data-id=\"b5ec139\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b37c26 gg-display-none-print elementor-widget elementor-widget-image\" data-id=\"7b37c26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/becoming-entrpreneurial-1-768x432.jpg\" class=\"attachment-medium_large size-medium_large wp-image-1129\" alt=\"Man analyzes data on computer\" srcset=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/becoming-entrpreneurial-1-768x432.jpg 768w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/becoming-entrpreneurial-1-300x169.jpg 300w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/becoming-entrpreneurial-1-1024x576.jpg 1024w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/becoming-entrpreneurial-1-1536x864.jpg 1536w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/becoming-entrpreneurial-1.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8465065 gg-font-v9 gg-text-with-paddingbottom gg-class-for-iphone8  elementor-widget elementor-widget-text-editor\" data-id=\"8465065\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In agilen Firmenstrukturen ist der Product Owner die Person, die f\u00fcr die Wertsteigerung verantwortlich ist, z.B. durch Priorisierung der Entwicklungsarbeit, Einbeziehung von Interessengruppen und Lernen vom Markt und den Kunden. Product Owner formulieren eine klare Vision, die die Produktentwicklung anleitet, wichtige Stakeholder einbezieht, die M\u00f6glichkeiten neuer Technologien nutzt und Funktionen entwickelt, um neue Zielgruppen anzusprechen. Im Idealfall agieren Product Owner als Unternehmer innerhalb ihrer Organisation und haben das Mandat, schwierige Entscheidungen zu treffen. Die Realit\u00e4t agiler Praktiken zeigt jedoch, dass Unternehmen ihre Product Owner auch daran hindern k\u00f6nnen, auf eine solch unternehmerische Weise zu handeln.<\/p>\n<p>Die Auseinandersetzung mit dem Kontext gr\u00f6\u00dferer Organisationen ist entscheidend, um die Rolle des Product Owner optimal zu nutzen, und unerl\u00e4sslich f\u00fcr den Weg in Richtung Flexibilit\u00e4t.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6b74c6 gg-font-v4 elementor-widget elementor-widget-heading\" data-id=\"c6b74c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Product Owner-Szenarien<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-692f284 gg-font-v9 gg-text-with-paddingbottom gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"692f284\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDie folgenden f\u00fcnf typischen Szenarien stehen dem unternehmerischen Handeln eines Product Owner oft im Weg:\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e316de9 gg-font-v4 elementor-widget elementor-widget-heading\" data-id=\"e316de9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1. Tod durch Hierarchie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88e2640 gg-font-v9 gg-text-with-paddingbottom gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"88e2640\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Firmen zeichnen sich gemeinhin durch eine strikte Trennung verschiedener Abteilungen aus. \u201eVertrieb\u201c und \u201eIT\u201c zum Beispiel kommunizieren und arbeiten meist nicht effizient zusammen. Eine Transformation zu einem neuen Gesch\u00e4ftsmodell und\/oder einem agilen Framework kann \u201evon oben\u201c durchgesetzt werden, dann aber manchmal zum Leidwesen aller Beteiligten. Product Owner sind dabei oft nicht die, die das Sagen haben, sondern sind stets in Gefahr, immer vermitteln zu m\u00fcssen: Sie unterstehen b\u00fcrokratischen Zw\u00e4ngen und Prozessen und stellen oft nur eine weitere Ebene in der Kommunikation zwischen verschiedenen Mitarbeitern und Abteilungen dar.<\/p>\n<p>In solchen F\u00e4llen ist es ratsam, die Kommunikation zwischen den Mitarbeitern auf eine Weise zu verbessern, die Verantwortung und Fachkenntnisse f\u00f6rdert. Product Owner m\u00fcssen sich darum bem\u00fchen, mehr Kompetenzen zu erhalten, um unabh\u00e4ngiger handeln und b\u00fcrokratische Hindernisse umgehen zu k\u00f6nnen. In Zusammenarbeit mit einem zust\u00e4ndigen Scrum Master kann ein unternehmerisch handelnder Product Owner dem \u201eTod durch Hierarchie\u201c entgehen, indem er \u00c4nderungen auf kleinerem Niveau vornimmt, was ihm zun\u00e4chst mehr Entscheidungsbefugnis und schlie\u00dflich eine gr\u00f6\u00dfere Wertsch\u00e4tzung f\u00fcr agilere Arbeitsweisen einbringt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59a2686 gg-font-v4 elementor-widget elementor-widget-heading\" data-id=\"59a2686\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">2. Stillstand<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbf52cd gg-font-v9 gg-text-with-paddingbottom gg-class-for-iphone8 gg-print-pb-3 elementor-widget elementor-widget-text-editor\" data-id=\"bbf52cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ein Unternehmen k\u00e4mpft darum, erfolgreich zu sein. Die Ums\u00e4tze sind vielleicht niedrig und die Wettbewerber auf dem Vormarsch. Es gibt endlose Diskussionen dar\u00fcber, was als n\u00e4chstes zu tun ist, aber irgendeiner der Beteiligten ist immer dagegen. Ressourcen, die f\u00fcr eine gr\u00f6\u00dftm\u00f6gliche Wirkung geb\u00fcndelt werden sollten, sind fragmentiert, was die F\u00e4higkeit des Unternehmens, irgendetwas zu erreichen, beeintr\u00e4chtigt.<\/p><p>Unternehmerisch auftretende Product Owner k\u00f6nnen den Lernprozess des Marktes und potenzieller Kunden optimieren, indem sie beispielsweise ein MVP (Minimum Viable Product) entwickeln und das Feedback der Zielgruppen daf\u00fcr einholen. Das MVP erm\u00f6glicht es, Feedback aus dem Markt in die Produktentwicklung einzubeziehen, wobei der Product Owner als wichtiger Botschafter f\u00fcr die Einbeziehung der Interessengruppen fungiert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f061522 gg-font-v4 gg-print-little-heading gg-print-little-heading gg-print-v2-pb-2 elementor-widget elementor-widget-heading\" data-id=\"f061522\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">3. L\u00e4hmung des Gesch\u00e4ftsmodells<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a629119 gg-display-none-print elementor-widget elementor-widget-image\" data-id=\"a629119\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/becoming-entrpreneurial-2-768x432.jpg\" class=\"attachment-medium_large size-medium_large wp-image-1130\" alt=\"Team meeting at the office\" srcset=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/becoming-entrpreneurial-2-768x432.jpg 768w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/becoming-entrpreneurial-2-300x169.jpg 300w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/becoming-entrpreneurial-2-1024x576.jpg 1024w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/becoming-entrpreneurial-2-1536x864.jpg 1536w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/becoming-entrpreneurial-2.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5495f1 gg-font-v9 gg-text-with-paddingbottom gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"c5495f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ein Unternehmen kann vom Markt und aus internen Diskussionen lernen, nutzt dies jedoch nicht zu seinem Vorteil, z. B. indem es sein Gesch\u00e4ftsmodell ernsthaft \u00fcberdenkt und dann einen neuen Ansatz verfolgt. Bestimmte Interessen, langfristige Vertr\u00e4ge oder einfach die Angst vor Ver\u00e4nderung k\u00f6nnen ernsthafte \u00c4nderungen ehemals erfolgreicher Gesch\u00e4ftsmodelle durchaus verhindern. Erst bei n\u00e4herer Betrachtung wird man sehen, dass die bisherigen Grundlagen bestehender Gesch\u00e4ftsmodelle langsam zerbr\u00f6ckeln.<\/p>\n<p>Product Owner sollten in der Lage sein, solche St\u00f6rungen zu beseitigen, indem sie Ideen einfach ausprobieren, blinde Flecken im Unternehmen aufsp\u00fcren und den Wert der Arbeit von Teams innerhalb des Unternehmens auch einmal in Frage stellen. Um Stagnation im Unternehmen zu \u00fcberwinden, ist es erforderlich, dass Product Owner mit verschiedenen internen und externen Stakeholdern zusammenarbeiten. Es sollte die Bereitschaft zur \u00dcberpr\u00fcfung und Kalibrierung der Gesch\u00e4ftsmodelle bestehen \u2013 durch Marktforschung, das Erstellen eines MVP, die Einbeziehung und das Management von Stakeholdern usw.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e7d38d gg-font-v4 gg-print-little-heading elementor-widget elementor-widget-heading\" data-id=\"5e7d38d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">4. Gr\u00fcn hinter den Ohren<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4ef4e5 gg-font-v9 gg-text-with-paddingbottom gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"a4ef4e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Agile Strukturen sind f\u00fcr ein Unternehmen vielleicht noch relativ neu \u2013 und anfangs muss jeder Mitarbeiter davon \u00fcberzeugt werden, wie wichtig Flexibilit\u00e4t und Agilit\u00e4t sind. So kann es vorkommen, dass einige Mitarbeiter Agilit\u00e4t als IT-Angelegenheit ansehen, bei der es in erster Linie um die H\u00e4ufigkeit und Flexibilit\u00e4t von Releases geht, um die Kunden zufrieden zu stellen. So mag es den Anschein haben, dass Agilit\u00e4t nicht jeden betrifft und man meint, die meisten Abteilungen k\u00f6nnen einfach so weitermachen und auf ihren ausgetretenen Pfaden ewig weitergehen.<\/p>\n<p>Das Thema Agilit\u00e4t fordert das gesamte Unternehmen und nie nur eine einzelne Abteilung wie z. B. die IT. Aufgabe der Product Owner ist es, die Grenzen zwischen Abteilungen und Fachgebieten zu \u00fcberwinden, um das operative Business wirklich mit der IT zu verkn\u00fcpfen. Durch die strategische Abstimmung von Projekt- und Programm-Management auf die produktorientierte Denkweise von agilen Frameworks kann die Einbindung von Projekt-, Produkt- und Programm-Managern sichergestellt werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25f53fa gg-font-v4 gg-print-little-heading gg-print-little-heading elementor-widget elementor-widget-heading\" data-id=\"25f53fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">5. Gier ist gut<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a78b2a gg-font-v9 gg-text-with-paddingbottom gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"2a78b2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Product Owner sind m\u00f6glicherweise vor allem daran interessiert, ihre eigenen, pers\u00f6nlichen Interessen zu verfolgen \u2013 frei nach dem Motto \u201eGier ist gut\u201c. Dadurch wird ein Unternehmen aber vom Product Owner in eine verletzbare Position gebracht, weil das Verfolgen ausschlie\u00dflich pers\u00f6nlicher Interessen die Wertsch\u00f6pfung beeintr\u00e4chtigen kann. Auch die Transformation zu agilen Strukturen kann innerhalb des Unternehmens negativ beeinflusst werden.<\/p><p>Wirklich als Unternehmer zu handeln, bedeutet auch, nach au\u00dfen hin offen zu sein, und entsprechend zu reagieren. Das Verfolgen pers\u00f6nlicher Interessen, die nicht mit denen der Firma \u00fcbereinstimmen, l\u00e4uft eher auf ein Pl\u00fcndern der Unternehmens-Assets hinaus.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ef2a2a gg-font-v4 elementor-widget elementor-widget-heading\" data-id=\"7ef2a2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Zusammenfassung: Best Practices<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e02b7a gg-font-v9 gg-class-for-iphone8  elementor-widget elementor-widget-text-editor\" data-id=\"4e02b7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der Weg zu mehr Agilit\u00e4t kann steinig sein. Wir empfehlen die folgenden Best Practices in Bezug auf Product Ownership, um Unternehmen zu helfen, reaktionsschnell und erfolgreich zu sein:<\/p>\n<ul>\n<li>Vermeiden Sie Fehlbesetzungen: Wenn die Transformation zu einer agilen Struktur nicht mit Sorgfalt durchgef\u00fchrt wird, erf\u00fcllen diejenigen, die eine neue Rolle bekleiden sollen (z. B. die des Product Owner), m\u00f6glicherweise nicht die erforderlichen beruflichen und pers\u00f6nlichen Voraussetzungen.<\/li>\n<li>Beauftragen Sie einen externen Product Owner: Unternehmen, die die Merkmale der Szenarien 1 (\u201eTod durch Hierarchie\u201c) und 4 (\u201eGr\u00fcn hinter den Ohren\u201c) aufweisen, k\u00f6nnen von einem externen Product Owner profitieren. Er oder sie kann dazu beitragen, die Transformation zur Agilit\u00e4t zu erleichtern, indem er als relativ unabh\u00e4ngiger Moderator den Konsens herstellt und andere Product Owner innerhalb des Unternehmens ausbildet.<\/li>\n<li>Formulieren Sie eine glasklare Produktvision und seien Sie bereit, die Realisierbarkeit rigoros zu testen, zum Beispiel mit Hilfe eines MVP.<\/li>\n<li>Bilden Sie interdisziplin\u00e4re, flexible, kreative und leistungsstarke Teams, die etwas bewegen k\u00f6nnen.<\/li>\n<li>Finden Sie heraus, welche Interessensgruppen Entscheidungsbefugnis haben und binden Sie sie mit Techniken ein, die den Dialog f\u00f6rdern. Damit erweitert sich der Einflussbereich des Product Owner.<\/li>\n<li>Erstellen Sie Produkt-Backlog-Items und Sprint-Ziele mit Hilfe von Input aus allen Ebenen des Unternehmens.<\/li>\n<li>Erm\u00f6glichen Sie die Zusammenarbeit zwischen Scrum Teams und internen\/externen Stakeholdern und erhalten Sie diese dauerhaft aufrecht.<\/li>\n<li>Scheitern Sie erneut, aber scheitern Sie besser: Akzeptieren Sie die Tatsache, dass ein fr\u00fchzeitiges Release oft der Weg zum Erfolg ist, auch wenn dies manchmal schmerzhaft sein kann.<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>In agilen Firmenstrukturen ist der Product Owner die Person, die f\u00fcr die Wertsteigerung verantwortlich ist, z.B. durch Priorisierung der Entwicklungsarbeit, Einbeziehung von Interessengruppen und Lernen vom Markt und den Kunden.<\/p>\n","protected":false},"featured_media":1129,"parent":0,"template":"","meta":{"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","footnotes":""},"topic":[122,119],"insights-single-templates":[386],"industry-taxonomy":[293],"content-type":[21],"country":[89],"service":[],"class_list":["post-1178","insights","type-insights","status-publish","has-post-thumbnail","hentry","topic-business-transformation","topic-qualitaetssicherung-und-entwicklung","insights-single-templates-old-template","industry-taxonomy-all","content-type-blog","country-irland"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Expleo | Unternehmerisch handeln<\/title>\n<meta name=\"description\" content=\"Der Product Owner die Person, die f\u00fcr die Wertsteigerung verantwortlich ist, Einbeziehung von Interessengruppen und den Kunden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unternehmerisch handeln: Maximieren Sie die Wirkung Ihrer Product Owner\" \/>\n<meta property=\"og:description\" content=\"Der Product Owner die Person, die f\u00fcr die Wertsteigerung verantwortlich ist, Einbeziehung von Interessengruppen und den Kunden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\/\" \/>\n<meta property=\"og:site_name\" content=\"Global DE\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-14T16:55:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/becoming-entrpreneurial-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/blog\\\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/blog\\\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\\\/\",\"name\":\"Expleo | Unternehmerisch handeln\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/blog\\\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/blog\\\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/becoming-entrpreneurial-1.jpg\",\"datePublished\":\"2018-07-23T10:59:00+00:00\",\"dateModified\":\"2024-02-14T16:55:13+00:00\",\"description\":\"Der Product Owner die Person, die f\u00fcr die Wertsteigerung verantwortlich ist, Einbeziehung von Interessengruppen und den Kunden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/blog\\\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/blog\\\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/blog\\\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/becoming-entrpreneurial-1.jpg\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/becoming-entrpreneurial-1.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Man analyzes data on computer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/blog\\\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einblicke\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Unternehmerisch handeln: Maximieren Sie die Wirkung Ihrer Product Owner\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\",\"name\":\"Expleo | DE\",\"description\":\"Expleo\",\"publisher\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#organization\",\"name\":\"Expleo | DE\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"width\":1600,\"height\":774,\"caption\":\"Expleo | DE\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Expleo | Unternehmerisch handeln","description":"Der Product Owner die Person, die f\u00fcr die Wertsteigerung verantwortlich ist, Einbeziehung von Interessengruppen und den Kunden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\/","og_locale":"de_DE","og_type":"article","og_title":"Unternehmerisch handeln: Maximieren Sie die Wirkung Ihrer Product Owner","og_description":"Der Product Owner die Person, die f\u00fcr die Wertsteigerung verantwortlich ist, Einbeziehung von Interessengruppen und den Kunden.","og_url":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\/","og_site_name":"Global DE","article_modified_time":"2024-02-14T16:55:13+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/becoming-entrpreneurial-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\/","url":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\/","name":"Expleo | Unternehmerisch handeln","isPartOf":{"@id":"https:\/\/expleo.com\/global\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\/#primaryimage"},"image":{"@id":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\/#primaryimage"},"thumbnailUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/becoming-entrpreneurial-1.jpg","datePublished":"2018-07-23T10:59:00+00:00","dateModified":"2024-02-14T16:55:13+00:00","description":"Der Product Owner die Person, die f\u00fcr die Wertsteigerung verantwortlich ist, Einbeziehung von Interessengruppen und den Kunden.","breadcrumb":{"@id":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expleo.com\/global\/de\/einblicke\/blog\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\/#primaryimage","url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/becoming-entrpreneurial-1.jpg","contentUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/becoming-entrpreneurial-1.jpg","width":1920,"height":1080,"caption":"Man analyzes data on computer"},{"@type":"BreadcrumbList","@id":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expleo.com\/global\/de\/"},{"@type":"ListItem","position":2,"name":"Einblicke","item":"https:\/\/expleo.com\/global\/de\/einblicke\/"},{"@type":"ListItem","position":3,"name":"Unternehmerisch handeln: Maximieren Sie die Wirkung Ihrer Product Owner"}]},{"@type":"WebSite","@id":"https:\/\/expleo.com\/global\/de\/#website","url":"https:\/\/expleo.com\/global\/de\/","name":"Expleo | DE","description":"Expleo","publisher":{"@id":"https:\/\/expleo.com\/global\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expleo.com\/global\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/expleo.com\/global\/de\/#organization","name":"Expleo | DE","url":"https:\/\/expleo.com\/global\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/expleo.com\/global\/de\/#\/schema\/logo\/image\/","url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","contentUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","width":1600,"height":774,"caption":"Expleo | DE"},"image":{"@id":"https:\/\/expleo.com\/global\/de\/#\/schema\/logo\/image\/"}}]}},"hreflang":{"rendered":"<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/einblicke\/blog\/becoming-entrepreneurial-maximising-the-impact-of-your-product-owners\/\" hreflang=\"x-default\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/einblicke\/blog\/becoming-entrepreneurial-maximising-the-impact-of-your-product-owners\/\" hreflang=\"en\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/fr\/einblicke\/blog\/methode-agile-comment-optimiser-limpact-de-vos-product-owners\/\" hreflang=\"fr\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\/\" hreflang=\"de\"\/>\n","structure":[{"blogId":4,"blogIsHidden":false,"postId":1547,"url":"https:\/\/expleo.com\/global\/en\/einblicke\/blog\/becoming-entrepreneurial-maximising-the-impact-of-your-product-owners\/","language":"en","default":true},{"blogId":5,"blogIsHidden":false,"postId":1212,"url":"https:\/\/expleo.com\/global\/fr\/einblicke\/blog\/methode-agile-comment-optimiser-limpact-de-vos-product-owners\/","language":"fr","default":false},{"blogId":6,"blogIsHidden":false,"postId":1178,"url":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/unternehmerisch-handeln-maximieren-sie-die-wirkung-ihrer-product-owner\/","language":"de","default":false}]},"_links":{"self":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights\/1178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/types\/insights"}],"version-history":[{"count":0,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights\/1178\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/media\/1129"}],"wp:attachment":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/media?parent=1178"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/topic?post=1178"},{"taxonomy":"insights-single-templates","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights-single-templates?post=1178"},{"taxonomy":"industry-taxonomy","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/industry-taxonomy?post=1178"},{"taxonomy":"content-type","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/content-type?post=1178"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/country?post=1178"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/service?post=1178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}