{"id":1396,"date":"2018-08-06T11:42:00","date_gmt":"2018-08-06T11:42:00","guid":{"rendered":"https:\/\/expleo.com\/global\/en\/?post_type=insight&#038;p=2592"},"modified":"2025-05-15T16:53:40","modified_gmt":"2025-05-15T16:53:40","slug":"die-dsgvo-als-sprungbrett-zu-mehr-innovation","status":"publish","type":"insights","link":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\/","title":{"rendered":"Die DSGVO als Sprungbrett zu mehr Innovation"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1396\" class=\"elementor elementor-1396\" data-elementor-post-type=\"insights\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bc55e0c gg-article-content gg-standard-article-template gg-simple-text gg-container-small-ptb-72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bc55e0c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee1b85a gg-tablet-view\" data-id=\"ee1b85a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db020f1 gg-display-none-print elementor-widget elementor-widget-image\" data-id=\"db020f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/08\/gdpr-768x432.jpg\" class=\"attachment-medium_large size-medium_large wp-image-39072\" alt=\"A digital circular interface with the text &quot;GDPR&quot; in the center, surrounded by glowing blue and red technological elements on a dark background, symbolizing data protection and privacy.\" srcset=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/08\/gdpr-768x432.jpg 768w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/08\/gdpr-300x169.jpg 300w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/08\/gdpr-1024x576.jpg 1024w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/08\/gdpr.jpg 1280w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe710fd gg-font-v9 gg-class-for-iphone8  elementor-widget elementor-widget-text-editor\" data-id=\"fe710fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Wirtschaft ist endlich in die Phase nach Inkrafttreten der DSGVO eingetreten und hat damit wohl auch das Gef\u00fchl der Angst vor den Problemen \u00fcberwunden, die sich aus den neuen Vorschriften ergeben k\u00f6nnen. Jetzt, da sich der Staub gelegt haben d\u00fcrfte, den tausende von Datenschutz-Zustimmungs-E-Mails aufgewirbelt haben, beginnen Unternehmen zu pr\u00fcfen, wie sie die neuen Prozesse zu ihrem Vorteil nutzen k\u00f6nnen. In Vorbereitung auf das Inkrafttreten der DSGVO waren viele Unternehmen gezwungen, die Informationen, die sie in unterschiedlichsten Datensilos aufbewahrt hatten, zu \u00fcberpr\u00fcfen und Prozesse zur Organisation, Klassifizierung und Kennzeichnung von Inhalten einzuf\u00fchren. In der Folge haben sie ihre Arbeitsabl\u00e4ufe gestrafft, um die eigenen Datenfluten besser bew\u00e4ltigen zu k\u00f6nnen.<\/p><p>Dies kam direkt der fortschreitenden digitalen Transformation dieser Unternehmen zugute, weil Inhalte jetzt besser verstanden und verarbeitet werden k\u00f6nnen, was wiederum die Unterbrechung von Arbeitsabl\u00e4ufen reduziert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ba2455 gg-font-v9 gg-class-for-iphone8 gg-print-pb-1  elementor-widget elementor-widget-text-editor\" data-id=\"1ba2455\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vor der DSGVO sahen Unternehmen die digitale Transformation gleicherma\u00dfen als Chance wie auch als Herausforderung, da sie sich von veralteter Technik und \u00fcberholten Prozessen, die als Wachstumshemmnisse fungierten, trennen mussten. Dabei ging es unter anderem darum, neue Technologien zu nutzen, die mehr Agilit\u00e4t und Innovation erm\u00f6glichen und gleichzeitig den Anforderungen der modernen Arbeitswelt gerecht werden, wie z.B. Remote-Zugriff auf Server. Gleichzeitig sollten diese neuen Technologien die Mitarbeiter unterst\u00fctzen und helfen, Engp\u00e4sse zu bew\u00e4ltigen, die in der Vergangenheit die Produktivit\u00e4t behindert haben. Probleme ergaben sich allerdings durch die Integration von noch ben\u00f6tigten Alt-Systemen und in der Benutzerakzeptanz. Andererseits wurden die Prozesse offener, angesichts zunehmend sachkundiger und fehlerkritischer Kunden und Anwender. Das bedeutet, dass die Mitarbeiter \u2013 darum bem\u00fcht, Workflows und Produktivit\u00e4t aufrecht zu erhalten \u2013 Praktiken der Problemumgehung einsetzten, und das auch in der IT, was jedoch gleichzeitig die Datenstr\u00f6me vergr\u00f6\u00dferte.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5328ca gg-font-v9 gg-class-for-iphone8  elementor-widget elementor-widget-text-editor\" data-id=\"f5328ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Wirtschaft ist endlich in die Phase nach Inkrafttreten der DSGVO eingetreten und hat damit wohl auch das Gef\u00fchl der Angst vor den Problemen \u00fcberwunden, die sich aus den neuen Vorschriften ergeben k\u00f6nnen. Jetzt, da sich der Staub gelegt haben d\u00fcrfte, den tausende von Datenschutz-Zustimmungs-E-Mails aufgewirbelt haben, beginnen Unternehmen zu pr\u00fcfen, wie sie die neuen Prozesse zu ihrem Vorteil nutzen k\u00f6nnen. In Vorbereitung auf das Inkrafttreten der DSGVO waren viele Unternehmen gezwungen, die Informationen, die sie in unterschiedlichsten Datensilos aufbewahrt hatten, zu \u00fcberpr\u00fcfen und Prozesse zur Organisation, Klassifizierung und Kennzeichnung von Inhalten einzuf\u00fchren. In der Folge haben sie ihre Arbeitsabl\u00e4ufe gestrafft, um die eigenen Datenfluten besser bew\u00e4ltigen zu k\u00f6nnen.<\/p><p>Dies kam direkt der fortschreitenden digitalen Transformation dieser Unternehmen zugute, weil Inhalte jetzt besser verstanden und verarbeitet werden k\u00f6nnen, was wiederum die Unterbrechung von Arbeitsabl\u00e4ufen reduziert.<\/p><p>Vor der DSGVO sahen Unternehmen die digitale Transformation gleicherma\u00dfen als Chance wie auch als Herausforderung, da sie sich von veralteter Technik und \u00fcberholten Prozessen, die als Wachstumshemmnisse fungierten, trennen mussten. Dabei ging es unter anderem darum, neue Technologien zu nutzen, die mehr Agilit\u00e4t und Innovation erm\u00f6glichen und gleichzeitig den Anforderungen der modernen Arbeitswelt gerecht werden, wie z.B. Remote-Zugriff auf Server. Gleichzeitig sollten diese neuen Technologien die Mitarbeiter unterst\u00fctzen und helfen, Engp\u00e4sse zu bew\u00e4ltigen, die in der Vergangenheit die Produktivit\u00e4t behindert haben. Probleme ergaben sich allerdings durch die Integration von noch ben\u00f6tigten Alt-Systemen und in der Benutzerakzeptanz. Andererseits wurden die Prozesse offener, angesichts zunehmend sachkundiger und fehlerkritischer Kunden und Anwender. Das bedeutet, dass die Mitarbeiter \u2013 darum bem\u00fcht, Workflows und Produktivit\u00e4t aufrecht zu erhalten \u2013 Praktiken der Problemumgehung einsetzten, und das auch in der IT, was jedoch gleichzeitig die Datenstr\u00f6me vergr\u00f6\u00dferte.<\/p><p>Die DSGVO erzwang die Identifizierung und Eind\u00e4mmung dieser Datenmenge. Die Definition und Sicherung reiner Unternehmensdaten entsprach grundlegenden Best Practices zur Einhaltung und dauerhaften Gew\u00e4hrleistung der Vorgaben der DSGVO \u2013 und damit auch der Vermeidung von Geldbu\u00dfen. Es stand allerdings zu viel auf dem Spiel und es steckte zu viel Wert in den Datenbest\u00e4nden mittelgro\u00dfer Unternehmen, um nicht ber\u00fccksichtigt zu werden. Unternehmen, die wertvolle Daten fr\u00fchzeitig identifiziert und dies als Teil ihrer Strategie f\u00fcr digitale Transformation in laufende Prozesse integriert hatten, waren ihren Wettbewerbern daher weit voraus.<\/p><p>Es ist jedoch nicht immer gleich zu erkennen, wie diese beiden Arten von Daten zusammenpassen. Die Vorbereitung auf die Einhaltung der DSGVO mag vielen daher wie eine teure \u00dcbung bei einem Probealarm erscheinen, von der viele Unternehmen erst einmal keinen greifbaren wirtschaftlichen Nutzen haben. Die vollst\u00e4ndige Einhaltung der Vorschriften war auch kein Garant f\u00fcr Sicherheit und f\u00fcgte eine neue Ebene von Prozessen hinzu, die einzuhalten waren. Die DSGVO sollte nicht am Ende des Prozesses stehen, sondern als weiterer Schritt oder vielleicht sogar als Sprungbrett auf dem Weg der digitalen Transformation angesehen werden \u2013 als ein n\u00fctzliches Puzzleteil, das Unternehmen letztlich hilft, ihr n\u00e4chstes gro\u00dfes Ziel zu erreichen. Durch die \u00dcberpr\u00fcfung der Daten, die ein Unternehmen besitzt, sowie der Art und Weise, wie mit ihnen umgegangen wird, k\u00f6nnen weitere m\u00f6gliche Ideen zur Verbesserung und Rationalisierung von Prozessen freigesetzt werden. Dar\u00fcber hinaus k\u00f6nnen durch die Analyse dieser Daten wichtige Erkenntnisse gewonnen werden, die letztendlich den Fortgang und das Wachstum eines Unternehmens bestimmen.<\/p><p>Es ist wichtig zu wissen, dass die Nutzung von Daten zwar viele Vorteilebietet, aber auch gr\u00f6\u00dfere Risiken darstellen kann. Der j\u00fcngste Skandal um Cambridge Analytica zeigte erneut, was passieren kann, wenn Unternehmen mit Daten zocken und dies als willkommene Einnahmequelle betrachten. Der Skandal lie\u00df den Aktienkurs von Facebook abst\u00fcrzen und f\u00fchrte schlie\u00dflich dazu, dass Cambridge Analytica\u00a0 dicht machen musste \u2013 was die tats\u00e4chlichen Kosten des Missbrauchs von Daten und Nutzervertrauen verdeutlicht. Es ist unwahrscheinlich, dass sich Kunden mit sch\u00f6nen Worten abspeisen lassen, wenn ihre pers\u00f6nlichen Daten kompromittiert wurden.<\/p><p>Um die Vorteile der Unternehmensaktivit\u00e4ten nach der Einf\u00fchrung der DSGVO voll auszusch\u00f6pfen, sollten Firmen objektiv untersuchen, inwiefern die Vorschriften mit ihren eigenen Gesch\u00e4ftszielen \u00fcbereinstimmen. M\u00f6glicherweise sind w\u00e4hrend des Prozesses zur Erlangung der Konformit\u00e4t bestimmte Bereiche aufgefallen, in denen sich das Unternehmen besonders hervortun konnte \u2013 und andere, die noch Nachholbedarf hatten. Dar\u00fcber hinaus reicht die Einhaltung der DSGVO allein nicht aus, um Datensicherheit zu gew\u00e4hrleisten, bietet hierzu aber eine gute Ausgangsbasis. Schutzma\u00dfnahmen k\u00f6nnen darauf aufbauen oder verst\u00e4rkt werden, um sicherzustellen, dass sie so robust wie m\u00f6glich sind und den Unternehmen das Vertrauen ihrer Kunden erhalten bleibt.<\/p><p>Mit der Zeit werden Unternehmen merken, wie die Prozesse zur Sicherstellung der Compliance die Erreichung ihrer laufenden Ziele bez\u00fcglich der digitalen Transformation erleichtern, insbesondere wenn sie von Anfang an intelligente Entscheidungen mit Fokus auf Qualit\u00e4t getroffen haben. Die Deadline zur Erreichung der Konformit\u00e4t kann nicht als Ende einer Reise, sondern als deren Anfang gesehen werden, mit Fokus auf die Aufrechterhaltung der Compliance und dem Aufbau auf bestehenden Prozessen.<\/p><p>Die Gesch\u00e4ftswelt ver\u00e4ndert sich rasant, und Unternehmensdaten k\u00f6nnen \u00fcber die reine Compliance hinaus f\u00fcr weitaus h\u00f6here Gewinne gut sein. Die Transparenz \u00fcber die Art und Weise, wie diese Daten verwendet werden, wird jedoch von entscheidender Bedeutung sein, insbesondere da sich immer mehr Kunden des Werts ihrer pers\u00f6nlichen Daten bewusst werden. Unternehmen sollten die Situation nach Inkrafttreten der DSGVO also positiv sehen und die Erfahrungen auf dem Weg zur digitalen Transformation nutzen, um die Zukunft mitzugestalten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Die Wirtschaft ist endlich in die Phase nach Inkrafttreten der DSGVO eingetreten und hat damit wohl auch das Gef\u00fchl der Angst vor den Problemen<\/p>\n","protected":false},"featured_media":39072,"parent":0,"template":"","meta":{"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","footnotes":""},"topic":[122,185],"insights-single-templates":[386],"industry-taxonomy":[293],"content-type":[21],"country":[259],"service":[56,191,81,238],"class_list":["post-1396","insights","type-insights","status-publish","has-post-thumbnail","hentry","topic-business-transformation","topic-datenwissenschaft-und-cybersicherheit","insights-single-templates-old-template","industry-taxonomy-all","content-type-blog","country-united-kingdom","service-ai-powered-software-qa-qe","service-qualitat-und-test","service-strategische-beratung-und-cx","service-transformation-consultancy"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Expleo | Die DSGVO als Sprungbrett zu mehr Innovation<\/title>\n<meta name=\"description\" content=\"Die Wirtschaft ist endlich in die Phase nach Inkrafttreten der DSGVO eingetreten und hat damit wohl auch das Gef\u00fchl der Angst vor den Problemen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die DSGVO als Sprungbrett zu mehr Innovation\" \/>\n<meta property=\"og:description\" content=\"Die Wirtschaft ist endlich in die Phase nach Inkrafttreten der DSGVO eingetreten und hat damit wohl auch das Gef\u00fchl der Angst vor den Problemen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\/\" \/>\n<meta property=\"og:site_name\" content=\"Global DE\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-15T16:53:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/08\/gdpr.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/blog\\\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/blog\\\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\\\/\",\"name\":\"Expleo | Die DSGVO als Sprungbrett zu mehr Innovation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/blog\\\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/blog\\\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/gdpr.jpg\",\"datePublished\":\"2018-08-06T11:42:00+00:00\",\"dateModified\":\"2025-05-15T16:53:40+00:00\",\"description\":\"Die Wirtschaft ist endlich in die Phase nach Inkrafttreten der DSGVO eingetreten und hat damit wohl auch das Gef\u00fchl der Angst vor den Problemen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/blog\\\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/blog\\\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/blog\\\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/gdpr.jpg\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/gdpr.jpg\",\"width\":1280,\"height\":720,\"caption\":\"A digital circular interface with the text \\\"GDPR\\\" in the center, surrounded by glowing blue and red technological elements on a dark background, symbolizing data protection and privacy.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/blog\\\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einblicke\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Die DSGVO als Sprungbrett zu mehr Innovation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\",\"name\":\"Expleo | DE\",\"description\":\"Expleo\",\"publisher\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#organization\",\"name\":\"Expleo | DE\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"width\":1600,\"height\":774,\"caption\":\"Expleo | DE\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Expleo | Die DSGVO als Sprungbrett zu mehr Innovation","description":"Die Wirtschaft ist endlich in die Phase nach Inkrafttreten der DSGVO eingetreten und hat damit wohl auch das Gef\u00fchl der Angst vor den Problemen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\/","og_locale":"de_DE","og_type":"article","og_title":"Die DSGVO als Sprungbrett zu mehr Innovation","og_description":"Die Wirtschaft ist endlich in die Phase nach Inkrafttreten der DSGVO eingetreten und hat damit wohl auch das Gef\u00fchl der Angst vor den Problemen.","og_url":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\/","og_site_name":"Global DE","article_modified_time":"2025-05-15T16:53:40+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/08\/gdpr.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\/","url":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\/","name":"Expleo | Die DSGVO als Sprungbrett zu mehr Innovation","isPartOf":{"@id":"https:\/\/expleo.com\/global\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\/#primaryimage"},"image":{"@id":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\/#primaryimage"},"thumbnailUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/08\/gdpr.jpg","datePublished":"2018-08-06T11:42:00+00:00","dateModified":"2025-05-15T16:53:40+00:00","description":"Die Wirtschaft ist endlich in die Phase nach Inkrafttreten der DSGVO eingetreten und hat damit wohl auch das Gef\u00fchl der Angst vor den Problemen.","breadcrumb":{"@id":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expleo.com\/global\/de\/einblicke\/blog\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\/#primaryimage","url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/08\/gdpr.jpg","contentUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/08\/gdpr.jpg","width":1280,"height":720,"caption":"A digital circular interface with the text \"GDPR\" in the center, surrounded by glowing blue and red technological elements on a dark background, symbolizing data protection and privacy."},{"@type":"BreadcrumbList","@id":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expleo.com\/global\/de\/"},{"@type":"ListItem","position":2,"name":"Einblicke","item":"https:\/\/expleo.com\/global\/de\/einblicke\/"},{"@type":"ListItem","position":3,"name":"Die DSGVO als Sprungbrett zu mehr Innovation"}]},{"@type":"WebSite","@id":"https:\/\/expleo.com\/global\/de\/#website","url":"https:\/\/expleo.com\/global\/de\/","name":"Expleo | DE","description":"Expleo","publisher":{"@id":"https:\/\/expleo.com\/global\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expleo.com\/global\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/expleo.com\/global\/de\/#organization","name":"Expleo | DE","url":"https:\/\/expleo.com\/global\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/expleo.com\/global\/de\/#\/schema\/logo\/image\/","url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","contentUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","width":1600,"height":774,"caption":"Expleo | DE"},"image":{"@id":"https:\/\/expleo.com\/global\/de\/#\/schema\/logo\/image\/"}}]}},"hreflang":{"rendered":"<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/einblicke\/blog\/gdpr-a-stepping-stone-to-innovation\/\" hreflang=\"x-default\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/einblicke\/blog\/gdpr-a-stepping-stone-to-innovation\/\" hreflang=\"en\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/fr\/einblicke\/blog\/rgpd-un-tremplin-vers-pour-linnovation\/\" hreflang=\"fr\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\/\" hreflang=\"de\"\/>\n","structure":[{"blogId":4,"blogIsHidden":false,"postId":2592,"url":"https:\/\/expleo.com\/global\/en\/einblicke\/blog\/gdpr-a-stepping-stone-to-innovation\/","language":"en","default":true},{"blogId":5,"blogIsHidden":false,"postId":1430,"url":"https:\/\/expleo.com\/global\/fr\/einblicke\/blog\/rgpd-un-tremplin-vers-pour-linnovation\/","language":"fr","default":false},{"blogId":6,"blogIsHidden":false,"postId":1396,"url":"https:\/\/expleo.com\/global\/de\/einblicke\/blog\/die-dsgvo-als-sprungbrett-zu-mehr-innovation\/","language":"de","default":false}]},"_links":{"self":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights\/1396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/types\/insights"}],"version-history":[{"count":0,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights\/1396\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/media\/39072"}],"wp:attachment":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/media?parent=1396"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/topic?post=1396"},{"taxonomy":"insights-single-templates","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights-single-templates?post=1396"},{"taxonomy":"industry-taxonomy","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/industry-taxonomy?post=1396"},{"taxonomy":"content-type","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/content-type?post=1396"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/country?post=1396"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/service?post=1396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}