{"id":602,"date":"2018-07-04T08:56:00","date_gmt":"2018-07-04T08:56:00","guid":{"rendered":"https:\/\/expleo.com\/insights\/uncategorized\/jtekt-corporation-in-europe-chooses-expleo-to-create-a-new-rd-services-center-in-france-2-3\/"},"modified":"2025-02-06T10:47:29","modified_gmt":"2025-02-06T10:47:29","slug":"jtekt-europe-setzt-auf-expleo","status":"publish","type":"insights","link":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/jtekt-europe-setzt-auf-expleo\/","title":{"rendered":"JTEKT Europe setzt auf EXPLEO"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"602\" class=\"elementor elementor-602\" data-elementor-post-type=\"insights\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4fdf58b gg-article-content  gg-standard-article-template gg-simple-text gg-container-small-ptb-72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fdf58b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0522d99 gg-tablet-view\" data-id=\"0522d99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8d291c gg-font-v9 gg-class-for-iphone8  elementor-widget elementor-widget-text-editor\" data-id=\"a8d291c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Paris, 4. Juli\u00a02018.<\/strong>\u00a0Der Automobilzulieferer JTEKT Europe und Expleo, ein f\u00fchrender Partner f\u00fcr Engineering, Qualit\u00e4tsdienstleistungen und digitale L\u00f6sungen, st\u00e4rken ihre strategische Partnerschaft: An den franz\u00f6sischen Standorten Irigny und Saint-Priest entstehen dazu neue Forschungs- und Entwicklungszentren mit Schwerpunkt autonomes Fahren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e3f966  gg-display-none-print elementor-widget elementor-widget-image\" data-id=\"9e3f966\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/07\/news-jtekt-1280x720-1-1-768x432.jpeg\" class=\"attachment-medium_large size-medium_large wp-image-35434\" alt=\"Two men in a modern office work together at a computer displaying a 3D CAD model of a mechanical part; one man is seated using the computer, while the other stands and looks at the screen.\" srcset=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/07\/news-jtekt-1280x720-1-1-768x432.jpeg 768w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/07\/news-jtekt-1280x720-1-1-300x169.jpeg 300w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/07\/news-jtekt-1280x720-1-1-1024x576.jpeg 1024w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/07\/news-jtekt-1280x720-1-1.jpeg 1280w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cae92ff gg-font-v9 gg-class-for-iphone8    elementor-widget elementor-widget-text-editor\" data-id=\"cae92ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die beiden Unternehmen haben ein Abkommen f\u00fcr eine mehrj\u00e4hrige Zusammenarbeit ihrer F&amp;E-Teams in einem auf zwei Standorte verteilten Servicezentrum unterzeichnet. Bereits seit Q1\/2018 arbeiten dort Ingenieure von JTEKT Europe und Expleo gemeinsam an innovativen Produktl\u00f6sungen, etwa zu den Themen Serienfertigung, Software-Engineering, Elektronik, aber auch im Bereich Konstruktion und Projektmanagement. Die Teams entwickeln und testen dar\u00fcber hinaus Embedded Systems und Produkte der JTEKT-Gruppe.<\/p><p>R\u00e9mi Festaz, Vice-President und Regionsverantwortlicher in Frankreich von Expleo: \u201cDer Aufbau eines gemeinsamen F&amp;E-Servicezentrums ist das Ergebnis einer f\u00fcnfzehnj\u00e4hrigen, vertrauensvollen Zusammenarbeit. Durch das hohe Ma\u00df an Vertrauen und die damit verbundene Verantwortung, k\u00f6nnen wir noch besser auf die Herausforderungen von JTEKT eingehen. Die Integration neuer Technologien zur Entwicklung von autonomen Fahrzeugen ist daf\u00fcr ein Beispiel\u201c.<\/p><p>Richard Chauvel-Sanz, Leiter des technischen Zentrums JTEKT Europa: \u201eDas mit unserem langj\u00e4hrigen Partner Expleo etablierte Servicezentrum stellt eine echte Erweiterung unseres Forschungs- und Entwicklungsprozesses dar. Das integrierte Modell definiert f\u00fcr uns neue Formen der Zusammenarbeit. Es hilft uns dabei, sowohl Reaktionsf\u00e4higkeit als auch Performance auszubauen und damit unsere Wertsch\u00f6pfung zu verbessern\u201c.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Der Automobilzulieferer JTEKT Europe und Expleo, ein f\u00fchrender Partner f\u00fcr Engineering, Qualit\u00e4tsdienstleistungen und digitale L\u00f6sungen, st\u00e4rken ihre strategische Partnerschaft.<\/p>\n","protected":false},"featured_media":0,"parent":0,"template":"","meta":{"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","footnotes":""},"topic":[117],"insights-single-templates":[386],"industry-taxonomy":[24],"content-type":[20],"country":[86],"service":[],"class_list":["post-602","insights","type-insights","status-publish","hentry","topic-innovation-and-r-and-d","insights-single-templates-old-template","industry-taxonomy-automotive","content-type-neuigkeiten","country-frankreich"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Expleo | JTEKT Europe setzt auf EXPLEO<\/title>\n<meta name=\"description\" content=\"JTEKT Europe und Expleo, ein f\u00fchrender Partner f\u00fcr Engineering, Qualit\u00e4tsdienstleistungen und digitale L\u00f6sungen, st\u00e4rken ihre strategische Partnerschaft.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/jtekt-europe-setzt-auf-expleo\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JTEKT Europe setzt auf EXPLEO\" \/>\n<meta property=\"og:description\" content=\"JTEKT Europe und Expleo, ein f\u00fchrender Partner f\u00fcr Engineering, Qualit\u00e4tsdienstleistungen und digitale L\u00f6sungen, st\u00e4rken ihre strategische Partnerschaft.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/jtekt-europe-setzt-auf-expleo\/\" \/>\n<meta property=\"og:site_name\" content=\"Global DE\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-06T10:47:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/07\/news-jtekt-1280x720-1-1-768x432.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/jtekt-europe-setzt-auf-expleo\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/jtekt-europe-setzt-auf-expleo\\\/\",\"name\":\"Expleo | JTEKT Europe setzt auf EXPLEO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/jtekt-europe-setzt-auf-expleo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/jtekt-europe-setzt-auf-expleo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/news-jtekt-1280x720-1-1-768x432.jpeg\",\"datePublished\":\"2018-07-04T08:56:00+00:00\",\"dateModified\":\"2025-02-06T10:47:29+00:00\",\"description\":\"JTEKT Europe und Expleo, ein f\u00fchrender Partner f\u00fcr Engineering, Qualit\u00e4tsdienstleistungen und digitale L\u00f6sungen, st\u00e4rken ihre strategische Partnerschaft.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/jtekt-europe-setzt-auf-expleo\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/jtekt-europe-setzt-auf-expleo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/jtekt-europe-setzt-auf-expleo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/news-jtekt-1280x720-1-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/news-jtekt-1280x720-1-1.jpeg\",\"width\":1280,\"height\":720,\"caption\":\"Two men in a modern office work together at a computer displaying a 3D CAD model of a mechanical part; one man is seated using the computer, while the other stands and looks at the screen.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/jtekt-europe-setzt-auf-expleo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einblicke\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"JTEKT Europe setzt auf EXPLEO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\",\"name\":\"Expleo | DE\",\"description\":\"Expleo\",\"publisher\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#organization\",\"name\":\"Expleo | DE\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"width\":1600,\"height\":774,\"caption\":\"Expleo | DE\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Expleo | JTEKT Europe setzt auf EXPLEO","description":"JTEKT Europe und Expleo, ein f\u00fchrender Partner f\u00fcr Engineering, Qualit\u00e4tsdienstleistungen und digitale L\u00f6sungen, st\u00e4rken ihre strategische Partnerschaft.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/jtekt-europe-setzt-auf-expleo\/","og_locale":"de_DE","og_type":"article","og_title":"JTEKT Europe setzt auf EXPLEO","og_description":"JTEKT Europe und Expleo, ein f\u00fchrender Partner f\u00fcr Engineering, Qualit\u00e4tsdienstleistungen und digitale L\u00f6sungen, st\u00e4rken ihre strategische Partnerschaft.","og_url":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/jtekt-europe-setzt-auf-expleo\/","og_site_name":"Global DE","article_modified_time":"2025-02-06T10:47:29+00:00","og_image":[{"url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/07\/news-jtekt-1280x720-1-1-768x432.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/jtekt-europe-setzt-auf-expleo\/","url":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/jtekt-europe-setzt-auf-expleo\/","name":"Expleo | JTEKT Europe setzt auf EXPLEO","isPartOf":{"@id":"https:\/\/expleo.com\/global\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/jtekt-europe-setzt-auf-expleo\/#primaryimage"},"image":{"@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/jtekt-europe-setzt-auf-expleo\/#primaryimage"},"thumbnailUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/07\/news-jtekt-1280x720-1-1-768x432.jpeg","datePublished":"2018-07-04T08:56:00+00:00","dateModified":"2025-02-06T10:47:29+00:00","description":"JTEKT Europe und Expleo, ein f\u00fchrender Partner f\u00fcr Engineering, Qualit\u00e4tsdienstleistungen und digitale L\u00f6sungen, st\u00e4rken ihre strategische Partnerschaft.","breadcrumb":{"@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/jtekt-europe-setzt-auf-expleo\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/jtekt-europe-setzt-auf-expleo\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/jtekt-europe-setzt-auf-expleo\/#primaryimage","url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/07\/news-jtekt-1280x720-1-1.jpeg","contentUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2018\/07\/news-jtekt-1280x720-1-1.jpeg","width":1280,"height":720,"caption":"Two men in a modern office work together at a computer displaying a 3D CAD model of a mechanical part; one man is seated using the computer, while the other stands and looks at the screen."},{"@type":"BreadcrumbList","@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/jtekt-europe-setzt-auf-expleo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expleo.com\/global\/de\/"},{"@type":"ListItem","position":2,"name":"Einblicke","item":"https:\/\/expleo.com\/global\/de\/einblicke\/"},{"@type":"ListItem","position":3,"name":"JTEKT Europe setzt auf EXPLEO"}]},{"@type":"WebSite","@id":"https:\/\/expleo.com\/global\/de\/#website","url":"https:\/\/expleo.com\/global\/de\/","name":"Expleo | DE","description":"Expleo","publisher":{"@id":"https:\/\/expleo.com\/global\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expleo.com\/global\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/expleo.com\/global\/de\/#organization","name":"Expleo | DE","url":"https:\/\/expleo.com\/global\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/expleo.com\/global\/de\/#\/schema\/logo\/image\/","url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","contentUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","width":1600,"height":774,"caption":"Expleo | DE"},"image":{"@id":"https:\/\/expleo.com\/global\/de\/#\/schema\/logo\/image\/"}}]}},"hreflang":{"rendered":"<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/einblicke\/news\/jtekt-corporation-in-europe-chooses-expleo-to-create-a-new-rd-services-center-in-france\/\" hreflang=\"x-default\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/einblicke\/news\/jtekt-corporation-in-europe-chooses-expleo-to-create-a-new-rd-services-center-in-france\/\" hreflang=\"en\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/fr\/einblicke\/actualite\/le-groupe-jtekt-en-europe-choisit-expleo-pour-creer-un-nouveau-centre-de-services-rd-en-france\/\" hreflang=\"fr\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/jtekt-europe-setzt-auf-expleo\/\" hreflang=\"de\"\/>\n","structure":[{"blogId":4,"blogIsHidden":false,"postId":742,"url":"https:\/\/expleo.com\/global\/en\/einblicke\/news\/jtekt-corporation-in-europe-chooses-expleo-to-create-a-new-rd-services-center-in-france\/","language":"en","default":true},{"blogId":5,"blogIsHidden":false,"postId":617,"url":"https:\/\/expleo.com\/global\/fr\/einblicke\/actualite\/le-groupe-jtekt-en-europe-choisit-expleo-pour-creer-un-nouveau-centre-de-services-rd-en-france\/","language":"fr","default":false},{"blogId":6,"blogIsHidden":false,"postId":602,"url":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/jtekt-europe-setzt-auf-expleo\/","language":"de","default":false}]},"_links":{"self":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights\/602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/types\/insights"}],"version-history":[{"count":0,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights\/602\/revisions"}],"wp:attachment":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/media?parent=602"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/topic?post=602"},{"taxonomy":"insights-single-templates","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights-single-templates?post=602"},{"taxonomy":"industry-taxonomy","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/industry-taxonomy?post=602"},{"taxonomy":"content-type","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/content-type?post=602"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/country?post=602"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/service?post=602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}