{"id":741,"date":"2018-11-19T06:21:00","date_gmt":"2018-11-19T06:21:00","guid":{"rendered":"https:\/\/expleo.com\/insights\/uncategorized\/jtekt-corporation-in-europe-chooses-expleo-to-create-a-new-rd-services-center-in-france-2-3-2\/"},"modified":"2024-02-28T14:13:06","modified_gmt":"2024-02-28T14:13:06","slug":"bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern","status":"publish","type":"insights","link":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\/","title":{"rendered":"BAMCO Konsortium: Entwicklung von biobasierten Verbundwerkstoffen mit Bambusfasern"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"741\" class=\"elementor elementor-741\" data-elementor-post-type=\"insights\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4fdf58b gg-article-content gg-standard-article-template gg-simple-text gg-container-small-ptb-72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fdf58b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0522d99 gg-tablet-view\" data-id=\"0522d99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8d291c gg-font-v9 gg-class-for-iphone8  elementor-widget elementor-widget-text-editor\" data-id=\"a8d291c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Paris, 19. November 2018.\u00a0<\/strong>Expleo, Arkema, Cobratex, Specific Polymers, Cirimat, Compositadour, Lisa Aeronautics und M\u00e9cano ID haben sich zusammengeschlossen, um gemeinsam neue technische Verbundwerkstoffe aus dem nachwachsenden Rohstoff Bambus-Langfasern zu konzipieren. Diese Innovation mit dem Namen BAMCO (BAmboo long fibre reinforced biobased Matrix COmposites) k\u00f6nnte auf Dauer die Umweltbilanz der Flugzeuge verbessern und durch seine Vorteile auch au\u00dferhalb des Luftfahrtsektors Anwendung finden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e3f966 gg-display-none-print elementor-widget elementor-widget-image\" data-id=\"9e3f966\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/news-bamco-1280x720-1-768x432.jpeg\" class=\"attachment-medium_large size-medium_large wp-image-377\" alt=\"A white plane\" srcset=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/news-bamco-1280x720-1-768x432.jpeg 768w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/news-bamco-1280x720-1-300x169.jpeg 300w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/news-bamco-1280x720-1-1024x576.jpeg 1024w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/news-bamco-1280x720-1.jpeg 1280w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cae92ff gg-font-v9 gg-class-for-iphone8    elementor-widget elementor-widget-text-editor\" data-id=\"cae92ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Reduzierung des \u00f6kologischen Fu\u00dfabdrucks geh\u00f6rt in immer st\u00e4rkerem Ma\u00dfe zu einem der Hauptanliegen der Industrie. Im Luftfahrtsektor laufen die Forschungsbem\u00fchungen insbesondere auf die Konzeption neuer Werkstoffe hinaus. Einige der aktuell verwendeten Polymer-Verbundwerkstoffe, z.B. aus Glasfaser-\/Phenolharz-Basis, werden in K\u00fcrze unter die europ\u00e4ische Chemikalienverordnung REACH fallen. Deshalb m\u00fcssen dringend alternative L\u00f6sungen gefunden werden, die die gleiche Leistungsf\u00e4higkeit aufweisen.<\/p>\n<p>Seit vier Jahren widmen sich Expleo und das Zentrum f\u00fcr Forschung und Materialwesen CIRIMAT in enger Zusammenarbeit dem Konzept eines bambusfaserverst\u00e4rkten Biowerkstoffs mit biobasierter thermoplastischer Matrix. Das Konzept hat bereits das Laborstadium verlassen und muss im n\u00e4chsten Schritt f\u00fcr die industrielle Produktion freigegeben werden.<\/p>\n<p>Dieser Herausforderung stellt sich das Gemeinschaftsprojekt FUI BAMCO mit neuen, aus Bambus-Langfasern gefertigten Biowerkstoffen. Im Vergleich zu den bereits bestehenden Alternativen aus Leinen- oder Hanffasern sind diese Biowerkstoffe v\u00f6llig neu und k\u00f6nnen auf Grund ihres Federgewichts (weniger Gewicht = geringerer Treibstoffverbrauch), ihrer W\u00e4rmebest\u00e4ndigkeit und ihrer mechanischen Eigenschaften (Festigkeit, Schlag- und Schwingungsabsorption) eine attraktive Alternative zu Glas-Phenolharz-Werkstoffen darstellen. Hinzu kommt, dass der Anbau von Bambus in allen Punkten den \u00f6kologischen Auflagen entspricht, denn Bambus ist ein rasch nachwachsender Rohstoff mit geringem Wasser- und Fl\u00e4chenbedarf, der ohne D\u00fcnger oder Pestizide auskommt.<\/p>\n<p>Im Luftfahrtsektor k\u00f6nnen die BAMCO-Verbundwerkstoffe f\u00fcr die Ausstattung der Kabinen und als Bestandteil der Beschichtungen und Verkleidungen des Flugzeugrumpfs bzw. des Bordverpflegungsbereiches verwendet werden. Auch Fertigteile f\u00fcr den Schiffsbau und den Freizeitsport k\u00f6nnen daraus hergestellt werden.<\/p>\n<p>Das vom Zentrum f\u00fcr Wettbewerbsf\u00e4higkeit Aerospace Valley gepr\u00fcfte und von der Generaldirektion Unternehmen im Rahmen des FUI 24 (Einheitlicher Interministerieller Fonds zur Finanzierung von Projekten der Zusammenarbeit von Forschung und Entwicklung) freigegebene BAMCO-Projekt wird von den franz\u00f6sischen Regionen Occitanie Pyr\u00e9n\u00e9es-M\u00e9diterran\u00e9e, Normandie und Bpifrance unterst\u00fctzt. Daran beteiligt sind acht Akteure, Unternehmen und Forschungslabore, die sich zu einem Konsortium zusammengeschlossen haben.<\/p>\n<p>Als Tr\u00e4ger des BAMCO-Projekts fungiert Expleo, anerkannter und zuverl\u00e4ssiger Entwicklungspartner der Industrie f\u00fcr Ingenieursdienstleistungen, innovative L\u00f6sungen und digitale L\u00f6sungen. Sein Know-how in den Bereichen Werkstoff- und Luftfahrttechnik stellt Expleo in den Dienst des Prototypbaus. Au\u00dferdem hat das Unternehmen die F\u00fchrung dieses f\u00fcr die Industrie der Zukunft so wichtige Projekt \u00fcbernommen.<\/p>\n<p><strong>Arkema<\/strong>\u00a0und\u00a0<strong>Specific Polymers<\/strong>\u00a0verantwortendie Formulierung der Zusammensetzung und der Ausf\u00fchrung biobasierter Polymere, die die Matrizen der Verbundwerkstoffe bilden.<\/p>\n<p><strong>Cobratex<\/strong>\u00a0untersucht unterschiedliche Bambusarten, die zum Teil in Frankreich angebaut werden, und bereitet eine Entscheidungsgrundlage vor. Um s\u00e4mtliche Vorgaben der Verarbeitung der unterschiedlichen Matrizen und Verfahren zu erf\u00fcllen, optimiert\u00a0<strong>Cobratex<\/strong>\u00a0das eigene Verarbeitungsverfahren sowie das eigene innovative Verst\u00e4rkungsmaterial. Zum Aufgabenbereich des Unternehmens geh\u00f6rt au\u00dferdem die ma\u00dfst\u00e4bliche Anpassung der direkt vom CIRIMAT entwickelten technischen Verst\u00e4rkungsmaterialien und Halbzeuge.<\/p>\n<p>Die Forschungslabors,\u00a0<strong>CIRIMAT<\/strong>\u00a0und\u00a0<strong>Compositadour<\/strong>\u00a0widmen sich der Verarbeitung der Biowerkstoffe im Labor bzw. in der Industrie. CIRIMAT leistet seinen Beitrag zum Projekt in Form von Konzeption und Entwicklung der Werkstoffe mit Langfaser-Bambus-Verst\u00e4rkung und mit thermo- bzw. duroplastischer Matrix im Labor.<\/p>\n<p><strong>M\u00e9cano ID<\/strong>\u00a0f\u00fchrt die Schwingungsversuche zur Festlegung der D\u00e4mpfungseigenschaften und die Modellierung des Verhaltens der Biowerkstoffe durch.<\/p>\n<p>Nicht zuletzt beteiligt sich der Flugzeugbauer<strong>\u00a0Lisa Aeronautics<\/strong>\u00a0an der Umsetzung eines Prototypenteils f\u00fcr seine k\u00fcnftigen Maschinen.<\/p>\n<p>Das BAMCO-Projekt ist jetzt mit dem Beginn der Entwicklungsarbeiten in seine operative Phase eingetreten. Die ersten Teile als Prototyp sind f\u00fcr 2021 vorgesehen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Expleo, Arkema, Cobratex, Specific Polymers, Cirimat, Compositadour, Lisa Aeronautics und M\u00e9cano ID haben sich zusammengeschlossen, um gemeinsam neue technische Verbundwerkstoffe aus dem nachwachsenden Rohstoff Bambus-Langfasern zu konzipieren.<\/p>\n","protected":false},"featured_media":377,"parent":0,"template":"","meta":{"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","footnotes":""},"topic":[116,117],"insights-single-templates":[386],"industry-taxonomy":[],"content-type":[20],"country":[86],"service":[31,200,214,193,32,238],"class_list":["post-741","insights","type-insights","status-publish","has-post-thumbnail","hentry","topic-engineering-design","topic-innovation-and-r-and-d","insights-single-templates-old-template","content-type-neuigkeiten","country-frankreich","service-design-thinking-und-lean-startup","service-e-mobilitat","service-innovation-management-solutions","service-ecodesign","service-sustainability-strategy-transformation","service-transformation-consultancy"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Expleo | BAMCO Konsortium<\/title>\n<meta name=\"description\" content=\"Expleo, Arkema, Cobratex, Specific Polymers, Cirimat, Compositadour, Lisa Aeronautics und M\u00e9cano ID haben sich. Lesen Sie Mehr.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BAMCO Konsortium: Entwicklung von biobasierten Verbundwerkstoffen mit Bambusfasern\" \/>\n<meta property=\"og:description\" content=\"Expleo, Arkema, Cobratex, Specific Polymers, Cirimat, Compositadour, Lisa Aeronautics und M\u00e9cano ID haben sich. Lesen Sie Mehr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\/\" \/>\n<meta property=\"og:site_name\" content=\"Global DE\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-28T14:13:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/news-bamco-1280x720-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\\\/\",\"name\":\"Expleo | BAMCO Konsortium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/news-bamco-1280x720-1.jpeg\",\"datePublished\":\"2018-11-19T06:21:00+00:00\",\"dateModified\":\"2024-02-28T14:13:06+00:00\",\"description\":\"Expleo, Arkema, Cobratex, Specific Polymers, Cirimat, Compositadour, Lisa Aeronautics und M\u00e9cano ID haben sich. Lesen Sie Mehr.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/news-bamco-1280x720-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/news-bamco-1280x720-1.jpeg\",\"width\":1280,\"height\":720,\"caption\":\"A white plane\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einblicke\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BAMCO Konsortium: Entwicklung von biobasierten Verbundwerkstoffen mit Bambusfasern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\",\"name\":\"Expleo | DE\",\"description\":\"Expleo\",\"publisher\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#organization\",\"name\":\"Expleo | DE\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"width\":1600,\"height\":774,\"caption\":\"Expleo | DE\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Expleo | BAMCO Konsortium","description":"Expleo, Arkema, Cobratex, Specific Polymers, Cirimat, Compositadour, Lisa Aeronautics und M\u00e9cano ID haben sich. Lesen Sie Mehr.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\/","og_locale":"de_DE","og_type":"article","og_title":"BAMCO Konsortium: Entwicklung von biobasierten Verbundwerkstoffen mit Bambusfasern","og_description":"Expleo, Arkema, Cobratex, Specific Polymers, Cirimat, Compositadour, Lisa Aeronautics und M\u00e9cano ID haben sich. Lesen Sie Mehr.","og_url":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\/","og_site_name":"Global DE","article_modified_time":"2024-02-28T14:13:06+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/news-bamco-1280x720-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\/","url":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\/","name":"Expleo | BAMCO Konsortium","isPartOf":{"@id":"https:\/\/expleo.com\/global\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\/#primaryimage"},"image":{"@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\/#primaryimage"},"thumbnailUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/news-bamco-1280x720-1.jpeg","datePublished":"2018-11-19T06:21:00+00:00","dateModified":"2024-02-28T14:13:06+00:00","description":"Expleo, Arkema, Cobratex, Specific Polymers, Cirimat, Compositadour, Lisa Aeronautics und M\u00e9cano ID haben sich. Lesen Sie Mehr.","breadcrumb":{"@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\/#primaryimage","url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/news-bamco-1280x720-1.jpeg","contentUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/news-bamco-1280x720-1.jpeg","width":1280,"height":720,"caption":"A white plane"},{"@type":"BreadcrumbList","@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expleo.com\/global\/de\/"},{"@type":"ListItem","position":2,"name":"Einblicke","item":"https:\/\/expleo.com\/global\/de\/einblicke\/"},{"@type":"ListItem","position":3,"name":"BAMCO Konsortium: Entwicklung von biobasierten Verbundwerkstoffen mit Bambusfasern"}]},{"@type":"WebSite","@id":"https:\/\/expleo.com\/global\/de\/#website","url":"https:\/\/expleo.com\/global\/de\/","name":"Expleo | DE","description":"Expleo","publisher":{"@id":"https:\/\/expleo.com\/global\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expleo.com\/global\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/expleo.com\/global\/de\/#organization","name":"Expleo | DE","url":"https:\/\/expleo.com\/global\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/expleo.com\/global\/de\/#\/schema\/logo\/image\/","url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","contentUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","width":1600,"height":774,"caption":"Expleo | DE"},"image":{"@id":"https:\/\/expleo.com\/global\/de\/#\/schema\/logo\/image\/"}}]}},"hreflang":{"rendered":"<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/einblicke\/news\/the-bamco-consortium-to-develop-biosourced-composites-using-bamboo-fibres\/\" hreflang=\"x-default\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/einblicke\/news\/the-bamco-consortium-to-develop-biosourced-composites-using-bamboo-fibres\/\" hreflang=\"en\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/fr\/einblicke\/actualite\/consortium-bamco-huit-acteurs-entreprises-et-laboratoires-de-recherche-unissent-leurs-expertises-pour-developper-des-composites-biosources-a-partir-de-fibres-de-bambou\/\" hreflang=\"fr\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\/\" hreflang=\"de\"\/>\n","structure":[{"blogId":4,"blogIsHidden":false,"postId":830,"url":"https:\/\/expleo.com\/global\/en\/einblicke\/news\/the-bamco-consortium-to-develop-biosourced-composites-using-bamboo-fibres\/","language":"en","default":true},{"blogId":5,"blogIsHidden":false,"postId":749,"url":"https:\/\/expleo.com\/global\/fr\/einblicke\/actualite\/consortium-bamco-huit-acteurs-entreprises-et-laboratoires-de-recherche-unissent-leurs-expertises-pour-developper-des-composites-biosources-a-partir-de-fibres-de-bambou\/","language":"fr","default":false},{"blogId":6,"blogIsHidden":false,"postId":741,"url":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/bamco-konsortium-entwicklung-von-biobasierten-verbundwerkstoffen-mit-bambusfasern\/","language":"de","default":false}]},"_links":{"self":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights\/741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/types\/insights"}],"version-history":[{"count":0,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights\/741\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/media\/377"}],"wp:attachment":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/media?parent=741"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/topic?post=741"},{"taxonomy":"insights-single-templates","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights-single-templates?post=741"},{"taxonomy":"industry-taxonomy","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/industry-taxonomy?post=741"},{"taxonomy":"content-type","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/content-type?post=741"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/country?post=741"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/service?post=741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}