{"id":831,"date":"2021-02-15T16:20:00","date_gmt":"2021-02-15T16:20:00","guid":{"rendered":"https:\/\/expleo.com\/global\/en\/?post_type=insight&#038;p=906"},"modified":"2024-02-14T09:29:28","modified_gmt":"2024-02-14T09:29:28","slug":"expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel","status":"publish","type":"insights","link":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\/","title":{"rendered":"Expleo beruft Florence Bigot zur General Secretary und General Counsel"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"831\" class=\"elementor elementor-831\" data-elementor-post-type=\"insights\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b28fa78 gg-article-content gg-standard-article-template gg-simple-text gg-container-small-ptb-72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b28fa78\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d18cf4 gg-tablet-view\" data-id=\"2d18cf4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-88cb762 gg-font-v9 gg-class-for-iphone8  elementor-widget elementor-widget-text-editor\" data-id=\"88cb762\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Paris, 15. Februar 2021<\/strong>\u00a0\u2013 Das Supervisory Board von Expleo hat mit sofortiger Wirkung Florence Bigot zur Group General Secretary und Group General Counsel ernannt und als Justiziarin der Gruppe in das Executive Board berufen. Florence Bigot folgt damit Nathalie Gicquel nach, die Karrierechancen au\u00dferhalb der Gruppe wahrnehmen wird.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b771102   gg-print-pb-2 elementor-widget elementor-widget-image\" data-id=\"b771102\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/florence-bigot-1280x720-1-768x432.jpg\" class=\"attachment-medium_large size-medium_large wp-image-824\" alt=\"Florence Bigot\" srcset=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/florence-bigot-1280x720-1-768x432.jpg 768w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/florence-bigot-1280x720-1-300x169.jpg 300w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/florence-bigot-1280x720-1-1024x576.jpg 1024w, https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/florence-bigot-1280x720-1.jpg 1280w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0274f9 gg-font-v9 gg-text-with-paddingbottom gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"f0274f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Florence Bigot bringt betr\u00e4chtliche internationale Erfahrungen in den Bereichen Recht und Technologie mit. Sie hatte bereits viele wichtige F\u00fchrungspositionen inne und verantwortete in gro\u00dfen globalen Organisationen wie Capgemini, Infosys und Logica umfassende Transformationsinitiativen.<\/p><p><strong>Rajesh Krishnamurthy, CEO von Expleo, kommentiert:<\/strong>\u00a0\u201eFlorence verf\u00fcgt \u00fcber ein enormes Wissen zu rechtlichen und kommerziellen Themen sowie ein tiefes Branchenverst\u00e4ndnis, das sie in schnell wachsenden IT-Service- und Technologie-Unternehmen aufgebaut hat. Ihre F\u00e4higkeiten und Erfahrungen werden f\u00fcr uns von gro\u00dfem Wert sein, um Effizienz und Agilit\u00e4t bei der Transformation von Expleo zu gew\u00e4hrleisten.\u201c<\/p><p><strong>Rajesh Krishnamurthy erg\u00e4nzt:<\/strong>\u00a0\u201eIch m\u00f6chte Nathalie Gicquel meinen aufrichtigen Dank und Respekt f\u00fcr den Beitrag ausdr\u00fccken, den sie bei der Strukturierung unserer Rechtsabteilungen und bei der Etablierung des Ethikbeirats und der Compliance-Richtlinien im Unternehmen geleistet hat.\u201c<\/p><p><strong>Florence Bigot, neue Group General Secretary und Group General Counsel, erl\u00e4utert:<\/strong>\u00a0\u201eIch freue mich, der Expleo Group an diesem entscheidenden Punkt ihrer Entwicklung beizutreten und dabei helfen zu k\u00f6nnen, ihren ambitionierten Weg der Transformation voranzutreiben.\u201c<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0f9136 gg-font-v4 gg-custom-dark-purple-color elementor-widget elementor-widget-heading\" data-id=\"f0f9136\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Biografie:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a1d8f3 gg-font-v9 gg-text-with-paddingbottom gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"9a1d8f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Florence Bigot schloss ihr Studium in International Business Law an der Fran\u00e7ois-Rabelais-Universit\u00e4t von Tours mit einem Master ab. Sie begann ihre Karriere als Legal Counsel in der Broadcast-Industrie bei Thomson Broadcast Systems, bevor sie zum Finanz- und Factoring-Dienstleister Atradius wechselte.<\/p><p>2004 wurde sie bei Logica Frankreich zur Head of Legal Affairs &amp; Commercial Manager berufen. Dort steuerte sie die kommerziellen und rechtlichen Gesch\u00e4fte des Unternehmens in Frankreich, wobei ihr Schwerpunkt auf gro\u00dfen Vertr\u00e4gen im Wert von bis zu 200 Mio. Euro lag. Weiterhin war sie f\u00fcr den Aufbau der Rechtsabteilung bei UNILOG verantwortlich.<\/p><p>Von Logica wechselte Florence 2010 zu Infosys, wo sie als Head of Legal f\u00fcr die Region Frankreich fungierte. Hier entwickelte und implementierte sie die juristischen Strategien der Organisation in Frankreich, insbesondere hinsichtlich Schutzrechten, Patenten und Lizenzen. 2013 \u00fcbernahm Florence bei Capgemini die Aufgabe der General Counsel, Ethics &amp; Compliance Officer f\u00fcr Frankreich und Marokko, trieb die Transformation der Rechtsabteilung zu einem strategischen Ansprechpartner im Unternehmen voran und steuerte die Compliance der Organisation mit Datenschutzanforderungen inklusive der DSGVO.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b598e7b gg-font-v4 gg-custom-dark-purple-color elementor-widget elementor-widget-heading\" data-id=\"b598e7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pressekontakt<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1ef279 gg-font-v9 gg-class-for-iphone8  elementor-widget elementor-widget-text-editor\" data-id=\"e1ef279\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Expleo<\/strong><br \/>Valentine Eman<br \/>Head of Corporate Communications<br \/><a href=\"mailto:valentine.eman@expleogroup.com\">valentine.eman@expleogroup.com<\/a><br \/>+33 (0) 6 71 15 99 61<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Paris, 15. Februar 2021 \u2013 Das Supervisory Board von Expleo hat mit sofortiger Wirkung Florence Bigot zur Group General Secretary und Group General Counsel ernannt und als Justiziarin der Gruppe in das Executive Board berufen. Florence Bigot folgt damit Nathalie Gicquel nach, die Karrierechancen au\u00dferhalb der Gruppe wahrnehmen wird.<\/p>\n","protected":false},"featured_media":824,"parent":0,"template":"","meta":{"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","footnotes":""},"topic":[114],"insights-single-templates":[386],"industry-taxonomy":[293],"content-type":[20],"country":[113],"service":[],"class_list":["post-831","insights","type-insights","status-publish","has-post-thumbnail","hentry","topic-mitarbeiter-und-management","insights-single-templates-old-template","industry-taxonomy-all","content-type-neuigkeiten","country-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Expleo | Florence Bigot zur General Secretary<\/title>\n<meta name=\"description\" content=\"Das Supervisory Board von Expleo hat mit sofortiger Wirkung Florence Bigot zur Group General Secretary und Group General Counsel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expleo beruft Florence Bigot zur General Secretary und General Counsel\" \/>\n<meta property=\"og:description\" content=\"Das Supervisory Board von Expleo hat mit sofortiger Wirkung Florence Bigot zur Group General Secretary und Group General Counsel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\/\" \/>\n<meta property=\"og:site_name\" content=\"Global DE\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-14T09:29:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/florence-bigot-1280x720-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\\\/\",\"name\":\"Expleo | Florence Bigot zur General Secretary\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/florence-bigot-1280x720-1.jpg\",\"datePublished\":\"2021-02-15T16:20:00+00:00\",\"dateModified\":\"2024-02-14T09:29:28+00:00\",\"description\":\"Das Supervisory Board von Expleo hat mit sofortiger Wirkung Florence Bigot zur Group General Secretary und Group General Counsel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/florence-bigot-1280x720-1.jpg\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/florence-bigot-1280x720-1.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Florence Bigot\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/neuigkeiten\\\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Einblicke\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/einblicke\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Expleo beruft Florence Bigot zur General Secretary und General Counsel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\",\"name\":\"Expleo | DE\",\"description\":\"Expleo\",\"publisher\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#organization\",\"name\":\"Expleo | DE\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"width\":1600,\"height\":774,\"caption\":\"Expleo | DE\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Expleo | Florence Bigot zur General Secretary","description":"Das Supervisory Board von Expleo hat mit sofortiger Wirkung Florence Bigot zur Group General Secretary und Group General Counsel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\/","og_locale":"de_DE","og_type":"article","og_title":"Expleo beruft Florence Bigot zur General Secretary und General Counsel","og_description":"Das Supervisory Board von Expleo hat mit sofortiger Wirkung Florence Bigot zur Group General Secretary und Group General Counsel.","og_url":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\/","og_site_name":"Global DE","article_modified_time":"2024-02-14T09:29:28+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/florence-bigot-1280x720-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\/","url":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\/","name":"Expleo | Florence Bigot zur General Secretary","isPartOf":{"@id":"https:\/\/expleo.com\/global\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\/#primaryimage"},"image":{"@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\/#primaryimage"},"thumbnailUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/florence-bigot-1280x720-1.jpg","datePublished":"2021-02-15T16:20:00+00:00","dateModified":"2024-02-14T09:29:28+00:00","description":"Das Supervisory Board von Expleo hat mit sofortiger Wirkung Florence Bigot zur Group General Secretary und Group General Counsel.","breadcrumb":{"@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\/#primaryimage","url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/florence-bigot-1280x720-1.jpg","contentUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2021\/10\/florence-bigot-1280x720-1.jpg","width":1280,"height":720,"caption":"Florence Bigot"},{"@type":"BreadcrumbList","@id":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expleo.com\/global\/de\/"},{"@type":"ListItem","position":2,"name":"Einblicke","item":"https:\/\/expleo.com\/global\/de\/einblicke\/"},{"@type":"ListItem","position":3,"name":"Expleo beruft Florence Bigot zur General Secretary und General Counsel"}]},{"@type":"WebSite","@id":"https:\/\/expleo.com\/global\/de\/#website","url":"https:\/\/expleo.com\/global\/de\/","name":"Expleo | DE","description":"Expleo","publisher":{"@id":"https:\/\/expleo.com\/global\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expleo.com\/global\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/expleo.com\/global\/de\/#organization","name":"Expleo | DE","url":"https:\/\/expleo.com\/global\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/expleo.com\/global\/de\/#\/schema\/logo\/image\/","url":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","contentUrl":"https:\/\/expleo.com\/global\/de\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","width":1600,"height":774,"caption":"Expleo | DE"},"image":{"@id":"https:\/\/expleo.com\/global\/de\/#\/schema\/logo\/image\/"}}]}},"hreflang":{"rendered":"<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/einblicke\/news\/florence-bigot-appointed-group-general-secretary-and-general-counsel\/\" hreflang=\"x-default\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/einblicke\/news\/florence-bigot-appointed-group-general-secretary-and-general-counsel\/\" hreflang=\"en\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/fr\/einblicke\/actualite\/florence-bigot-nommee-secretaire-generale-et-directrice-juridique-dexpleo\/\" hreflang=\"fr\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\/\" hreflang=\"de\"\/>\n","structure":[{"blogId":4,"blogIsHidden":false,"postId":906,"url":"https:\/\/expleo.com\/global\/en\/einblicke\/news\/florence-bigot-appointed-group-general-secretary-and-general-counsel\/","language":"en","default":true},{"blogId":5,"blogIsHidden":false,"postId":844,"url":"https:\/\/expleo.com\/global\/fr\/einblicke\/actualite\/florence-bigot-nommee-secretaire-generale-et-directrice-juridique-dexpleo\/","language":"fr","default":false},{"blogId":6,"blogIsHidden":false,"postId":831,"url":"https:\/\/expleo.com\/global\/de\/einblicke\/neuigkeiten\/expleo-beruft-florence-bigot-zur-general-secretary-und-general-counsel\/","language":"de","default":false}]},"_links":{"self":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights\/831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/types\/insights"}],"version-history":[{"count":0,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights\/831\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/media\/824"}],"wp:attachment":[{"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/media?parent=831"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/topic?post=831"},{"taxonomy":"insights-single-templates","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/insights-single-templates?post=831"},{"taxonomy":"industry-taxonomy","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/industry-taxonomy?post=831"},{"taxonomy":"content-type","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/content-type?post=831"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/country?post=831"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/expleo.com\/global\/de\/wp-json\/wp\/v2\/service?post=831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}