{"id":37529,"date":"2022-08-15T08:40:21","date_gmt":"2022-08-15T08:40:21","guid":{"rendered":"https:\/\/expleo.com\/global\/en\/?post_type=industries&#038;p=37529"},"modified":"2025-12-09T20:43:11","modified_gmt":"2025-12-09T20:43:11","slug":"marine","status":"publish","type":"industries","link":"https:\/\/expleo.com\/global\/en\/industries\/marine\/","title":{"rendered":"Marine"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"37529\" class=\"elementor elementor-37529\" data-elementor-post-type=\"industries\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ab5f5e gg-sticky-subnav-container sticky-nav-link-tracking elementor-hidden-mobile elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6ab5f5e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ed23cd1 gg-sticky-subnav-column\" data-id=\"ed23cd1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0fe0e31 gg-sticky-subnav-links gg-container-small elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0fe0e31\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5ad2737\" data-id=\"5ad2737\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1cbfb4 elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f1cbfb4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#overview\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Overview<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#solutions\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Solutions<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#services\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Services<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#case\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Case studies<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#get-in-touch\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Get in Touch<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-291f6d0 gg-sticky-subnav-replacement elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"291f6d0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3319add\" data-id=\"3319add\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f95aa1b gg-article-content gg-article-content gg-container-small-ptb-96 gg-simple-cta-section-white-v2  gg-scroll-to-section elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f95aa1b\" data-element_type=\"section\" data-e-type=\"section\" id=\"overview\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c61358\" data-id=\"2c61358\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c4e8f5 gg-tagline-heading-left  elementor-widget elementor-widget-heading\" data-id=\"7c4e8f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">GAIN A TRUSTED TECHNOLOGY PARTNER<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64414e6 gg-heading gg-font-v2 elementor-widget elementor-widget-heading\" data-id=\"64414e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Modernising and transforming naval defence through engineering excellence <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51e0009 gg-font-v9 elementor-widget elementor-widget-text-editor\" data-id=\"51e0009\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"TextRun SCXW247355399 BCX8\" lang=\"EN-GB\" xml:lang=\"EN-GB\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW247355399 BCX8\">Keep pace with demand for the next generation of ships and submarines whilst harnessing technological advances in complex programmes. <\/span><\/span><\/p><p><span class=\"TextRun SCXW247355399 BCX8\" lang=\"EN-GB\" xml:lang=\"EN-GB\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW247355399 BCX8\">We deliver naval engineering <\/span><span class=\"NormalTextRun SCXW247355399 BCX8\">expertise<\/span><span class=\"NormalTextRun SCXW247355399 BCX8\"> that finds the pathway forward with the best in innovation and technology, while optimising operational efficiency through digitalisation of data.<\/span><\/span><span class=\"EOP SCXW247355399 BCX8\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:720,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb6d331 gg-image-with-overalpping-text gg-image-with-overalpping-text-v1 gg-container-large elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb6d331\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-08e575c\" data-id=\"08e575c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb30bd6 gg-image-with-overalpping-text__tagline gg-font-v33 elementor-widget elementor-widget-heading\" data-id=\"cb30bd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Featured<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf002cf gg-image-with-overalpping-text__heading elementor-widget elementor-widget-heading\" data-id=\"cf002cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">How to make progress <br>across your entire life cycle <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07eacd7 gg-button-v3 elementor-widget elementor-widget-button\" data-id=\"07eacd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/expleo.com\/global\/en\/insights\/campaigns\/marine-digital-engineering-now\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DISCOVER<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54a755e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54a755e\" data-element_type=\"section\" data-e-type=\"section\" id=\"solutions\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-141f50c\" data-id=\"141f50c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86c5b0d elementor-widget elementor-widget-solution_tab\" data-id=\"86c5b0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"solution_tab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"solution-explore-tabs\" class=\"solution-explore-widget\"><h2 class=\"solution-module-title\">Deliver more for less, faster than ever<\/h2><p class=\"solution-module-sub-heading\"><\/p><div class=\"solution-tabs-wrap\"><ul class=\"solution-tabs-list\" role=\"tablist\"><li class=\"solution-tab solution-tab-active\" data-index=\"0\"><button type=\"button\" class=\"solution-tab-btn\">OPTIMISING OPERATIONAL EFFICIENCY<\/button><\/li><li class=\"solution-tab\" data-index=\"1\"><button type=\"button\" class=\"solution-tab-btn\">COMPLEX SYSTEMS DELIVERY<\/button><\/li><li class=\"solution-tab\" data-index=\"2\"><button type=\"button\" class=\"solution-tab-btn\">TRANSFORMING DELIVERY CAPABILITY<\/button><\/li><\/ul><p class=\"module-dropdown-title\">Select a solution<\/p><select class=\"solution-tabs-dropdown\"><option value=\"0\" selected>OPTIMISING OPERATIONAL EFFICIENCY<\/option><option value=\"1\" >COMPLEX SYSTEMS DELIVERY<\/option><option value=\"2\" >TRANSFORMING DELIVERY CAPABILITY<\/option><\/select><\/div><div class=\"solution-card-container\"><article class=\"solution-card solution-card--active\" data-index=\"0\"><figure class=\"solution-card-image\"><picture><source media=\"(max-width:767px)\" srcset=\"https:\/\/expleo.com\/global\/en\/wp-content\/uploads\/2021\/10\/industries-naval-solution-transforming-delivery-capability_1280x720.jpg\"><source media=\"(max-width:1024px)\" srcset=\"https:\/\/expleo.com\/global\/en\/wp-content\/uploads\/2021\/10\/industries-naval-solution-transforming-delivery-capability_1280x720.jpg\"><img decoding=\"async\" src=\"https:\/\/expleo.com\/global\/en\/wp-content\/uploads\/2022\/08\/industries-naval-solution-transforming-delivery-capability_square.jpg\" alt=\"\"><\/picture><\/figure><div class=\"solution-card-content\"><h3 class=\"solution-card-title\">Optimise operational efficiency through digitalisation of data<\/h3><div class=\"solution-card-desc\">We develop data driven solutions that enhance your abilities to deliver value and improve performance in real time.\u202fUsing our proven digital transformation capabilities\u202fin Hyper Automation, Data Analytics, Digital Twins and Machine Learning, we help automate repetitive tasks and optimise complex processes, improving the quality and integrity of decision making while reducing overall time to market. <\/div><\/div><\/article><article class=\"solution-card\" data-index=\"1\"><figure class=\"solution-card-image\"><picture><img decoding=\"async\" src=\"https:\/\/expleo.com\/global\/en\/wp-content\/uploads\/2022\/08\/data-complexity-infographic_1280x720.jpg\" alt=\"\"><\/picture><\/figure><div class=\"solution-card-content\"><h3 class=\"solution-card-title\">Tackling complex systems delivery in highly regulated environments<\/h3><div class=\"solution-card-desc\">Manage\u202fcomplexity\u202fof systems architectures\u202fto keep pace in an ever-shifting technological landscape. We help our clients define, develop, and integrate safety-critical systems using a rigorous approach, ensuring inter-connectivity across your systems, maintaining data protection and\u202fstrict security\u202fprotocols\u202fagainst external threats. <\/div><\/div><\/article><article class=\"solution-card\" data-index=\"2\"><figure class=\"solution-card-image\"><picture><img decoding=\"async\" src=\"https:\/\/expleo.com\/global\/en\/wp-content\/uploads\/2022\/08\/ship-full-speed-ahead-1280x720-1.jpg\" alt=\"\"><\/picture><\/figure><div class=\"solution-card-content\"><h3 class=\"solution-card-title\">Transforming your naval engineering delivery capability<\/h3><div class=\"solution-card-desc\">Drive operational excellence for enduring performance. Our trusted team\u202fbring\u202fthe cross-industry experience, credibility and capability to accelerate your critical-path. Through our engineering expertise, we work with our customers to drive value and increase their competitive edge to help deliver sooner, smarter, better. <\/div><\/div><\/article><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7955e49 service-exploration-component gg-pt-96 gg-pb-96 gg-scroll-to-section elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7955e49\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45e5fc6 service-exploration-component__column\" data-id=\"45e5fc6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbd841e service-exploration-component__heading-v2 e-transform elementor-widget elementor-widget-heading\" data-id=\"cbd841e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_transform_translateX_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateX_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_translateY_effect_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wide range of Services to drive your success<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"jet-tabs-navigation-enabled elementor-element elementor-element-9301a63 service-exploration-component__tabs-v2 elementor-widget elementor-widget-jet-tabs\" data-id=\"9301a63\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;tabs_position&quot;:&quot;left&quot;,&quot;tabs_position_mobile&quot;:&quot;top&quot;}\" data-widget_type=\"jet-tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"jet-tabs jet-tabs-position-left jet-tabs-move-up-effect \" data-settings=\"{&quot;activeIndex&quot;:0,&quot;event&quot;:&quot;hover&quot;,&quot;autoSwitch&quot;:false,&quot;autoSwitchDelay&quot;:3000,&quot;ajaxTemplate&quot;:false,&quot;tabsPosition&quot;:&quot;left&quot;,&quot;switchScrolling&quot;:false,&quot;switchScrollingOffset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"jet-tabs__control-wrapper\" role=\"tablist\">\n\n                                    <div class=\"elementor-repeater-item-f308df0 elementor-repeater-item-f308df0 jet-tabs__control jet-tabs__control-icon-left elementor-menu-anchor active-tab \" id=\"jet-tabs-control-1541\" data-tab=\"1\" tabindex=\"0\" role=\"tab\" aria-controls=\"jet-tabs-content-1541\" aria-expanded=\"true\" data-template-id=\"58441\"><div class=\"jet-tabs__control-inner\"><div class=\"jet-tabs__label-icon jet-tabs-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"28\" viewBox=\"0 0 28 28\" fill=\"none\"><path d=\"M10.2482 7.08397C8.00815 8.39997 6.60815 10.836 6.63615 13.44C6.63615 16.016 7.98015 18.396 10.1642 19.712V20.636C9.80015 20.804 9.57615 21.168 9.63215 21.588L9.88415 23.52C10.2202 25.732 12.2922 27.272 14.5042 26.936C16.2682 26.684 17.6682 25.284 17.9202 23.52L18.2002 21.56C18.2562 21.168 18.0322 20.776 17.6682 20.608V19.684C21.1682 17.64 22.3162 13.16 20.2722 9.65997C18.2282 6.18797 13.7482 5.03997 10.2482 7.08397ZM13.4682 13.468C13.4682 13.216 13.6922 12.992 13.9442 12.992C14.1962 12.992 14.4202 13.216 14.4202 13.468C14.4202 13.72 14.1962 13.944 13.9442 13.944C13.6922 13.944 13.4682 13.748 13.4682 13.468ZM16.4082 18.424C16.1002 18.592 15.9042 18.928 15.9322 19.292V20.552H14.8122V15.54C15.9322 15.064 16.4642 13.748 15.9882 12.6C15.5122 11.452 14.1962 10.948 13.0482 11.424C11.9002 11.9 11.3962 13.216 11.8722 14.364C12.0962 14.896 12.5162 15.316 13.0482 15.54V20.58H11.9282V19.32C11.9562 18.956 11.7602 18.62 11.4522 18.452C8.70815 17.08 7.58815 13.748 8.96015 10.976C9.91215 9.09997 11.8162 7.89597 13.9162 7.89597C16.9962 7.92397 19.4322 10.472 19.4042 13.524C19.4042 15.596 18.2282 17.472 16.4082 18.424Z\" fill=\"white\"><\/path><path d=\"M13.9439 5.06777C14.4198 5.06777 14.8398 4.67577 14.8398 4.19977V1.70777C14.8398 1.23177 14.4478 0.811768 13.9439 0.811768C13.4399 0.811768 13.0479 1.20377 13.0479 1.70777V4.17177C13.0479 4.67577 13.4399 5.06777 13.9439 5.06777Z\" fill=\"white\"><\/path><path d=\"M20.748 7.5882C20.804 7.5322 20.86 7.4762 20.916 7.4202L22.6521 5.6842C22.9881 5.3482 22.9881 4.7882 22.6521 4.4522C22.3161 4.1162 21.756 4.1162 21.42 4.4522L19.684 6.1882C19.292 6.4682 19.208 7.0282 19.516 7.4202C19.796 7.81219 20.356 7.89619 20.748 7.5882Z\" fill=\"white\"><\/path><path d=\"M5.2358 5.68387L6.9718 7.41987C7.2518 7.81187 7.8118 7.89587 8.2038 7.58787C8.5958 7.30787 8.6798 6.74787 8.3718 6.35587C8.3158 6.29987 8.2598 6.21587 8.2038 6.18787L6.4678 4.45187C6.1878 4.05987 5.6278 3.97587 5.2358 4.28387C4.8438 4.59187 4.7598 5.12387 5.0678 5.51587C5.0958 5.57187 5.1518 5.62787 5.2358 5.68387Z\" fill=\"white\"><\/path><\/svg><\/div><div class=\"jet-tabs__label-text\">Innovation research &amp; technology<\/div><\/div><\/div><div class=\"elementor-repeater-item-0cc53c1 elementor-repeater-item-0cc53c1 jet-tabs__control jet-tabs__control-icon-left elementor-menu-anchor  \" id=\"jet-tabs-control-1542\" data-tab=\"2\" tabindex=\"0\" role=\"tab\" aria-controls=\"jet-tabs-content-1542\" aria-expanded=\"false\" data-template-id=\"58444\"><div class=\"jet-tabs__control-inner\"><div class=\"jet-tabs__label-icon jet-tabs-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"28\" viewBox=\"0 0 28 28\" fill=\"none\"><path d=\"M13.7488 6.91607C15.0323 6.91607 16.0728 5.87558 16.0728 4.59207C16.0728 3.30856 15.0323 2.26807 13.7488 2.26807C12.4653 2.26807 11.4248 3.30856 11.4248 4.59207C11.4248 5.87558 12.4653 6.91607 13.7488 6.91607Z\" fill=\"white\"><\/path><path d=\"M10.2769 12.712H17.2209C17.9209 12.712 18.3689 12.236 18.3689 11.564V10.976C18.3689 9.35204 17.1089 8.09204 15.4849 8.09204H12.0129C10.3889 8.09204 9.12891 9.38004 9.12891 10.976V11.564C9.12891 12.236 9.57691 12.712 10.2769 12.712Z\" fill=\"white\"><\/path><path d=\"M6.80447 19.6561C8.08798 19.6561 9.12847 18.6156 9.12847 17.3321C9.12847 16.0485 8.08798 15.0081 6.80447 15.0081C5.52096 15.0081 4.48047 16.0485 4.48047 17.3321C4.48047 18.6156 5.52096 19.6561 6.80447 19.6561Z\" fill=\"white\"><\/path><path d=\"M8.54057 20.804H5.06857C3.44457 20.804 2.18457 22.092 2.18457 23.688V24.276C2.18457 24.976 2.63257 25.424 3.33257 25.424H10.2766C10.9766 25.424 11.4246 24.948 11.4246 24.276V23.688C11.4526 22.064 10.1646 20.804 8.54057 20.804Z\" fill=\"white\"><\/path><path d=\"M20.6922 19.6558C21.9757 19.6558 23.0162 18.6153 23.0162 17.3318C23.0162 16.0483 21.9757 15.0078 20.6922 15.0078C19.4087 15.0078 18.3682 16.0483 18.3682 17.3318C18.3682 18.6153 19.4087 19.6558 20.6922 19.6558Z\" fill=\"white\"><\/path><path d=\"M22.4283 20.8037H18.9563C17.3323 20.8037 16.0723 22.0917 16.0723 23.6877V24.2757C16.0723 24.9757 16.5483 25.4237 17.2203 25.4237H24.1643C24.8643 25.4237 25.3123 24.9477 25.3123 24.2757V23.6877C25.3403 22.0637 24.0523 20.8037 22.4283 20.8037Z\" fill=\"white\"><\/path><path d=\"M16.465 17.5564L14.925 16.6324V15.0084C14.925 14.3644 14.421 13.8604 13.777 13.8604C13.133 13.8604 12.629 14.3644 12.629 15.0084V16.6324L11.089 17.5564C10.529 17.8924 10.361 18.5924 10.669 19.1244C10.977 19.6564 11.677 19.8524 12.209 19.5444L13.777 18.6764L15.345 19.5444C15.905 19.8524 16.577 19.6564 16.885 19.1244C17.193 18.5924 17.025 17.8644 16.465 17.5564Z\" fill=\"white\"><\/path><\/svg><\/div><div class=\"jet-tabs__label-text\">Transformation consultancy<\/div><\/div><\/div><div class=\"elementor-repeater-item-0aff5b2 elementor-repeater-item-0aff5b2 jet-tabs__control jet-tabs__control-icon-left elementor-menu-anchor  \" id=\"jet-tabs-control-1543\" data-tab=\"3\" tabindex=\"0\" role=\"tab\" aria-controls=\"jet-tabs-content-1543\" aria-expanded=\"false\" data-template-id=\"58498\"><div class=\"jet-tabs__control-inner\"><div class=\"jet-tabs__label-icon jet-tabs-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"28\" viewBox=\"0 0 28 28\" fill=\"none\"><path d=\"M24.0803 21.3359C24.0803 20.7759 23.9963 20.2719 23.8283 19.7679C23.8003 19.6839 23.7723 19.5999 23.7443 19.4879L21.4763 13.6639C21.4763 13.6639 21.0283 12.5159 19.8803 12.9639L19.8243 12.9919C19.8243 12.9919 19.1523 13.2719 19.0403 13.9159L18.8163 13.3559C18.8163 13.3559 18.3683 12.2079 17.2203 12.6559L17.1643 12.6839C17.1643 12.6839 16.2403 13.0479 16.3803 13.9439C16.1563 13.6639 15.7083 13.3279 15.0083 13.6079L14.9523 13.6359C14.9523 13.6359 14.2803 13.8879 14.1683 14.5319L12.0403 8.98788C12.0403 8.98788 11.5363 7.69988 10.2763 8.20388L10.2203 8.23188C10.2203 8.23188 8.9323 8.73588 9.4363 9.99588L13.5803 20.7479L11.6763 19.7119C11.6763 19.7119 10.3883 19.0119 9.6883 20.2999L9.6603 20.3279C9.6603 20.3279 8.9603 21.6159 10.2483 22.3159L15.8203 25.3119C16.6883 26.0399 17.7803 26.4599 18.9843 26.4599C21.8403 26.4879 24.0803 24.1919 24.0803 21.3359Z\" fill=\"white\"><\/path><path d=\"M10.3042 3.44385C7.72825 3.44385 5.65625 5.54385 5.65625 8.11985C5.65625 9.88385 6.69225 11.5358 8.28825 12.3198C8.37225 12.3478 8.42825 12.3758 8.54025 12.3758C8.73625 12.3758 8.93225 12.2638 9.01625 12.0678C9.15625 11.7878 9.04425 11.4798 8.76425 11.3398C7.53225 10.7518 6.72025 9.49185 6.72025 8.11985C6.72025 6.13185 8.31625 4.53585 10.3042 4.53585C12.2922 4.53585 13.8882 6.15985 13.8882 8.11985C13.8882 8.23185 13.8882 8.31585 13.8602 8.42785V8.45585C13.8042 8.76385 13.6922 9.09985 13.5522 9.40785C13.4962 9.54785 13.4682 9.68785 13.5242 9.82785C13.5802 9.96785 13.6642 10.0798 13.8042 10.1358C14.0562 10.2758 14.3922 10.1638 14.5322 9.91185C14.7002 9.57585 14.8402 9.21185 14.9242 8.84785C14.9522 8.81985 14.9522 8.76385 14.9802 8.70785C15.0082 8.53985 15.0082 8.34385 15.0082 8.14785C14.9802 5.54385 12.8802 3.44385 10.3042 3.44385Z\" fill=\"white\"><\/path><path d=\"M10.304 1.23193C6.52401 1.23193 3.41602 4.31193 3.41602 8.11993C3.41602 11.5639 5.96402 14.4759 9.38001 14.9239C9.40801 14.9239 9.43601 14.9239 9.46401 14.9239C9.74401 14.9239 9.96801 14.7279 9.99602 14.4479C10.024 14.3079 9.96801 14.1679 9.88401 14.0559C9.80001 13.9439 9.66001 13.8599 9.52001 13.8599C6.66402 13.4679 4.50802 11.0039 4.50802 8.11993C4.50802 4.92793 7.11202 2.32393 10.304 2.32393C13.496 2.32393 16.1 4.92793 16.1 8.11993C16.1 9.21193 15.792 10.2759 15.232 11.1719C15.064 11.4239 15.148 11.7599 15.4 11.9279C15.512 12.0119 15.68 12.0399 15.82 11.9839C15.96 11.9559 16.072 11.8719 16.156 11.7319C16.828 10.6399 17.192 9.37993 17.192 8.09193C17.192 4.31193 14.084 1.23193 10.304 1.23193Z\" fill=\"white\"><\/path><\/svg><\/div><div class=\"jet-tabs__label-text\">AI &amp; digital transformation<\/div><\/div><\/div><div class=\"elementor-repeater-item-4e436bc elementor-repeater-item-4e436bc jet-tabs__control jet-tabs__control-icon-left elementor-menu-anchor  \" id=\"jet-tabs-control-1544\" data-tab=\"4\" tabindex=\"0\" role=\"tab\" aria-controls=\"jet-tabs-content-1544\" aria-expanded=\"false\" data-template-id=\"58509\"><div class=\"jet-tabs__control-inner\"><div class=\"jet-tabs__label-icon jet-tabs-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"28\" viewBox=\"0 0 28 28\" fill=\"none\"><path d=\"M19.9925 22.6242C19.6005 22.6802 19.1805 22.5402 18.9005 22.2042C18.4805 21.7002 18.5645 20.9722 19.0685 20.5522C19.7125 20.0202 20.3005 19.3762 20.7765 18.6762C21.9525 16.9122 22.4285 14.7842 22.0925 12.6562C21.3645 8.06418 17.0245 4.92818 12.4325 5.68418C11.7885 5.79618 11.2005 5.34818 11.0885 4.70418C10.9765 4.06018 11.4245 3.47218 12.0685 3.36018C17.8925 2.46418 23.4365 6.46818 24.3885 12.3202C24.8085 15.0082 24.2205 17.7242 22.7365 19.9922C22.1485 20.8882 21.4205 21.7002 20.5805 22.3722C20.3845 22.5122 20.1885 22.5962 19.9925 22.6242Z\" fill=\"white\"><\/path><path d=\"M16.1556 24.276C16.4636 24.024 16.6316 23.604 16.5756 23.184C16.4636 22.54 15.8756 22.12 15.2316 22.204C14.3916 22.344 13.5516 22.344 12.7116 22.232C10.6116 21.952 8.70762 20.86 7.36362 19.208C4.42362 15.596 4.95562 10.276 8.56762 7.33599C9.07162 6.91599 9.15562 6.18799 8.73562 5.68399C8.31562 5.17999 7.58762 5.09599 7.08362 5.51599C2.43562 9.32399 1.76362 16.128 5.51562 20.72C7.25162 22.82 9.65962 24.192 12.3756 24.584C13.4396 24.724 14.5316 24.724 15.5956 24.556C15.7916 24.5 15.9876 24.416 16.1556 24.276Z\" fill=\"white\"><\/path><path d=\"M19.0964 14.868L18.5644 14.672C18.3404 14.588 18.1724 14.336 18.2004 14.112V13.664C18.1724 13.44 18.3124 13.188 18.5364 13.076L19.0684 12.824C19.2644 12.74 19.4044 12.488 19.3204 12.264C19.3204 12.264 19.2364 11.956 19.0684 11.62C18.9004 11.284 18.7324 11.004 18.7324 11.004C18.5924 10.808 18.3404 10.724 18.1444 10.836L17.6124 11.088C17.4164 11.172 17.1084 11.116 16.9684 10.948L16.5764 10.64C16.4084 10.5 16.3244 10.192 16.4084 9.99601L16.6044 9.46401C16.6884 9.24001 16.5764 9.01601 16.3804 8.90401L15.0644 8.40001C14.8404 8.34401 14.6164 8.45601 14.5324 8.68001L14.3364 9.21201C14.2524 9.43601 14.0004 9.57601 13.7764 9.57601H13.3284C13.1044 9.60401 12.8524 9.46401 12.7404 9.24001L12.4884 8.70801C12.4044 8.51201 12.1244 8.37201 11.9284 8.45601C11.9284 8.45601 11.6204 8.54001 11.2844 8.68001C10.9484 8.84801 10.6684 8.98801 10.6684 8.98801C10.4724 9.12801 10.3884 9.38001 10.5004 9.57601L10.7524 10.108C10.8364 10.304 10.7804 10.612 10.6124 10.752L10.3044 11.088C10.1644 11.256 9.8844 11.34 9.6604 11.256L9.1284 11.06C8.9044 10.976 8.6524 11.088 8.5684 11.284L8.0924 12.572C8.0364 12.796 8.1484 13.02 8.3724 13.104L8.9044 13.3C9.1284 13.384 9.2964 13.636 9.2684 13.86V14.308C9.2964 14.532 9.1564 14.784 8.9324 14.896L8.4004 15.204C8.2044 15.288 8.0644 15.54 8.1484 15.764C8.1484 15.764 8.2324 16.072 8.4004 16.408C8.5684 16.744 8.7364 17.024 8.7364 17.024C8.8764 17.22 9.1284 17.304 9.3244 17.192L9.8564 16.94C10.0524 16.856 10.3604 16.912 10.5004 17.08L10.8364 17.388C11.0044 17.528 11.0884 17.836 11.0044 18.032L10.8084 18.564C10.7244 18.788 10.8364 19.012 11.0324 19.124L12.3204 19.6C12.5444 19.656 12.7684 19.544 12.8524 19.32L13.0484 18.788C13.1324 18.564 13.3844 18.424 13.6084 18.424H14.0564C14.2804 18.396 14.5324 18.536 14.6444 18.76L14.8964 19.292C14.9804 19.488 15.2324 19.628 15.4564 19.544C15.4564 19.544 15.7644 19.46 16.1004 19.32C16.4364 19.152 16.7164 19.012 16.7164 19.012C16.9124 18.872 16.9964 18.62 16.8844 18.424L16.6324 17.892C16.5484 17.696 16.6044 17.388 16.7724 17.248L17.0804 16.912C17.2204 16.744 17.5004 16.66 17.7244 16.744L18.2564 16.94C18.4804 17.024 18.7324 16.912 18.8164 16.716L19.2924 15.428C19.4324 15.176 19.3204 14.924 19.0964 14.868ZM14.5884 15.876C13.5524 16.352 12.3204 15.876 11.8444 14.84C11.3684 13.804 11.8164 12.6 12.8524 12.124C13.8884 11.648 15.1204 12.124 15.5964 13.16C16.0724 14.196 15.6244 15.4 14.5884 15.876Z\" fill=\"white\"><\/path><path d=\"M13.8603 7.41986C13.6643 7.41986 13.4683 7.36386 13.3003 7.22386L10.8083 5.09586C10.6123 4.92786 10.5283 4.70386 10.5283 4.45186C10.5283 4.19986 10.6403 3.97586 10.8083 3.80786L13.3003 1.62386C13.6363 1.31586 14.1683 1.34386 14.4763 1.70786C14.7843 2.04386 14.7563 2.57586 14.3923 2.88386L12.6283 4.42386L14.3923 5.93586C14.7563 6.24386 14.7843 6.77586 14.4763 7.11186C14.3363 7.33586 14.1123 7.41986 13.8603 7.41986Z\" fill=\"white\"><\/path><path d=\"M13.7483 26.6001C13.5243 26.6001 13.2723 26.5161 13.1043 26.3201C12.7963 25.9841 12.8243 25.4521 13.1883 25.1441L14.9523 23.6041L13.1883 22.0921C12.8243 21.7841 12.7963 21.2521 13.1043 20.9161C13.4123 20.5521 13.9443 20.5241 14.2803 20.8321L16.7723 22.9601C16.9683 23.1281 17.0523 23.3521 17.0523 23.6041C17.0523 23.8561 16.9403 24.0801 16.7723 24.2481L14.2803 26.4321C14.1403 26.5441 13.9443 26.6001 13.7483 26.6001Z\" fill=\"white\"><\/path><\/svg><\/div><div class=\"jet-tabs__label-text\">Product engineering<\/div><\/div><\/div><div class=\"elementor-repeater-item-f357bdc elementor-repeater-item-f357bdc jet-tabs__control jet-tabs__control-icon-left elementor-menu-anchor  \" id=\"jet-tabs-control-1545\" data-tab=\"5\" tabindex=\"0\" role=\"tab\" aria-controls=\"jet-tabs-content-1545\" aria-expanded=\"false\" data-template-id=\"58512\"><div class=\"jet-tabs__control-inner\"><div class=\"jet-tabs__label-icon jet-tabs-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"28\" viewBox=\"0 0 28 28\" fill=\"none\"><path d=\"M21.6997 8.70803C20.4117 7.89603 18.8717 7.81203 17.5837 8.37203L14.9797 7.25203C14.9797 6.04803 14.3917 4.87203 13.2997 4.17203C12.4597 3.64003 11.4517 3.47203 10.5277 3.66803L9.96773 1.68003C9.88373 1.37203 9.57573 1.12003 9.21173 1.12003L6.43973 0.98003C5.99173 0.95203 5.59973 1.31603 5.57173 1.76403C5.54373 2.21203 5.90773 2.60403 6.35573 2.63203L8.53973 2.74403L9.01573 4.45203C8.73573 4.70403 8.45573 4.98403 8.23173 5.32003C8.00773 5.65603 7.86773 6.02003 7.78373 6.38403L6.04773 6.66403L5.03973 4.73203C4.81573 4.34003 4.33973 4.17203 3.91973 4.39603C3.52773 4.62003 3.35973 5.09603 3.58373 5.51603L4.87173 7.98003C4.92773 8.12003 5.03973 8.20403 5.15173 8.28803C5.31973 8.40003 5.51573 8.42803 5.71173 8.40003L7.75573 8.06403C7.95173 8.98803 8.51173 9.82803 9.35173 10.36C10.4437 11.06 11.7597 11.116 12.8517 10.612L14.9517 12.516C14.9797 13.552 15.3717 14.56 16.0717 15.344L12.9917 20.692C12.2357 21.616 12.9917 22.904 14.3077 22.904H18.7597C19.5997 22.904 20.3277 22.316 20.3557 21.588L20.7197 16.548C21.6157 16.24 22.4277 15.652 22.9877 14.784C24.3037 12.74 23.7157 10.024 21.6997 8.70803ZM12.6557 8.12003C12.1797 8.87603 11.1717 9.07203 10.4437 8.59603C9.68773 8.12003 9.49173 7.11203 9.96773 6.38403C10.4437 5.65603 11.4517 5.43203 12.1797 5.90803C12.9357 6.38403 13.1597 7.39203 12.6557 8.12003Z\" fill=\"white\"><\/path><path d=\"M20.9442 24.8359H12.3482C11.8162 24.8359 11.3682 25.2839 11.3682 25.8159C11.3682 26.3479 11.7882 26.7959 12.3482 26.7959H20.9162C21.4482 26.7959 21.8962 26.3479 21.8962 25.8159C21.8962 25.2839 21.4762 24.8359 20.9442 24.8359Z\" fill=\"white\"><\/path><\/svg><\/div><div class=\"jet-tabs__label-text\">Manufacturing &amp; supply chain<\/div><\/div><\/div><div class=\"elementor-repeater-item-756ee3b elementor-repeater-item-756ee3b jet-tabs__control jet-tabs__control-icon-left elementor-menu-anchor  \" id=\"jet-tabs-control-1546\" data-tab=\"6\" tabindex=\"0\" role=\"tab\" aria-controls=\"jet-tabs-content-1546\" aria-expanded=\"false\" data-template-id=\"58515\"><div class=\"jet-tabs__control-inner\"><div class=\"jet-tabs__label-icon jet-tabs-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"28\" viewBox=\"0 0 28 28\" fill=\"none\"><path d=\"M16.9959 24.304C17.4999 23.884 18.1439 23.576 18.8439 23.548L20.3559 23.436C21.9519 23.324 23.2119 22.064 23.2959 20.496L23.4079 18.984C23.4359 18.312 23.7439 17.668 24.1639 17.164L25.1719 16.016C26.2079 14.784 26.2079 13.02 25.1719 11.844L24.1639 10.696C23.7439 10.192 23.4359 9.548 23.4079 8.876L23.2959 7.364C23.1839 5.796 21.9239 4.536 20.3559 4.424L18.8439 4.312C18.1719 4.284 17.4999 3.976 17.0239 3.556L15.8759 2.548C14.6439 1.512 12.8799 1.512 11.7039 2.548L10.5559 3.444C10.0519 3.864 9.40786 4.172 8.73586 4.2L7.22386 4.312C5.65586 4.424 4.39586 5.684 4.28386 7.252L4.17186 8.764C4.14386 9.436 3.83586 10.108 3.41586 10.584L2.40786 11.732C1.37186 12.964 1.37186 14.728 2.40786 15.904L3.41586 17.052C3.83586 17.556 4.14386 18.2 4.17186 18.872L4.28386 20.384C4.39586 21.98 5.65586 23.24 7.22386 23.324L8.73586 23.436C9.40786 23.464 10.0799 23.772 10.5839 24.192L11.7319 25.2C12.9639 26.236 14.7279 26.236 15.9039 25.2L16.9959 24.304ZM6.99986 13.888C6.99986 10.136 10.0239 7.14 13.7479 7.14C17.4719 7.14 20.4959 10.164 20.4959 13.888C20.4959 17.612 17.4999 20.636 13.7479 20.636C9.99586 20.636 6.99986 17.584 6.99986 13.888Z\" fill=\"white\"><\/path><path d=\"M13.2998 16.744C13.0198 16.744 12.7398 16.632 12.5158 16.436L10.7798 14.7C10.3598 14.28 10.3598 13.58 10.7798 13.16C11.1998 12.74 11.8998 12.74 12.3198 13.16L13.2998 14.14L15.7918 11.648C16.2118 11.228 16.9118 11.228 17.3318 11.648C17.7518 12.068 17.7518 12.768 17.3318 13.188L14.0558 16.408C13.8598 16.632 13.5798 16.744 13.2998 16.744Z\" fill=\"white\"><\/path><\/svg><\/div><div class=\"jet-tabs__label-text\">Quality &amp; testing<\/div><\/div><\/div><div class=\"elementor-repeater-item-5de7163 elementor-repeater-item-5de7163 jet-tabs__control jet-tabs__control-icon-left elementor-menu-anchor  \" id=\"jet-tabs-control-1547\" data-tab=\"7\" tabindex=\"0\" role=\"tab\" aria-controls=\"jet-tabs-content-1547\" aria-expanded=\"false\" data-template-id=\"58518\"><div class=\"jet-tabs__control-inner\"><div class=\"jet-tabs__label-icon jet-tabs-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"28\" viewBox=\"0 0 28 28\" fill=\"none\"><path d=\"M16.5765 8.6239C18.4476 8.6239 19.9645 7.10704 19.9645 5.2359C19.9645 3.36476 18.4476 1.8479 16.5765 1.8479C14.7053 1.8479 13.1885 3.36476 13.1885 5.2359C13.1885 7.10704 14.7053 8.6239 16.5765 8.6239Z\" fill=\"white\"><\/path><path d=\"M11.508 17.0798H21.644C22.652 17.0798 23.324 16.4078 23.324 15.3998V14.5598C23.324 12.1798 21.448 10.3318 19.096 10.3318H14.056C11.676 10.3318 9.82796 12.2078 9.82796 14.5598V15.3998C9.79996 16.4078 10.5 17.0798 11.508 17.0798Z\" fill=\"white\"><\/path><path d=\"M25.0316 19.7961C24.6116 18.9561 23.6036 18.6201 22.7636 19.0121L20.1596 20.3281C20.2436 20.7481 20.3276 21.6441 19.7956 22.3721C19.3476 22.9601 18.6756 23.2401 17.7236 23.2401H13.4396C13.1036 23.2401 12.7956 22.9601 12.7956 22.5961C12.7956 22.2321 13.0756 21.9521 13.4396 21.9521H17.6956C17.7236 21.9521 17.7236 21.9521 17.7516 21.9521H17.9196C18.1156 21.9521 18.2836 21.8961 18.4236 21.8401C18.5356 21.7841 18.6196 21.7281 18.7036 21.6721C18.9556 21.4481 19.1236 21.1121 19.1236 20.7481C19.1236 20.0761 18.5916 19.5441 17.9196 19.5441H17.3596H16.5756H14.7556L13.8316 19.0401C12.9636 18.5641 11.9556 18.3121 10.9756 18.3121H9.04358V18.2841C9.04358 17.6121 8.51158 17.0801 7.83958 17.0801H3.47158C2.79958 17.0801 2.26758 17.6121 2.26758 18.2841V24.1641C2.26758 24.8361 2.79958 25.3681 3.47158 25.3681H7.83958C8.51158 25.3681 9.04358 24.8361 9.04358 24.1641L13.2156 25.5361C13.8316 25.7321 14.4756 25.8441 15.1196 25.8441C16.0156 25.8441 16.9116 25.6481 17.7236 25.2561L24.2476 22.0641C24.6396 21.8681 24.9476 21.5321 25.1156 21.0841C25.2556 20.6641 25.2276 20.2161 25.0316 19.7961Z\" fill=\"white\"><\/path><\/svg><\/div><div class=\"jet-tabs__label-text\">Customer support &amp; maintenance<\/div><\/div><\/div>\n                    \t\t\t    <\/div>\n\t\t\t<div class=\"jet-tabs__content-wrapper\">\n\t\t\t\t<div id=\"jet-tabs-content-1541\" class=\"jet-tabs__content active-content\" data-tab=\"1\" role=\"tabpanel\" aria-hidden=\"false\" data-template-id=\"58441\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"58441\" class=\"elementor elementor-58441\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-097f9f1 service-exploration-component-template elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"097f9f1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55e6858 service-exploration-component-column-second\" data-id=\"55e6858\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42708a3 service-exploration-component__template-heading gg-font-v4 elementor-widget elementor-widget-heading\" data-id=\"42708a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Innovation research &amp; technology<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f09443 service-exploration-component__description gg-font-v9 elementor-widget elementor-widget-text-editor\" data-id=\"0f09443\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>With our open innovation approach and cross-functional engineering-technology expertise, we help R&amp;T managers accelerate go-to-market innovations, stay ahead of the competition, and achieve Sustainable Development Goals (SDGs).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79dbd26 service-exploration-component__services gg-font-v12 elementor-widget elementor-widget-heading\" data-id=\"79dbd26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Services<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b19e63 service-exploration-component__list gg-font-v9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6b19e63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Green future<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Generative AI<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Digital twin<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Software-defined everything<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Safety and cybersecurity<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Reinventing the CX<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Autonomous collaboration<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23967a6 service-exploration-component__button gg-button-v3 elementor-widget elementor-widget-button\" data-id=\"23967a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/expleo.com\/global\/en\/about-us\/innovation-impact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discover these services<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div id=\"jet-tabs-content-1542\" class=\"jet-tabs__content \" data-tab=\"2\" role=\"tabpanel\" aria-hidden=\"true\" data-template-id=\"58444\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"58444\" class=\"elementor elementor-58444\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e651f1a service-exploration-component-template elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e651f1a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57a04ac service-exploration-component-column-second\" data-id=\"57a04ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16e0454 service-exploration-component__template-heading gg-font-v4 elementor-widget elementor-widget-heading\" data-id=\"16e0454\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Transformation Consultancy <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50ddce2 service-exploration-component__description gg-font-v9 elementor-widget elementor-widget-text-editor\" data-id=\"50ddce2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Our management consulting services are designed to help executives and managers navigate complex challenges across sectors, including automotive, aerospace, railway, defence, energy, banking, and insurance.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c8f0f9 service-exploration-component__services gg-font-v12 elementor-widget elementor-widget-heading\" data-id=\"8c8f0f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Services<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2eceb81 service-exploration-component__list gg-font-v9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2eceb81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sustainability strategy &amp; transformation\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Enterprise transformation\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Digital transformation strategy \u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">People &amp; change management<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Training &amp; upskilling\u200b - Expleo academy\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5ac237a service-exploration-component__button gg-button-v3 elementor-widget elementor-widget-button\" data-id=\"5ac237a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/expleo.com\/global\/en\/services\/transformation-consultancy\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discover these services<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div id=\"jet-tabs-content-1543\" class=\"jet-tabs__content \" data-tab=\"3\" role=\"tabpanel\" aria-hidden=\"true\" data-template-id=\"58498\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"58498\" class=\"elementor elementor-58498\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3251747 service-exploration-component-template elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3251747\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a8b1ab service-exploration-component-column-second\" data-id=\"3a8b1ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4e2aff service-exploration-component__template-heading gg-font-v4 elementor-widget elementor-widget-heading\" data-id=\"f4e2aff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AI &amp; digital transformation <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fad1846 service-exploration-component__description gg-font-v9 elementor-widget elementor-widget-text-editor\" data-id=\"fad1846\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>We help leading industries successfully navigate complex digital transformations and deliver measurable ROIs. Our services are designed to meet the needs of IT and digital departments, allowing them to better understand business operations and provide value revenue generation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cfa62c service-exploration-component__services gg-font-v12 elementor-widget elementor-widget-heading\" data-id=\"6cfa62c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Services<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-037f912 service-exploration-component__list gg-font-v9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"037f912\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Data analytics \u200b &amp; AI solutions\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">IT\/OT cybersecurity compliance &amp; risk management\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Application development\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cloud modernisation\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">AI-powered DevSecOps\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Tech-enabled business processes\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Application transformation assurance\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6c7cfb service-exploration-component__button gg-button-v3 elementor-widget elementor-widget-button\" data-id=\"b6c7cfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/expleo.com\/global\/en\/services\/digital-transformation\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discover these services<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div id=\"jet-tabs-content-1544\" class=\"jet-tabs__content \" data-tab=\"4\" role=\"tabpanel\" aria-hidden=\"true\" data-template-id=\"58509\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"58509\" class=\"elementor elementor-58509\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fd8a838 service-exploration-component-template elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd8a838\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b2652c service-exploration-component-column-second\" data-id=\"8b2652c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab2bd7b service-exploration-component__template-heading gg-font-v4 elementor-widget elementor-widget-heading\" data-id=\"ab2bd7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Product engineering<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d19f2de service-exploration-component__description gg-font-v9 elementor-widget elementor-widget-text-editor\" data-id=\"d19f2de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>We deliver comprehensive product engineering services to the automotive, aerospace, defence, railway, and energy industries. From design to certification, our cross-functional engineering teams ensure on-time, on-budget delivery of products, that meet end-user requirements.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65a22a3 service-exploration-component__services gg-font-v12 elementor-widget elementor-widget-heading\" data-id=\"65a22a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Services<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d9afb9 service-exploration-component__list gg-font-v9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"7d9afb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Embedded system design &amp; validation <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Shift to software-defined everything\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">MBSE &amp; MBD engineering\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Simulation &amp; analysis of complex structure\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">High-grade surface plastic solutions\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">RAMS &amp; FuSa of complex systems\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Flying engineers for embedded systems\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Electronic &amp; electrical design\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ba7220 service-exploration-component__button gg-button-v3 elementor-widget elementor-widget-button\" data-id=\"1ba7220\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/expleo.com\/global\/en\/services\/product-engineering\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discover these services<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div id=\"jet-tabs-content-1545\" class=\"jet-tabs__content \" data-tab=\"5\" role=\"tabpanel\" aria-hidden=\"true\" data-template-id=\"58512\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"58512\" class=\"elementor elementor-58512\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a6d574f service-exploration-component-template elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a6d574f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bc960b0 service-exploration-component-column-second\" data-id=\"bc960b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20bce87 service-exploration-component__template-heading gg-font-v4 elementor-widget elementor-widget-heading\" data-id=\"20bce87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Manufacturing &amp; supply chain<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97567a1 service-exploration-component__description gg-font-v9 elementor-widget elementor-widget-text-editor\" data-id=\"97567a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Our consultants and engineers help manufacturing companies achieve superior performance by securing supply chains and designing efficient tools and processes for operations.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45a767e service-exploration-component__services gg-font-v12 elementor-widget elementor-widget-heading\" data-id=\"45a767e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Services<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07ca47a service-exploration-component__list gg-font-v9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"07ca47a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Industrial start-up group\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Industrial automation system architecture &amp; commissioning\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Supply chain assessment &amp; recovery\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Industrial process development &amp; sustainability\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Industrial process operation &amp; optimisation\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Product industrial transfer \/ transfer of work<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Smart jigs &amp; tools solutions\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0492ca8 service-exploration-component__button gg-button-v3 elementor-widget elementor-widget-button\" data-id=\"0492ca8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/expleo.com\/global\/en\/services\/manufacturing-supply-chain\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discover these services<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div id=\"jet-tabs-content-1546\" class=\"jet-tabs__content \" data-tab=\"6\" role=\"tabpanel\" aria-hidden=\"true\" data-template-id=\"58515\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"58515\" class=\"elementor elementor-58515\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f55b255 service-exploration-component-template elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f55b255\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6193208 service-exploration-component-column-second\" data-id=\"6193208\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a3a363 service-exploration-component__template-heading gg-font-v4 elementor-widget elementor-widget-heading\" data-id=\"8a3a363\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quality &amp; testing<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-261e579 service-exploration-component__description gg-font-v9 elementor-widget elementor-widget-text-editor\" data-id=\"261e579\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>We support our clients through design, build, and operation to implement quality processes and ensure flawless products and bug-free applications.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09985f4 service-exploration-component__services gg-font-v12 elementor-widget elementor-widget-heading\" data-id=\"09985f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Services<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0baa5f9 service-exploration-component__list gg-font-v9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0baa5f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">AI-powered \u200b software QA\/QE\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Product penetration testing\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Electronic test bench solutions\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Integrated quality management for manufacturing\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">AI-powered visual inspection\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Regulatory compliance management for manufacturing\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Data integrity in the manufacturing process\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6119f80 service-exploration-component__button gg-button-v3 elementor-widget elementor-widget-button\" data-id=\"6119f80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/expleo.com\/global\/en\/services\/quality-and-testing\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discover these services<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div id=\"jet-tabs-content-1547\" class=\"jet-tabs__content \" data-tab=\"7\" role=\"tabpanel\" aria-hidden=\"true\" data-template-id=\"58518\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"58518\" class=\"elementor elementor-58518\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3880817 service-exploration-component-template elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3880817\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ea3f200 service-exploration-component-column-second\" data-id=\"ea3f200\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b80712d service-exploration-component__template-heading gg-font-v4 elementor-widget elementor-widget-heading\" data-id=\"b80712d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Customer support &amp; maintenance<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40255a2 service-exploration-component__description gg-font-v9 elementor-widget elementor-widget-text-editor\" data-id=\"40255a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>By providing predictive data analytics, maintenance strategy and processes, automation of customer service workflows, and serial engineering-RAMS support, we support leading manufacturers and service providers to obtain the highest end-customer satisfaction the lowest Total Cost of Ownership (TCO).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adb7b8a service-exploration-component__services gg-font-v12 elementor-widget elementor-widget-heading\" data-id=\"adb7b8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Services<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bedf5a service-exploration-component__list gg-font-v9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"3bedf5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Data-first after-sales technical helpdesk<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Technical publications\u200b<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">AI-powered CX &amp; product quality analytics<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">AI-powered predictive maintenance<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96685c0 service-exploration-component__button gg-button-v3 elementor-widget elementor-widget-button\" data-id=\"96685c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/expleo.com\/global\/en\/services\/customer-support-maintenance\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Discover these services<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>We help you get out in front with our engineering services, extensive sector knowledge and tried and tested innovations.<\/p>\n","protected":false},"featured_media":8135,"parent":0,"menu_order":0,"template":"","meta":{"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","_angie_page":false,"footnotes":""},"industry-taxonomy":[21],"service":[],"class_list":["post-37529","industries","type-industries","status-publish","has-post-thumbnail","hentry","industry-taxonomy-marine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Expleo | Transforming marine through engineering excellence<\/title>\n<meta name=\"description\" content=\"Keep pace with demand for the next generation of ships and submarines whilst harnessing technological advances in complex programmes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expleo.com\/global\/en\/industries\/marine\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marine\" \/>\n<meta property=\"og:description\" content=\"Keep pace with demand for the next generation of ships and submarines whilst harnessing technological advances in complex programmes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expleo.com\/global\/en\/industries\/marine\/\" \/>\n<meta property=\"og:site_name\" content=\"Global EN\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-09T20:43:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expleo.com\/global\/en\/wp-content\/uploads\/2021\/11\/industries-defence-naval-card.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"390\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/industries\\\/marine\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/industries\\\/marine\\\/\",\"name\":\"Expleo | Transforming marine through engineering excellence\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/industries\\\/marine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/industries\\\/marine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/industries-defence-naval-card.jpg\",\"datePublished\":\"2022-08-15T08:40:21+00:00\",\"dateModified\":\"2025-12-09T20:43:11+00:00\",\"description\":\"Keep pace with demand for the next generation of ships and submarines whilst harnessing technological advances in complex programmes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/industries\\\/marine\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/industries\\\/marine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/industries\\\/marine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/industries-defence-naval-card.jpg\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/industries-defence-naval-card.jpg\",\"width\":350,\"height\":390,\"caption\":\"Navy ships\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/industries\\\/marine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Industries\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/industries\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Marine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/\",\"name\":\"Expleo | EN\",\"description\":\"Expleo\",\"publisher\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/#organization\",\"name\":\"Expleo | EN\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"width\":1600,\"height\":774,\"caption\":\"Expleo | EN\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Expleo | Transforming marine through engineering excellence","description":"Keep pace with demand for the next generation of ships and submarines whilst harnessing technological advances in complex programmes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expleo.com\/global\/en\/industries\/marine\/","og_locale":"en_GB","og_type":"article","og_title":"Marine","og_description":"Keep pace with demand for the next generation of ships and submarines whilst harnessing technological advances in complex programmes.","og_url":"https:\/\/expleo.com\/global\/en\/industries\/marine\/","og_site_name":"Global EN","article_modified_time":"2025-12-09T20:43:11+00:00","og_image":[{"width":350,"height":390,"url":"https:\/\/expleo.com\/global\/en\/wp-content\/uploads\/2021\/11\/industries-defence-naval-card.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/expleo.com\/global\/en\/industries\/marine\/","url":"https:\/\/expleo.com\/global\/en\/industries\/marine\/","name":"Expleo | Transforming marine through engineering excellence","isPartOf":{"@id":"https:\/\/expleo.com\/global\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expleo.com\/global\/en\/industries\/marine\/#primaryimage"},"image":{"@id":"https:\/\/expleo.com\/global\/en\/industries\/marine\/#primaryimage"},"thumbnailUrl":"https:\/\/expleo.com\/global\/en\/wp-content\/uploads\/2021\/11\/industries-defence-naval-card.jpg","datePublished":"2022-08-15T08:40:21+00:00","dateModified":"2025-12-09T20:43:11+00:00","description":"Keep pace with demand for the next generation of ships and submarines whilst harnessing technological advances in complex programmes.","breadcrumb":{"@id":"https:\/\/expleo.com\/global\/en\/industries\/marine\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expleo.com\/global\/en\/industries\/marine\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/expleo.com\/global\/en\/industries\/marine\/#primaryimage","url":"https:\/\/expleo.com\/global\/en\/wp-content\/uploads\/2021\/11\/industries-defence-naval-card.jpg","contentUrl":"https:\/\/expleo.com\/global\/en\/wp-content\/uploads\/2021\/11\/industries-defence-naval-card.jpg","width":350,"height":390,"caption":"Navy ships"},{"@type":"BreadcrumbList","@id":"https:\/\/expleo.com\/global\/en\/industries\/marine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expleo.com\/global\/en\/"},{"@type":"ListItem","position":2,"name":"Industries","item":"https:\/\/expleo.com\/global\/en\/industries\/"},{"@type":"ListItem","position":3,"name":"Marine"}]},{"@type":"WebSite","@id":"https:\/\/expleo.com\/global\/en\/#website","url":"https:\/\/expleo.com\/global\/en\/","name":"Expleo | EN","description":"Expleo","publisher":{"@id":"https:\/\/expleo.com\/global\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expleo.com\/global\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/expleo.com\/global\/en\/#organization","name":"Expleo | EN","url":"https:\/\/expleo.com\/global\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/expleo.com\/global\/en\/#\/schema\/logo\/image\/","url":"https:\/\/expleo.com\/global\/en\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","contentUrl":"https:\/\/expleo.com\/global\/en\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","width":1600,"height":774,"caption":"Expleo | EN"},"image":{"@id":"https:\/\/expleo.com\/global\/en\/#\/schema\/logo\/image\/"}}]}},"hreflang":{"rendered":"<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/industries\/marine\/\" hreflang=\"x-default\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/industries\/marine\/\" hreflang=\"en\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/fr\/industries\/marine\/\" hreflang=\"fr\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/de\/industries\/marine\/\" hreflang=\"de\"\/>\n","structure":[{"blogId":4,"blogIsHidden":false,"postId":37529,"url":"https:\/\/expleo.com\/global\/en\/industries\/marine\/","language":"en","default":true},{"blogId":5,"blogIsHidden":false,"postId":22893,"url":"https:\/\/expleo.com\/global\/fr\/industries\/marine\/","language":"fr","default":false},{"blogId":6,"blogIsHidden":false,"postId":21912,"url":"https:\/\/expleo.com\/global\/de\/industries\/marine\/","language":"de","default":false}]},"_links":{"self":[{"href":"https:\/\/expleo.com\/global\/en\/wp-json\/wp\/v2\/industries\/37529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expleo.com\/global\/en\/wp-json\/wp\/v2\/industries"}],"about":[{"href":"https:\/\/expleo.com\/global\/en\/wp-json\/wp\/v2\/types\/industries"}],"version-history":[{"count":10,"href":"https:\/\/expleo.com\/global\/en\/wp-json\/wp\/v2\/industries\/37529\/revisions"}],"predecessor-version":[{"id":112945,"href":"https:\/\/expleo.com\/global\/en\/wp-json\/wp\/v2\/industries\/37529\/revisions\/112945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expleo.com\/global\/en\/wp-json\/wp\/v2\/media\/8135"}],"wp:attachment":[{"href":"https:\/\/expleo.com\/global\/en\/wp-json\/wp\/v2\/media?parent=37529"}],"wp:term":[{"taxonomy":"industry-taxonomy","embeddable":true,"href":"https:\/\/expleo.com\/global\/en\/wp-json\/wp\/v2\/industry-taxonomy?post=37529"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/expleo.com\/global\/en\/wp-json\/wp\/v2\/service?post=37529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}