{"id":4267,"date":"2018-11-30T17:15:00","date_gmt":"2018-11-30T17:15:00","guid":{"rendered":"https:\/\/expleo.com\/?post_type=case-studies&#038;p=14305"},"modified":"2024-03-20T09:38:15","modified_gmt":"2024-03-20T09:38:15","slug":"automatisation-de-tests-pour-siemens-plm","status":"publish","type":"case-studies","link":"https:\/\/expleo.com\/global\/fr\/cas-clients\/automatisation-de-tests-pour-siemens-plm\/","title":{"rendered":"Automatisation de tests pour Siemens PLM"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4267\" class=\"elementor elementor-4267\" data-elementor-post-type=\"case-studies\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c1e1011 gg-simple-text gg-container-small-ptb-96 gg-article-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c1e1011\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9a20d80\" data-id=\"9a20d80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-abfc32a gg-font-v5 gg-text-with-paddingbottom gg-custom-dark-purple-color  elementor-widget elementor-widget-heading\" data-id=\"abfc32a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Automatisation de tests \u00e0 grande \u00e9chelle et solution de tests de r\u00e9gression pour Siemens PLM Software<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f56665c gg-font-v8 gg-custom-dark-purple-color elementor-widget elementor-widget-heading\" data-id=\"f56665c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contexte et d\u00e9fis<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbba99c gg-font-v9 elementor-widget elementor-widget-text-editor\" data-id=\"bbba99c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Siemens PLM Software est l\u2019un des principaux fournisseurs mondiaux de logiciels et de services d\u00e9di\u00e9s \u00e0 la gestion du cycle de vie des produits (Product Lifecycle Management \u2013 PLM), avec 69\u00a0500\u00a0clients dans le monde.<\/p><p>Les 100\u00a0plus gros clients de Siemens utilisent leur technologie en moyenne depuis 18\u00a0ans, soit bien avant l\u2019existence m\u00eame de la plupart des soci\u00e9t\u00e9s de logiciels. Le produit va continuer \u00e0 se d\u00e9velopper. De nouvelles versions sont d\u00e9ploy\u00e9es tous les six mois et des correctifs sont distribu\u00e9s encore plus fr\u00e9quemment. Parfois, il existe des variations sp\u00e9cifiques \u00e0 un client.<\/p><p>En outre, en fonction des variations de plateformes d\u2019un client \u00e0 l\u2019autre, les mises \u00e0 jour du produit doivent \u00eatre appliqu\u00e9es \u00e0 divers syst\u00e8mes d\u2019exploitation et navigateurs. Le nombre total de tests \u00e9l\u00e9mentaires pour un produit aussi complexe s\u2019\u00e9l\u00e8ve \u00e0 plusieurs dizaines de milliers.<\/p><p>Tandis que des modifications telles que des corrections de bugs et de nouvelles fonctionnalit\u00e9s sont introduites avec succ\u00e8s dans chaque version, il est presque impossible de terminer les tests de r\u00e9gression de tous les sc\u00e9narios de test dans le temps disponible avant la date de publication. Cela entra\u00eene des probl\u00e8mes de qualit\u00e9 rencontr\u00e9s par les utilisateurs finaux ou des retards de publication. De mani\u00e8re g\u00e9n\u00e9rale, les tests reposent sur des tests s\u00e9lectifs effectu\u00e9s par des experts. Mais, \u00e9tant donn\u00e9 la taille et la complexit\u00e9 du produit, le nombre d\u2019experts n\u2019est jamais suffisant et leur disponibilit\u00e9 n\u2019est pas garantie.<\/p><p>Il a \u00e9t\u00e9 parfaitement compris et accept\u00e9 depuis longtemps que l\u2019automatisation \u00e9tait la solution \u00e0 ce probl\u00e8me de tests de r\u00e9gression. L\u2019automatisation avait d\u00e9j\u00e0 \u00e9t\u00e9 tent\u00e9e dans le pass\u00e9 par les meilleures ressources internes qui connaissaient le produit et le processus d\u2019automatisation. Un programme pilote a abouti, r\u00e9alisant avec succ\u00e8s des centaines de tests \u00e9l\u00e9mentaires.<\/p><p>Le v\u00e9ritable d\u00e9fi a cependant consist\u00e9 \u00e0 adapter l\u2019automatisation de la r\u00e9gression \u00e0 des dizaines de milliers de tests. Siemens a choisi de discuter de ses exigences avec les sp\u00e9cialistes Testing chez Expleo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-581b3af gg-font-v8 gg-custom-dark-purple-color elementor-widget elementor-widget-heading\" data-id=\"581b3af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Solution et r\u00e9sultats<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2c4ce2 gg-font-v9 gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"f2c4ce2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La solution d\u2019Expleo \u00e0 ce probl\u00e8me d\u2019automatisation de tests \u00e0 grande \u00e9chelle est Test Automation FaQtory\u00ae.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c7f6f6 gg-font-v10 gg-custom-dark-purple-color  elementor-widget elementor-widget-heading\" data-id=\"7c7f6f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Utilisation de la cha\u00eene de montage<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d37f8ce gg-font-v9 gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"d37f8ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Apr\u00e8s avoir analys\u00e9 le probl\u00e8me, Expleo a conclu que la r\u00e9alisation de tests \u00e0 grande \u00e9chelle pouvait \u00eatre obtenue en utilisant le mod\u00e8le de \u00ab\u00a0cha\u00eene de montage\u00a0\u00bb utilis\u00e9 en fabrication. Le travail d\u2019automatisation a \u00e9t\u00e9 divis\u00e9 en trois \u00ab\u00a0stations\u00a0\u00bb\u00a0:<\/p><ul><li>Experts \u2013 connaissent le produit, mais n\u2019ont pas besoin de conna\u00eetre l\u2019automatisation.<\/li><li>Concepteurs de framework \u2013 experts en automatisation, mais ayant \u00e9galement besoin de conna\u00eetre le produit dans une certaine mesure.<\/li><li>\u00c9quipe d\u2019automatisation \u2013 experts en automatisation, mais qui n\u2019ont pas besoin de conna\u00eetre le produit.<\/li><\/ul><p>Toutes les stations ont des interfaces clairement d\u00e9finies, ce qui facilite l\u2019efficacit\u00e9 globale de la cha\u00eene de montage.<\/p><p>Le succ\u00e8s de la r\u00e9alisation de ces tests \u00e0 grande \u00e9chelle a \u00e9t\u00e9 obtenu en \u00e9largissant l\u2019\u00e9quipe d\u2019automatisation \u2013 simple \u00e0 r\u00e9aliser pour un partenaire d\u2019assurance qualit\u00e9\u00a0comme Expleo \u2013 et en maintenant des \u00e9quipes d\u2019experts et de concepteurs de framework relativement petites.<\/p><p>Les experts proviennent de Siemens PLM et l\u2019\u00e9quipe de conception de framework est compos\u00e9e du personnel de Siemens PLM et d\u2019Expleo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a06803c gg-font-v10 gg-custom-dark-purple-color  elementor-widget elementor-widget-heading\" data-id=\"a06803c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9veloppement d\u2019outils<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7c949b gg-font-v9 gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"b7c949b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Poursuivant l\u2019analogie de la\u00a0cha\u00eene de montage, l\u2019\u00e9quipe Expleo a d\u00e9velopp\u00e9 un certain nombre d\u2019outils pour les diff\u00e9rentes \u00e9quipes, afin d\u2019augmenter leur coh\u00e9rence et leur productivit\u00e9, tout en r\u00e9duisant la d\u00e9pendance humaine.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7898e2 gg-font-v10 gg-custom-dark-purple-color  elementor-widget elementor-widget-heading\" data-id=\"b7898e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tarification bas\u00e9e sur les r\u00e9sultats<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af0b6d3 gg-font-v9 gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"af0b6d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019une des caract\u00e9ristiques les plus importantes de ce mod\u00e8le est la tarification bas\u00e9e sur les r\u00e9sultats. La grille tarifaire comprend uniquement le prix de l\u2019automatisation, de l\u2019ex\u00e9cution et de la maintenance d\u2019un sc\u00e9nario de test. Expleo n\u2019a charg\u00e9 Siemens PLM que pour ce qui a \u00e9t\u00e9 livr\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-647779f gg-font-v10 gg-custom-dark-purple-color  elementor-widget elementor-widget-heading\" data-id=\"647779f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Phase d\u2019\u00e9talonnage<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d613ee gg-font-v9 gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"6d613ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La mission a \u00e9t\u00e9 pr\u00e9c\u00e9d\u00e9e d\u2019une phase d\u2019\u00e9talonnage au cours de laquelle un ensemble de tests complexes a \u00e9t\u00e9 automatis\u00e9, non seulement pour valider l\u2019outil et le framework, mais \u00e9galement pour calibrer les prix unitaires. L\u2019\u00e9talonnage prend en compte le nombre de tests \u00e0 automatiser et le calendrier de publication du produit ou de l\u2019application, ce qui d\u00e9termine la fr\u00e9quence d\u2019ex\u00e9cution de la suite de r\u00e9gression automatis\u00e9e.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42451dc gg-font-v10 gg-custom-dark-purple-color  elementor-widget elementor-widget-heading\" data-id=\"42451dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Engagement pluriannuel selon la m\u00e9thodologie Agile<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41ac226 gg-font-v9 gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"41ac226\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019engagement est pluriannuel, mais utilise le paradigme\u00a0agile\u00a0des sprints mensuels et du d\u00e9veloppement et du d\u00e9ploiement incr\u00e9mentiels de la suite d\u2019automatisation. Cela permet de choisir chaque mois des cas pilotes pour l\u2019automatisation et de maintenir la suite d\u2019automatisation \u00e0 jour avec les versions les plus r\u00e9centes du produit test\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-715255b gg-article-content gg-simple-cta-purple-section gg-container-small-ptb-96 gg-simple-text elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"715255b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf21714\" data-id=\"bf21714\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df34682 gg-custom-white-color  gg-font-v8 elementor-widget elementor-widget-heading\" data-id=\"df34682\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Expleo, au service de ses clients<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9793164 gg-custom-white-color gg-font-v10 gg-custom-dark-purple-color  elementor-widget elementor-widget-heading\" data-id=\"9793164\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">V\u00e9ritable partenariat<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a7743a gg-custom-white-color gg-font-v9 gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"6a7743a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cette approche a permis de cr\u00e9er un v\u00e9ritable partenariat entre le client et Expleo, chaque partenaire se concentrant sur le noyau de leurs comp\u00e9tences. L\u2019automatisation de ces tests \u00e0 grande \u00e9chelle n\u2019a \u00e9t\u00e9 possible que gr\u00e2ce \u00e0 la forte expertise\u00a0Testing\u00a0d\u2019Expleo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d5cb57 gg-custom-white-color gg-font-v10 gg-custom-dark-purple-color  elementor-widget elementor-widget-heading\" data-id=\"8d5cb57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Transfert des risques \u00e0 Expleo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97b3f29 gg-custom-white-color gg-font-v9 gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"97b3f29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le risque li\u00e9 au d\u00e9ploiement r\u00e9ussi de l\u2019automatisation a \u00e9t\u00e9 transf\u00e9r\u00e9 de mani\u00e8re \u00e9quitable \u00e0 Expleo, par opposition \u00e0 un mod\u00e8le d\u2019engagement bas\u00e9 sur l\u2019effectif, dans lequel les risques demeurent principalement avec le client. Siemens PLM n\u2019a donc pay\u00e9 que ce qui a \u00e9t\u00e9 d\u00e9livr\u00e9 avec succ\u00e8s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9fa9d0 gg-custom-white-color gg-font-v10 gg-custom-dark-purple-color  elementor-widget elementor-widget-heading\" data-id=\"c9fa9d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La tarification bas\u00e9e sur les r\u00e9sultats incite \u00e0 l\u2019efficacit\u00e9<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91538f4 gg-custom-white-color gg-font-v9 gg-class-for-iphone8 elementor-widget elementor-widget-text-editor\" data-id=\"91538f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mais l\u2019avantage r\u00e9el de la tarification bas\u00e9e sur la production est encore plus subtil. Dans un mod\u00e8le bas\u00e9 sur les effectifs, l\u2019efficacit\u00e9 peut ne pas \u00eatre souhaitable, car elle pourrait r\u00e9duire l\u2019effectif du prestataire. Avec le mod\u00e8le bas\u00e9 sur les r\u00e9sultats, le prestataire trouve le moyen d\u2019am\u00e9liorer r\u00e9guli\u00e8rement les r\u00e9sultats livr\u00e9s. Ainsi, cette approche encourage l\u2019efficacit\u00e9 tout au long du processus. Siemens PLM peut donc s\u2019attendre \u00e0 ce que cette approche soit b\u00e9n\u00e9fique, ann\u00e9e apr\u00e8s ann\u00e9e, soit en atteignant un volume d\u2019automatisation plus important, soit en obtenant une r\u00e9duction des co\u00fbts pour le m\u00eame volume.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76bdf00 gg-simple-cta-section-grey gg-container-small-ptb-96 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76bdf00\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ba9852\" data-id=\"4ba9852\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39bfc20 elementor-widget elementor-widget-gravity-advanced-cta\" data-id=\"39bfc20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"gravity-advanced-cta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"gg-advanced-cta\">\r\n            \r\n        <p class=\"gg-advanced-cta__heading gg-tagline-heading-left\">\r\n        <strong>        QUALITY & TESTING        <\/strong>        <\/p>\r\n        \r\n        <h2 class=\"gg-advanced-cta__subheading gg-font-v2\">\r\n                <span>Software testing & integration<\/span>                <\/h2>\r\n                <div class=\"gg-advanced-cta__description gg-font-v9\">\r\n            <span><p>Software Quality assurance and testing are as important as software development to improve the end-customer experience. At Expleo, our teams work together in our best-in-class technological centres all over the world to operate a scalable and cost-effective global delivery model.<\/p><\/span>        <\/div>\r\n        \r\n        <div class=\"gg-advanced-cta__button-first gg-advanced-cta__button gg-button-v3\">\r\n            <a href=\"https:\/\/expleo.com\/global\/fr\/services\/qualite-tests\/\">\r\n                EN SAVOIR PLUS            <\/a>\r\n        <\/div>\r\n\r\n                <\/div>\r\n\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Explorez les solutions d\u2019automatisation des tests et de tests de r\u00e9gression \u00e0 grande \u00e9chelle que nous avons mises en place pour Siemens, afin de garantir la qualit\u00e9 de leurs produits.<\/p>\n","protected":false},"featured_media":4233,"template":"","meta":{"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","_angie_page":false,"service-grey-banner":"false","service-grey-banner-link":"","footnotes":""},"case-study-single-templates":[],"topic":[124,126],"industry-taxonomy":[36],"country":[91],"service":[69,191],"class_list":["post-4267","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","topic-quality-assurance-and-software-development","topic-industry-4-0","industry-taxonomy-manufacturing-and-construction","country-france","service-qa-qe-des-logiciels-alimentes-par-lia","service-qualite-and-tests"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Expleo | Automatisation de tests pour Siemens PLM<\/title>\n<meta name=\"description\" content=\"Explorez les solutions d\u2019automatisation des tests \u00e0 grande \u00e9chelle, mises en place pour Siemens, afin de garantir la qualit\u00e9 de leurs produits.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expleo.com\/global\/fr\/cas-clients\/automatisation-de-tests-pour-siemens-plm\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Automatisation de tests pour Siemens PLM\" \/>\n<meta property=\"og:description\" content=\"Explorez les solutions d\u2019automatisation des tests \u00e0 grande \u00e9chelle, mises en place pour Siemens, afin de garantir la qualit\u00e9 de leurs produits.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expleo.com\/global\/fr\/cas-clients\/automatisation-de-tests-pour-siemens-plm\/\" \/>\n<meta property=\"og:site_name\" content=\"Global FR\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-20T09:38:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2018\/11\/grid-homepage-industries-industrial.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/automatisation-de-tests-pour-siemens-plm\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/automatisation-de-tests-pour-siemens-plm\\\/\",\"name\":\"Expleo | Automatisation de tests pour Siemens PLM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/automatisation-de-tests-pour-siemens-plm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/automatisation-de-tests-pour-siemens-plm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/grid-homepage-industries-industrial.jpg\",\"datePublished\":\"2018-11-30T17:15:00+00:00\",\"dateModified\":\"2024-03-20T09:38:15+00:00\",\"description\":\"Explorez les solutions d\u2019automatisation des tests \u00e0 grande \u00e9chelle, mises en place pour Siemens, afin de garantir la qualit\u00e9 de leurs produits.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/automatisation-de-tests-pour-siemens-plm\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/automatisation-de-tests-pour-siemens-plm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/automatisation-de-tests-pour-siemens-plm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/grid-homepage-industries-industrial.jpg\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/grid-homepage-industries-industrial.jpg\",\"width\":640,\"height\":360,\"caption\":\"Automated machine in a lab\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/automatisation-de-tests-pour-siemens-plm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cas Clients\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Automatisation de tests pour Siemens PLM\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\",\"name\":\"Expleo | FR\",\"description\":\"Expleo\",\"publisher\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#organization\",\"name\":\"Expleo | FR\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"width\":1600,\"height\":774,\"caption\":\"Expleo | FR\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Expleo | Automatisation de tests pour Siemens PLM","description":"Explorez les solutions d\u2019automatisation des tests \u00e0 grande \u00e9chelle, mises en place pour Siemens, afin de garantir la qualit\u00e9 de leurs produits.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expleo.com\/global\/fr\/cas-clients\/automatisation-de-tests-pour-siemens-plm\/","og_locale":"fr_FR","og_type":"article","og_title":"Automatisation de tests pour Siemens PLM","og_description":"Explorez les solutions d\u2019automatisation des tests \u00e0 grande \u00e9chelle, mises en place pour Siemens, afin de garantir la qualit\u00e9 de leurs produits.","og_url":"https:\/\/expleo.com\/global\/fr\/cas-clients\/automatisation-de-tests-pour-siemens-plm\/","og_site_name":"Global FR","article_modified_time":"2024-03-20T09:38:15+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2018\/11\/grid-homepage-industries-industrial.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/expleo.com\/global\/fr\/cas-clients\/automatisation-de-tests-pour-siemens-plm\/","url":"https:\/\/expleo.com\/global\/fr\/cas-clients\/automatisation-de-tests-pour-siemens-plm\/","name":"Expleo | Automatisation de tests pour Siemens PLM","isPartOf":{"@id":"https:\/\/expleo.com\/global\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expleo.com\/global\/fr\/cas-clients\/automatisation-de-tests-pour-siemens-plm\/#primaryimage"},"image":{"@id":"https:\/\/expleo.com\/global\/fr\/cas-clients\/automatisation-de-tests-pour-siemens-plm\/#primaryimage"},"thumbnailUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2018\/11\/grid-homepage-industries-industrial.jpg","datePublished":"2018-11-30T17:15:00+00:00","dateModified":"2024-03-20T09:38:15+00:00","description":"Explorez les solutions d\u2019automatisation des tests \u00e0 grande \u00e9chelle, mises en place pour Siemens, afin de garantir la qualit\u00e9 de leurs produits.","breadcrumb":{"@id":"https:\/\/expleo.com\/global\/fr\/cas-clients\/automatisation-de-tests-pour-siemens-plm\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expleo.com\/global\/fr\/cas-clients\/automatisation-de-tests-pour-siemens-plm\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/expleo.com\/global\/fr\/cas-clients\/automatisation-de-tests-pour-siemens-plm\/#primaryimage","url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2018\/11\/grid-homepage-industries-industrial.jpg","contentUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2018\/11\/grid-homepage-industries-industrial.jpg","width":640,"height":360,"caption":"Automated machine in a lab"},{"@type":"BreadcrumbList","@id":"https:\/\/expleo.com\/global\/fr\/cas-clients\/automatisation-de-tests-pour-siemens-plm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expleo.com\/global\/fr\/"},{"@type":"ListItem","position":2,"name":"Cas Clients","item":"https:\/\/expleo.com\/global\/fr\/cas-clients\/"},{"@type":"ListItem","position":3,"name":"Automatisation de tests pour Siemens PLM"}]},{"@type":"WebSite","@id":"https:\/\/expleo.com\/global\/fr\/#website","url":"https:\/\/expleo.com\/global\/fr\/","name":"Expleo | FR","description":"Expleo","publisher":{"@id":"https:\/\/expleo.com\/global\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expleo.com\/global\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/expleo.com\/global\/fr\/#organization","name":"Expleo | FR","url":"https:\/\/expleo.com\/global\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/expleo.com\/global\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","contentUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","width":1600,"height":774,"caption":"Expleo | FR"},"image":{"@id":"https:\/\/expleo.com\/global\/fr\/#\/schema\/logo\/image\/"}}]}},"hreflang":{"rendered":"<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/cas-clients\/test-automation-for-siemens-plm\/\" hreflang=\"x-default\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/cas-clients\/test-automation-for-siemens-plm\/\" hreflang=\"en\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/fr\/cas-clients\/automatisation-de-tests-pour-siemens-plm\/\" hreflang=\"fr\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/de\/cas-clients\/testautomatisierung-fur-siemens-plm\/\" hreflang=\"de\"\/>\n","structure":[{"blogId":4,"blogIsHidden":false,"postId":7068,"url":"https:\/\/expleo.com\/global\/en\/cas-clients\/test-automation-for-siemens-plm\/","language":"en","default":true},{"blogId":5,"blogIsHidden":false,"postId":4267,"url":"https:\/\/expleo.com\/global\/fr\/cas-clients\/automatisation-de-tests-pour-siemens-plm\/","language":"fr","default":false},{"blogId":6,"blogIsHidden":false,"postId":4213,"url":"https:\/\/expleo.com\/global\/de\/cas-clients\/testautomatisierung-fur-siemens-plm\/","language":"de","default":false}]},"_links":{"self":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/case-studies\/4267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/types\/case-studies"}],"version-history":[{"count":0,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/case-studies\/4267\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/media\/4233"}],"wp:attachment":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/media?parent=4267"}],"wp:term":[{"taxonomy":"case-study-single-templates","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/case-study-single-templates?post=4267"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/topic?post=4267"},{"taxonomy":"industry-taxonomy","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/industry-taxonomy?post=4267"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/country?post=4267"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/service?post=4267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}