{"id":43565,"date":"2024-10-08T12:13:59","date_gmt":"2024-10-08T12:13:59","guid":{"rendered":"https:\/\/expleo.com\/global\/en\/?post_type=case-studies&#038;p=91391"},"modified":"2024-11-06T13:31:59","modified_gmt":"2024-11-06T13:31:59","slug":"rationalisation-mise-service-qualification","status":"publish","type":"case-studies","link":"https:\/\/expleo.com\/global\/fr\/cas-clients\/rationalisation-mise-service-qualification\/","title":{"rendered":"Rationalisation de la mise en service et de la qualification\u00a0"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"43565\" class=\"elementor elementor-43565\" data-elementor-post-type=\"case-studies\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f90a717 gg-simple-text gg-container-small gg-article-content elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f90a717\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7fec14d\" data-id=\"7fec14d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5038fce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5038fce\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c82a453\" data-id=\"c82a453\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac97cba elementor-widget elementor-widget-image\" data-id=\"ac97cba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"185\" height=\"185\" src=\"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2024\/09\/icon_team-1.svg\" class=\"attachment-large size-large wp-image-42983\" alt=\"A purple icon of three stylized people, with two circles representing heads on either side and one head in the center above an arch, symbolizing a group or community.\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-788c605 gg-custom-white-color  gg-font-v8 elementor-widget elementor-widget-heading\" data-id=\"788c605\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c9quipe d\u00e9di\u00e9e sur site <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b4e9ec7\" data-id=\"b4e9ec7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eed6e49 elementor-widget elementor-widget-image\" data-id=\"eed6e49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"185\" height=\"185\" src=\"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2024\/09\/icon_digital-solution.svg\" class=\"attachment-large size-large wp-image-43015\" alt=\"A purple icon showing a document with lines next to a smartphone, connected by a curved arrow pointing from the document to the phone, symbolizing file transfer or document sharing to a mobile device.\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6de6e86 gg-custom-white-color  gg-font-v8 elementor-widget elementor-widget-heading\" data-id=\"6de6e86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Solution num\u00e9rique KNEAT \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-219f85b\" data-id=\"219f85b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93d08a8 elementor-widget elementor-widget-image\" data-id=\"93d08a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"185\" height=\"185\" src=\"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2024\/09\/icon_specialists.svg\" class=\"attachment-large size-large wp-image-42937\" alt=\"Purple icon of three human figures arranged in a triangle, connected by lines, symbolizing teamwork, collaboration, or a network.\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a46a622 gg-custom-white-color  gg-font-v8 elementor-widget elementor-widget-heading\" data-id=\"a46a622\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pilotage des activit\u00e9s de C&amp;Q dans trois d\u00e9partements cl\u00e9s <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cb89c0 elementor-widget elementor-widget-spacer\" data-id=\"4cb89c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8511820 gg-custom-white-color  gg-font-v8 elementor-widget elementor-widget-heading\" data-id=\"8511820\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9fi<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3763859 gg-custom-white-color  gg-font-v8 elementor-widget elementor-widget-heading\" data-id=\"3763859\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">G\u00e9rer des projets complexes avec des ambitions audacieuses\u00a0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7dbde70 elementor-widget elementor-widget-text-editor\" data-id=\"7dbde70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Notre client, un acteur de premier plan dans le secteur de la fabrication pharmaceutique, s&#8217;est lanc\u00e9 dans un plan d&#8217;investissement ambitieux, n\u00e9cessitant une gestion compl\u00e8te de la mise en service et de la qualification (C&amp;Q) dans trois d\u00e9partements cl\u00e9s\u202f: Fabrication aseptique, \u00c9nergie (y compris HVAC) et Approvisionnement. Afin d\u2019accompagner la hausse significative de ses activit\u00e9s, il recherchait un partenaire capable de fournir des solutions fiables et flexibles et de s&#8217;int\u00e9grer parfaitement \u00e0 ses \u00e9quipes et \u00e0 son infrastructure existantes.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:180,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f811de gg-custom-white-color  gg-font-v8 elementor-widget elementor-widget-heading\" data-id=\"0f811de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Solution<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09e946a gg-custom-white-color  gg-font-v8 elementor-widget elementor-widget-heading\" data-id=\"09e946a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Une gestion souple et fiable des activit\u00e9s de C&amp;Q\u00a0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58a7e92 elementor-widget elementor-widget-text-editor\" data-id=\"58a7e92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">Depuis\u202f2020, notre partenariat avec le client a consid\u00e9rablement am\u00e9lior\u00e9 ses processus de C&amp;Q, si bien que les projets restent sur la bonne voie et respectent le budget. En d\u00e9ployant une strat\u00e9gie solide bas\u00e9e sur les normes ASTM\u202fE2500, nous avons rationalis\u00e9 le processus de qualification pour aboutir \u00e0 une gestion efficace et d\u00e9mat\u00e9rialis\u00e9e de la documentation, gr\u00e2ce \u00e0 la solution num\u00e9rique KNEAT.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:180,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">Notre mod\u00e8le, bas\u00e9 sur un centre de services flexible, nous a permis d&#8217;augmenter les ressources en fonction des besoins. L\u2019\u00e9quipe d\u00e9di\u00e9e sur site a pris en charge les domaines critiques tels que la propret\u00e9 des installations, l\u2019HVAC, la formulation, le remplissage et la finition, ainsi que le contr\u00f4le qualit\u00e9. Ainsi, nous avions la garantie que chaque aspect du processus r\u00e9pondait aux normes industrielles les plus \u00e9lev\u00e9es.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bc1113 gg-custom-white-color  gg-font-v8 elementor-widget elementor-widget-heading\" data-id=\"9bc1113\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00e9sultat<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3912661 gg-custom-white-color  gg-font-v8 elementor-widget elementor-widget-heading\" data-id=\"3912661\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Efficacit\u00e9 accrue et r\u00e9tention des connaissances<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee2f573 elementor-widget elementor-widget-text-editor\" data-id=\"ee2f573\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"auto\">L\u2019accueil de notre \u00e9quipe au sein du personnel existant du client a eu pour effet d\u2019acc\u00e9l\u00e9rer son int\u00e9gration. Gr\u00e2ce au mod\u00e8le contractuel flexible, les activit\u00e9s critiques ont \u00e9t\u00e9 hi\u00e9rarchis\u00e9es, garantissant ainsi le respect des d\u00e9lais sans sacrifier la qualit\u00e9. En outre, notre pr\u00e9sence \u00e0 long terme sur place a permis de conserver les connaissances, ce qui a assur\u00e9 la continuit\u00e9 des processus de C&amp;Q.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:180,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p><p><span data-contrast=\"auto\">En fin de compte, le client a b\u00e9n\u00e9fici\u00e9 non seulement d\u2019une garantie de conformit\u00e9 avec les exigences r\u00e9glementaires, mais \u00e9galement d\u2019une croissance soutenue visant \u00e0 renforcer sa position concurrentielle sur le march\u00e9.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:180,&quot;335559740&quot;:276}\">\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09ffad8 gg-custom-white-color  gg-font-v8 elementor-widget elementor-widget-heading\" data-id=\"09ffad8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avantages<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b0f0231 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0f0231\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5f1c2dc\" data-id=\"5f1c2dc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38de7fa elementor-widget elementor-widget-image\" data-id=\"38de7fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"185\" src=\"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2024\/09\/icon_time_white.svg\" class=\"attachment-large size-large wp-image-42935\" alt=\"White clock icon with an arrow curving around its top right, pointing clockwise. Four dots follow the arrow, suggesting the passage of time or a progress indicator, on a light gray background.\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f07b858 elementor-widget elementor-widget-spacer\" data-id=\"f07b858\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7aaa663 gg-custom-white-color  gg-font-v8 elementor-widget elementor-widget-heading\" data-id=\"7aaa663\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ach\u00e8vement en temps voulu des activit\u00e9s critiques  <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-eedad95\" data-id=\"eedad95\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-903d100 elementor-widget elementor-widget-image\" data-id=\"903d100\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"185\" src=\"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2024\/09\/icon_continuity_white.svg\" class=\"attachment-large size-large wp-image-43014\" alt=\"A white infinity symbol on a light gray background.\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-612f091 elementor-widget elementor-widget-spacer\" data-id=\"612f091\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbfc110 gg-custom-white-color  gg-font-v8 elementor-widget elementor-widget-heading\" data-id=\"fbfc110\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Continuit\u00e9 des processus de C&amp;Q <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-be44c3a\" data-id=\"be44c3a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31266ce elementor-widget elementor-widget-image\" data-id=\"31266ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"185\" height=\"185\" src=\"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2024\/09\/icon_decrease_white.svg\" class=\"attachment-large size-large wp-image-42939\" alt=\"A white icon of a bar chart with three bars decreasing in height from left to right and a downward-pointing arrow above them, indicating a decline or decrease.\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9363b01 elementor-widget elementor-widget-spacer\" data-id=\"9363b01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3907b16 gg-custom-white-color  gg-font-v8 elementor-widget elementor-widget-heading\" data-id=\"3907b16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Besoins en formation initiale r\u00e9duits  <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7bbc5b0 gg-image-with-overalpping-text gg-image-with-overalpping-text-v2 gg-container-large elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7bbc5b0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57019b0\" data-id=\"57019b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d82dfde gg-image-with-overalpping-text__heading elementor-widget elementor-widget-heading\" data-id=\"d82dfde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Votre  catalyseur de la transformation d\u00e9di\u00e9 aux sciences de la vie\u202f\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83b0321 elementor-widget elementor-widget-text-editor\" data-id=\"83b0321\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9couvrez comment acc\u00e9l\u00e9rer votre succ\u00e8s avec Expleo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c95b9b2 gg-button-v6 elementor-widget elementor-widget-button\" data-id=\"c95b9b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/expleo.com\/global\/fr\/secteurs\/sciences-de-la-vie\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00e0 d\u00e9couvrir<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c9quipe d\u00e9di\u00e9e sur site Solution num\u00e9rique KNEAT Pilotage des activit\u00e9s de C&#038;Q dans trois d\u00e9partements cl\u00e9s D\u00e9fi G\u00e9rer des projets complexes avec des ambitions audacieuses\u00a0 Notre client, un acteur de premier plan dans le secteur de la fabrication pharmaceutique, s&#8217;est lanc\u00e9 dans un plan d&#8217;investissement ambitieux, n\u00e9cessitant une gestion compl\u00e8te de la mise en service [&hellip;]<\/p>\n","protected":false},"featured_media":42943,"template":"","meta":{"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","_angie_page":false,"service-grey-banner":"false","service-grey-banner-link":"","footnotes":""},"case-study-single-templates":[494],"topic":[129,121,119],"industry-taxonomy":[135],"country":[116],"service":[204,189,58],"class_list":["post-43565","case-studies","type-case-studies","status-publish","has-post-thumbnail","hentry","case-study-single-templates-new-template","topic-compliance-and-regulation","topic-innovation-conception","topic-people-and-leadership","industry-taxonomy-sciences-de-la-vie","country-global","service-fpga-et-systemes-electroniques","service-ingenierie-produits-and-procedes","service-conception-de-produit-et-ingenierie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Expleo | Rationalisation de la mise en service<\/title>\n<meta name=\"description\" content=\"Notre client, un acteur de premier plan dans le secteur de la fabrication pharmaceutique, s&#039;est lanc\u00e9 dans un plan d&#039;investissement ambitieux. A d\u00e9couvrir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expleo.com\/global\/fr\/cas-clients\/rationalisation-mise-service-qualification\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rationalisation de la mise en service et de la qualification\u00a0\" \/>\n<meta property=\"og:description\" content=\"Notre client, un acteur de premier plan dans le secteur de la fabrication pharmaceutique, s&#039;est lanc\u00e9 dans un plan d&#039;investissement ambitieux. A d\u00e9couvrir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expleo.com\/global\/fr\/cas-clients\/rationalisation-mise-service-qualification\/\" \/>\n<meta property=\"og:site_name\" content=\"Global FR\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-06T13:31:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2024\/09\/medical-glass-bottles-production.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/rationalisation-mise-service-qualification\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/rationalisation-mise-service-qualification\\\/\",\"name\":\"Expleo | Rationalisation de la mise en service\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/rationalisation-mise-service-qualification\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/rationalisation-mise-service-qualification\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/medical-glass-bottles-production.jpg\",\"datePublished\":\"2024-10-08T12:13:59+00:00\",\"dateModified\":\"2024-11-06T13:31:59+00:00\",\"description\":\"Notre client, un acteur de premier plan dans le secteur de la fabrication pharmaceutique, s'est lanc\u00e9 dans un plan d'investissement ambitieux. A d\u00e9couvrir.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/rationalisation-mise-service-qualification\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/rationalisation-mise-service-qualification\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/rationalisation-mise-service-qualification\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/medical-glass-bottles-production.jpg\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/medical-glass-bottles-production.jpg\",\"width\":1280,\"height\":720,\"caption\":\"A close-up of a pharmaceutical production line where small glass vials are being automated through a filling machine. The machinery is precisely aligned to fill each of the vials, showcasing a sterile and efficient manufacturing process.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/rationalisation-mise-service-qualification\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cas Clients\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/cas-clients\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rationalisation de la mise en service et de la qualification\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\",\"name\":\"Expleo | FR\",\"description\":\"Expleo\",\"publisher\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#organization\",\"name\":\"Expleo | FR\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"width\":1600,\"height\":774,\"caption\":\"Expleo | FR\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Expleo | Rationalisation de la mise en service","description":"Notre client, un acteur de premier plan dans le secteur de la fabrication pharmaceutique, s'est lanc\u00e9 dans un plan d'investissement ambitieux. A d\u00e9couvrir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expleo.com\/global\/fr\/cas-clients\/rationalisation-mise-service-qualification\/","og_locale":"fr_FR","og_type":"article","og_title":"Rationalisation de la mise en service et de la qualification\u00a0","og_description":"Notre client, un acteur de premier plan dans le secteur de la fabrication pharmaceutique, s'est lanc\u00e9 dans un plan d'investissement ambitieux. A d\u00e9couvrir.","og_url":"https:\/\/expleo.com\/global\/fr\/cas-clients\/rationalisation-mise-service-qualification\/","og_site_name":"Global FR","article_modified_time":"2024-11-06T13:31:59+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2024\/09\/medical-glass-bottles-production.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/expleo.com\/global\/fr\/cas-clients\/rationalisation-mise-service-qualification\/","url":"https:\/\/expleo.com\/global\/fr\/cas-clients\/rationalisation-mise-service-qualification\/","name":"Expleo | Rationalisation de la mise en service","isPartOf":{"@id":"https:\/\/expleo.com\/global\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expleo.com\/global\/fr\/cas-clients\/rationalisation-mise-service-qualification\/#primaryimage"},"image":{"@id":"https:\/\/expleo.com\/global\/fr\/cas-clients\/rationalisation-mise-service-qualification\/#primaryimage"},"thumbnailUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2024\/09\/medical-glass-bottles-production.jpg","datePublished":"2024-10-08T12:13:59+00:00","dateModified":"2024-11-06T13:31:59+00:00","description":"Notre client, un acteur de premier plan dans le secteur de la fabrication pharmaceutique, s'est lanc\u00e9 dans un plan d'investissement ambitieux. A d\u00e9couvrir.","breadcrumb":{"@id":"https:\/\/expleo.com\/global\/fr\/cas-clients\/rationalisation-mise-service-qualification\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expleo.com\/global\/fr\/cas-clients\/rationalisation-mise-service-qualification\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/expleo.com\/global\/fr\/cas-clients\/rationalisation-mise-service-qualification\/#primaryimage","url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2024\/09\/medical-glass-bottles-production.jpg","contentUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2024\/09\/medical-glass-bottles-production.jpg","width":1280,"height":720,"caption":"A close-up of a pharmaceutical production line where small glass vials are being automated through a filling machine. The machinery is precisely aligned to fill each of the vials, showcasing a sterile and efficient manufacturing process."},{"@type":"BreadcrumbList","@id":"https:\/\/expleo.com\/global\/fr\/cas-clients\/rationalisation-mise-service-qualification\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expleo.com\/global\/fr\/"},{"@type":"ListItem","position":2,"name":"Cas Clients","item":"https:\/\/expleo.com\/global\/fr\/cas-clients\/"},{"@type":"ListItem","position":3,"name":"Rationalisation de la mise en service et de la qualification\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/expleo.com\/global\/fr\/#website","url":"https:\/\/expleo.com\/global\/fr\/","name":"Expleo | FR","description":"Expleo","publisher":{"@id":"https:\/\/expleo.com\/global\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expleo.com\/global\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/expleo.com\/global\/fr\/#organization","name":"Expleo | FR","url":"https:\/\/expleo.com\/global\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/expleo.com\/global\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","contentUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","width":1600,"height":774,"caption":"Expleo | FR"},"image":{"@id":"https:\/\/expleo.com\/global\/fr\/#\/schema\/logo\/image\/"}}]}},"hreflang":{"rendered":"<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/cas-clients\/streamlining-commissioning-and-qualification\/\" hreflang=\"x-default\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/cas-clients\/streamlining-commissioning-and-qualification\/\" hreflang=\"en\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/fr\/cas-clients\/rationalisation-mise-service-qualification\/\" hreflang=\"fr\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/de\/cas-clients\/optimierung-von-inbetriebnahme-und-qualifizierung\/\" hreflang=\"de\"\/>\n","structure":[{"blogId":4,"blogIsHidden":false,"postId":91391,"url":"https:\/\/expleo.com\/global\/en\/cas-clients\/streamlining-commissioning-and-qualification\/","language":"en","default":true},{"blogId":5,"blogIsHidden":false,"postId":43565,"url":"https:\/\/expleo.com\/global\/fr\/cas-clients\/rationalisation-mise-service-qualification\/","language":"fr","default":false},{"blogId":6,"blogIsHidden":false,"postId":36459,"url":"https:\/\/expleo.com\/global\/de\/cas-clients\/optimierung-von-inbetriebnahme-und-qualifizierung\/","language":"de","default":false}]},"_links":{"self":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/case-studies\/43565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/case-studies"}],"about":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/types\/case-studies"}],"version-history":[{"count":0,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/case-studies\/43565\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/media\/42943"}],"wp:attachment":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/media?parent=43565"}],"wp:term":[{"taxonomy":"case-study-single-templates","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/case-study-single-templates?post=43565"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/topic?post=43565"},{"taxonomy":"industry-taxonomy","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/industry-taxonomy?post=43565"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/country?post=43565"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/service?post=43565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}