{"id":19561,"date":"2022-04-27T04:38:00","date_gmt":"2022-04-27T04:38:00","guid":{"rendered":"https:\/\/expleo.com\/global\/fr\/?post_type=insights&#038;p=19561"},"modified":"2024-03-11T16:32:07","modified_gmt":"2024-03-11T16:32:07","slug":"leaders-ingenierie-qualite-classement-neat-nelsonhall","status":"publish","type":"insights","link":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/leaders-ingenierie-qualite-classement-neat-nelsonhall\/","title":{"rendered":"Expleo class\u00e9  parmi les \u00ab leaders \u00bb en ing\u00e9nierie de la qualit\u00e9 par le classement NEAT de NelsonHall"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"19561\" class=\"elementor elementor-19561\" data-elementor-post-type=\"insights\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af1a838 gg-article-content  gg-standard-article-template gg-simple-text gg-container-small-ptb-72  elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af1a838\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ed1d69\" data-id=\"4ed1d69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b5444d gg-article-content  gg-standard-article-template gg-simple-text gg-container-small-ptb-72  elementor-widget elementor-widget-text-editor\" data-id=\"7b5444d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Londres, UK, 27 Avril 2022 \u2013\u202f<\/strong><span data-contrast=\"none\">Expleo<\/span><span data-contrast=\"none\"> figure parmi les entreprises leaders dans la cat\u00e9gorie ing\u00e9nierie de qualit\u00e9 du rapport NEAT 2021 publi\u00e9 par le cabinet <\/span><a href=\"https:\/\/research.nelson-hall.com\/\"><span data-contrast=\"none\">NelsonHall<\/span><\/a><span data-contrast=\"none\">,<\/span><span data-contrast=\"none\"> un cabinet d\u2019analyse des processus d\u2019entreprise et des services informatiques. Pour la troisi\u00e8me ann\u00e9e cons\u00e9cutive, Expleo est reconnu pour son expertise ainsi que pour son implication dans le d\u00e9veloppement des comp\u00e9tences de demain, et notamment dans le domaine du digital o\u00f9 la demande est croissante.<\/span><\/p><p><span data-contrast=\"none\">Le rapport annuel de NelsonHall \u00e9value les performances mondiales de 15 prestataires de services sur des expertises cl\u00e9s telles que l&#8217;IA, le cloud, l\u2019ing\u00e9nierie de qualit\u00e9 et la s\u00e9curit\u00e9. Le march\u00e9 mondial des services de tests de logiciels est actuellement \u00e9valu\u00e9 \u00e0 36 milliards de dollars et devrait, selon NelsonHall, cro\u00eetre de 3 % en 2022.<\/span><\/p><p><span data-contrast=\"auto\">Au-del\u00e0 d\u2019\u00eatre reconnu comme \u00ab\u202fleader\u202f\u00bb dans l\u2019\u00e9valuation globale du secteur, Expleo a \u00e9t\u00e9 \u00e9galement \u00e9t\u00e9 positionn\u00e9 en tant que \u00ab\u202fleader\u202f\u00bb dans les cat\u00e9gories des tests AI et cognitifs, des tests de s\u00e9curit\u00e9 des applications et des tests continus.<\/span><\/p><p><strong>Rob McConnell, Director &amp; Global Head of Advanced Solutions chez Expleo, a d\u00e9clar\u00e9 :<\/strong> <i><span data-contrast=\"auto\">\u00ab\u202fLe secteur des tests de logiciels continue d&#8217;\u00e9voluer car les organisations utilisent chaque jour davantage de logiciels et de technologies sophistiqu\u00e9es dans leurs op\u00e9rations. Ce mouvement de fond, conjugu\u00e9 au rythme soutenu du changement du secteur, signifie que ceux qui utilisent les anciennes m\u00e9thodologies et anciens outils perdent du temps et de l&#8217;argent \u00e0 tester les mauvaises choses au mauvais moment. Gr\u00e2ce \u00e0 de meilleures pratiques, les tests de logiciels deviennent \u00e0 la fois davantage automatis\u00e9s et int\u00e9gr\u00e9s aux m\u00e9thodes Agile et DevOps tout en \u00e9tant renforc\u00e9s par les technologies d&#8217;IA et d&#8217;apprentissage automatique (machine learning).\u202f\u00bb<\/span><\/i><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><strong>Dominique Raviart, Directeur des services informatiques chez NelsonHall, commente :<\/strong> <i><span data-contrast=\"auto\">\u00ab\u202fExpleo poursuit son parcours d&#8217;automatisation, en comblant les lacunes laiss\u00e9es par les outils de test. L&#8217;entreprise a investi dans le test continu, le DevOps et l&#8217;IA pour r\u00e9pondre \u00e0 la demande de d\u00e9veloppements plus agiles et de tests plus cibl\u00e9s. Expleo dispose par ailleurs d&#8217;une multitude d&#8217;analyses bas\u00e9es sur l&#8217;IA pour r\u00e9duire le poids de l&#8217;assurance qualit\u00e9 tout en maximisant la couverture. Cela correspond bien \u00e0 la demande des clients d\u00e9sireux de r\u00e9inventer leurs proc\u00e9dures de tests.\u202f\u00bb<\/span><\/i><span data-ccp-props=\"{\">\u00a0<\/span><\/p><p><strong>McConnell ajoute : <\/strong><i><span data-contrast=\"auto\">\u00ab\u202fLes nouvelles technologies que nous avons adopt\u00e9es contribuent \u00e0 limiter la d\u00e9pendance aux comp\u00e9tences techniques et \u00e0 r\u00e9duire la pression sur ces ressources limit\u00e9es. La demande\u202fpour ces comp\u00e9tences sp\u00e9cifiques \u00e9tant en hausse, cela \u00f4te un poids aux entreprises.\u202f\u00bb<\/span><\/i><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Expleo class\u00e9  parmi les \u00ab leaders \u00bb en ing\u00e9nierie de la qualit\u00e9 par le classement du cabinet d&#8217;analyse NelsonHall. Pour la troisi\u00e8me ann\u00e9e cons\u00e9cutive, Expleo figure dans ce classement pour son expertises en IA, cloud et cyber\u00e9curit\u00e9.  <\/p>\n","protected":false},"author":81,"featured_media":19575,"parent":0,"template":"","meta":{"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","_angie_page":false,"footnotes":""},"topic":[124,310,374,121],"insights-single-templates":[492],"industry-taxonomy":[373],"content-type":[20],"country":[116],"service":[],"class_list":["post-19561","insights","type-insights","status-publish","has-post-thumbnail","hentry","topic-quality-assurance-and-software-development","topic-corporate","topic-groupe","topic-innovation-conception","insights-single-templates-old-template","industry-taxonomy-all","content-type-actualite","country-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Expleo, \u00ab leaders \u00bb en ing\u00e9nierie d&#039;apr\u00e8s NEAT de NelsonHall<\/title>\n<meta name=\"description\" content=\"Expleo figure parmi les entreprises leader dans la cat\u00e9gorie ing\u00e9nierie de la qualit\u00e9, et notamment son expertise en IA, cloud et cybers\u00e9curit\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/leaders-ingenierie-qualite-classement-neat-nelsonhall\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expleo class\u00e9 parmi les \u00ab leaders \u00bb en ing\u00e9nierie de la qualit\u00e9 par le classement NEAT de NelsonHall\" \/>\n<meta property=\"og:description\" content=\"Expleo figure parmi les entreprises leader dans la cat\u00e9gorie ing\u00e9nierie de la qualit\u00e9, et notamment son expertise en IA, cloud et cybers\u00e9curit\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/leaders-ingenierie-qualite-classement-neat-nelsonhall\/\" \/>\n<meta property=\"og:site_name\" content=\"Global FR\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-11T16:32:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2022\/08\/big-data-1024x576.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/leaders-ingenierie-qualite-classement-neat-nelsonhall\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/leaders-ingenierie-qualite-classement-neat-nelsonhall\\\/\",\"name\":\"Expleo, \u00ab leaders \u00bb en ing\u00e9nierie d'apr\u00e8s NEAT de NelsonHall\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/leaders-ingenierie-qualite-classement-neat-nelsonhall\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/leaders-ingenierie-qualite-classement-neat-nelsonhall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/big-data.jpg\",\"datePublished\":\"2022-04-27T04:38:00+00:00\",\"dateModified\":\"2024-03-11T16:32:07+00:00\",\"description\":\"Expleo figure parmi les entreprises leader dans la cat\u00e9gorie ing\u00e9nierie de la qualit\u00e9, et notamment son expertise en IA, cloud et cybers\u00e9curit\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/leaders-ingenierie-qualite-classement-neat-nelsonhall\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/leaders-ingenierie-qualite-classement-neat-nelsonhall\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/leaders-ingenierie-qualite-classement-neat-nelsonhall\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/big-data.jpg\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/big-data.jpg\",\"width\":1280,\"height\":720,\"caption\":\"Abstract radial chart with glowing lines and dots on a dark background. The lines radiate outward from a central circle, forming a pattern reminiscent of \\\"Demystifying Hyperautomation: Helpful or Hype?\\\", highlighting key information with various colors and intensities.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/leaders-ingenierie-qualite-classement-neat-nelsonhall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perspectives\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Expleo class\u00e9 parmi les \u00ab leaders \u00bb en ing\u00e9nierie de la qualit\u00e9 par le classement NEAT de NelsonHall\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\",\"name\":\"Expleo | FR\",\"description\":\"Expleo\",\"publisher\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#organization\",\"name\":\"Expleo | FR\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"width\":1600,\"height\":774,\"caption\":\"Expleo | FR\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Expleo, \u00ab leaders \u00bb en ing\u00e9nierie d'apr\u00e8s NEAT de NelsonHall","description":"Expleo figure parmi les entreprises leader dans la cat\u00e9gorie ing\u00e9nierie de la qualit\u00e9, et notamment son expertise en IA, cloud et cybers\u00e9curit\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/leaders-ingenierie-qualite-classement-neat-nelsonhall\/","og_locale":"fr_FR","og_type":"article","og_title":"Expleo class\u00e9 parmi les \u00ab leaders \u00bb en ing\u00e9nierie de la qualit\u00e9 par le classement NEAT de NelsonHall","og_description":"Expleo figure parmi les entreprises leader dans la cat\u00e9gorie ing\u00e9nierie de la qualit\u00e9, et notamment son expertise en IA, cloud et cybers\u00e9curit\u00e9.","og_url":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/leaders-ingenierie-qualite-classement-neat-nelsonhall\/","og_site_name":"Global FR","article_modified_time":"2024-03-11T16:32:07+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2022\/08\/big-data-1024x576.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/leaders-ingenierie-qualite-classement-neat-nelsonhall\/","url":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/leaders-ingenierie-qualite-classement-neat-nelsonhall\/","name":"Expleo, \u00ab leaders \u00bb en ing\u00e9nierie d'apr\u00e8s NEAT de NelsonHall","isPartOf":{"@id":"https:\/\/expleo.com\/global\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/leaders-ingenierie-qualite-classement-neat-nelsonhall\/#primaryimage"},"image":{"@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/leaders-ingenierie-qualite-classement-neat-nelsonhall\/#primaryimage"},"thumbnailUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2022\/08\/big-data.jpg","datePublished":"2022-04-27T04:38:00+00:00","dateModified":"2024-03-11T16:32:07+00:00","description":"Expleo figure parmi les entreprises leader dans la cat\u00e9gorie ing\u00e9nierie de la qualit\u00e9, et notamment son expertise en IA, cloud et cybers\u00e9curit\u00e9.","breadcrumb":{"@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/leaders-ingenierie-qualite-classement-neat-nelsonhall\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/leaders-ingenierie-qualite-classement-neat-nelsonhall\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/leaders-ingenierie-qualite-classement-neat-nelsonhall\/#primaryimage","url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2022\/08\/big-data.jpg","contentUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2022\/08\/big-data.jpg","width":1280,"height":720,"caption":"Abstract radial chart with glowing lines and dots on a dark background. The lines radiate outward from a central circle, forming a pattern reminiscent of \"Demystifying Hyperautomation: Helpful or Hype?\", highlighting key information with various colors and intensities."},{"@type":"BreadcrumbList","@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/leaders-ingenierie-qualite-classement-neat-nelsonhall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expleo.com\/global\/fr\/"},{"@type":"ListItem","position":2,"name":"Perspectives","item":"https:\/\/expleo.com\/global\/fr\/perspectives\/"},{"@type":"ListItem","position":3,"name":"Expleo class\u00e9 parmi les \u00ab leaders \u00bb en ing\u00e9nierie de la qualit\u00e9 par le classement NEAT de NelsonHall"}]},{"@type":"WebSite","@id":"https:\/\/expleo.com\/global\/fr\/#website","url":"https:\/\/expleo.com\/global\/fr\/","name":"Expleo | FR","description":"Expleo","publisher":{"@id":"https:\/\/expleo.com\/global\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expleo.com\/global\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/expleo.com\/global\/fr\/#organization","name":"Expleo | FR","url":"https:\/\/expleo.com\/global\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/expleo.com\/global\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","contentUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","width":1600,"height":774,"caption":"Expleo | FR"},"image":{"@id":"https:\/\/expleo.com\/global\/fr\/#\/schema\/logo\/image\/"}}]}},"hreflang":{"rendered":"<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/perspectives\/news\/leader-nelsonhall-evaluation-quality-engineering\/\" hreflang=\"x-default\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/perspectives\/news\/leader-nelsonhall-evaluation-quality-engineering\/\" hreflang=\"en\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/leaders-ingenierie-qualite-classement-neat-nelsonhall\/\" hreflang=\"fr\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/de\/perspectives\/neuigkeiten\/nelsonhall-quality-engineering\/\" hreflang=\"de\"\/>\n","structure":[{"blogId":4,"blogIsHidden":false,"postId":32069,"url":"https:\/\/expleo.com\/global\/en\/perspectives\/news\/leader-nelsonhall-evaluation-quality-engineering\/","language":"en","default":true},{"blogId":5,"blogIsHidden":false,"postId":19561,"url":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/leaders-ingenierie-qualite-classement-neat-nelsonhall\/","language":"fr","default":false},{"blogId":6,"blogIsHidden":false,"postId":19648,"url":"https:\/\/expleo.com\/global\/de\/perspectives\/neuigkeiten\/nelsonhall-quality-engineering\/","language":"de","default":false}]},"_links":{"self":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights\/19561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/types\/insights"}],"author":[{"embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/users\/81"}],"version-history":[{"count":0,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights\/19561\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/media\/19575"}],"wp:attachment":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/media?parent=19561"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/topic?post=19561"},{"taxonomy":"insights-single-templates","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights-single-templates?post=19561"},{"taxonomy":"industry-taxonomy","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/industry-taxonomy?post=19561"},{"taxonomy":"content-type","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/content-type?post=19561"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/country?post=19561"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/service?post=19561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}