{"id":637,"date":"2018-06-13T03:29:00","date_gmt":"2018-06-13T03:29:00","guid":{"rendered":"https:\/\/expleo.com\/global\/en\/?post_type=insight&#038;p=438"},"modified":"2025-02-06T10:50:33","modified_gmt":"2025-02-06T10:50:33","slug":"sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion","status":"publish","type":"insights","link":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\/","title":{"rendered":"Sono Motors choisit Expleo pour d\u00e9velopper un concept d\u2019\u00e9clairage original pour sa voiture \u00e9lectrique solaire Sion"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"637\" class=\"elementor elementor-637\" data-elementor-post-type=\"insights\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4fdf58b gg-article-content  gg-standard-article-template gg-simple-text gg-container-small-ptb-72  gg-print-ptb-null elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fdf58b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0522d99 gg-tablet-view\" data-id=\"0522d99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8d291c gg-font-v9 gg-class-for-iphone8 gg-print-pb-4 elementor-widget elementor-widget-text-editor\" data-id=\"a8d291c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Paris, le 13 juin 2018.\u00a0<\/strong>Automotive Solutions Germany (ASG), filiale d\u2019Expleo sp\u00e9cialiste des solutions d\u2019\u00e9clairage pour l\u2019automobile,va accompagner Sono Motors dans le d\u00e9veloppement du syst\u00e8me d\u2019\u00e9clairage ext\u00e9rieur de la Sion, premier v\u00e9hicule \u00e9lectrique de s\u00e9rie capable de recharger ses batteries gr\u00e2ce \u00e0 des panneaux solaires.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e3f966 gg-display-none-print elementor-widget elementor-widget-image\" data-id=\"9e3f966\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2018\/06\/sono-motors-800x450-1-768x432.jpeg\" class=\"attachment-medium_large size-medium_large wp-image-45101\" alt=\"A black electric car with solar panels on its hood is parked near a marina with boats in the background under a partly cloudy sky.\" srcset=\"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2018\/06\/sono-motors-800x450-1-768x432.jpeg 768w, https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2018\/06\/sono-motors-800x450-1-300x169.jpeg 300w, https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2018\/06\/sono-motors-800x450-1.jpeg 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cae92ff gg-font-v9 gg-class-for-iphone8    elementor-widget elementor-widget-text-editor\" data-id=\"cae92ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ASG-Expleo doit concevoir et pr\u00e9parer la production en s\u00e9rie de l\u2019\u00e9clairage ext\u00e9rieur de la Sion, des phares avant et feux arri\u00e8re aux feux stop sur\u00e9lev\u00e9s. Une \u00e9quipe r\u00e9unissant les experts d\u2019ASG-Expleo et de Sono Motors assurera le d\u00e9veloppement d\u2019une solution sur-mesure associant la technologie LED, r\u00e9sistante et ultral\u00e9g\u00e8re, et les lampes \u00e0 r\u00e9flecteur, moins on\u00e9reuses.<\/p><p>\u00ab Nous sommes ravis de pouvoir coop\u00e9rer avec Sono Motors sur ce projet d\u2019innovation. Nous allons int\u00e9grer une technologie de pointe d\u2019\u00e9clairage ultral\u00e9ger dans le design fonctionnel de la voiture de fa\u00e7on \u00e0 respecter les objectifs du projet Sion en termes de contr\u00f4le des co\u00fbts et de durabilit\u00e9 \u00bb, explique Andreas Spiegelberger, Directeur g\u00e9n\u00e9rald\u2019ASG-Expleo.<\/p><p>\u00ab Nous nous r\u00e9jouissons de faire \u00e9quipe avec ASG-Expleo qui, entant que sp\u00e9cialiste de l\u2019\u00e9clairage automobile et fort d\u2019une longue exp\u00e9rience,est un partenaire cl\u00e9 pour le d\u00e9veloppement et la production des \u00e9quipements LED de la Sion \u00bb, ajoute Jona Christians, CEO de Sono Motors.<\/p><p>La Sion est la premi\u00e8re voiture de s\u00e9rie \u00e0 utiliser des panneaux solaires install\u00e9s sur le ch\u00e2ssis pour recharger ses batteries. Gr\u00e2ce aux cellules solaires int\u00e9gr\u00e9es, une grande partie de l\u2019\u00e9nergie n\u00e9cessaire au fonctionnement provient d\u2019une source enti\u00e8rement renouvelable : le soleil. L\u2019objectif est de faire en sorte que la Sion soit mise en circulation au cours du second semestre 2019 \u00e0 un tarif de 16 000 \u20ac(batterie non comprise).<\/p><p><strong>A propos de Sono Motors<\/strong><\/p><p>Constructeur automobile innovant g\u00e9r\u00e9 par ses propri\u00e9taires, Sono Motors a \u00e9t\u00e9 cr\u00e9\u00e9 en 2016 par deux amis dont la vision est de proposer un concept de mobilit\u00e9 durable ind\u00e9pendant des combustibles fossiles. Aujourd\u2019hui, c\u2019est une \u00e9quipe exp\u00e9riment\u00e9e d\u2019ing\u00e9nieurs, de designers, de techniciens et d\u2019experts du secteur qui d\u00e9veloppe et construit un v\u00e9hicule \u00e9lectrique tourn\u00e9 vers l\u2019avenir, dot\u00e9 de cellules solaires int\u00e9gr\u00e9es et utilisables au quotidien. L\u2019ensemble des \u00e9missions de CO\u2082 r\u00e9sultant de la production et de la fabrication du v\u00e9hicule seront compens\u00e9es. Soutenus par des investisseurs renomm\u00e9s et par un financement participatif, les premiers prototypes ont \u00e9t\u00e9 produits en 2017 et test\u00e9s sur route par plus de 8000 conducteurs dans le cadre des tourn\u00e9es organis\u00e9es par la marque. Les r\u00e9actions tr\u00e8s positives sur le v\u00e9hicule et le concept de mobilit\u00e9 associ\u00e9 confortent la vision des fondateurs, qui deviendra r\u00e9alit\u00e9 en 2019, lors de la mise en production de la voiture \u00e9lectrique Sion.\u00a0<a href=\"http:\/\/www.sonomotors.com\/\" target=\"_blank\" rel=\"noopener\">www.sonomotors.com<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Paris, le 13 juin 2018.\u00a0Automotive Solutions Germany (ASG), filiale d\u2019Expleo sp\u00e9cialiste des solutions d\u2019\u00e9clairage pour l\u2019automobile,va accompagner Sono Motors dans le d\u00e9veloppement du syst\u00e8me d\u2019\u00e9clairage ext\u00e9rieur de la Sion, premier v\u00e9hicule \u00e9lectrique de s\u00e9rie capable de recharger ses batteries gr\u00e2ce \u00e0 des panneaux solaires. ASG-Expleo doit concevoir et pr\u00e9parer la production en s\u00e9rie de l\u2019\u00e9clairage [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":0,"template":"","meta":{"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","footnotes":""},"topic":[121,122],"insights-single-templates":[492],"industry-taxonomy":[24],"content-type":[20],"country":[92],"service":[186,29],"class_list":["post-637","insights","type-insights","status-publish","hentry","topic-innovation-conception","topic-innovation-and-r-and-d","insights-single-templates-old-template","industry-taxonomy-automobile","content-type-actualite","country-germany","service-gestion-de-linnovation-and-solutions","service-laboratoire-dinnovations"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sono Motors choisit Expleo pour son concept d\u2019\u00e9clairage<\/title>\n<meta name=\"description\" content=\"Automotive Solutions Germany (ASG), filiale d\u2019Expleo accompagne Sono Motors pour d\u00e9velopper le syst\u00e8me d\u2019\u00e9clairage ext\u00e9rieur de la Sion.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sono Motors choisit Expleo pour d\u00e9velopper un concept d\u2019\u00e9clairage original pour sa voiture \u00e9lectrique solaire Sion\" \/>\n<meta property=\"og:description\" content=\"Automotive Solutions Germany (ASG), filiale d\u2019Expleo accompagne Sono Motors pour d\u00e9velopper le syst\u00e8me d\u2019\u00e9clairage ext\u00e9rieur de la Sion.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\/\" \/>\n<meta property=\"og:site_name\" content=\"Global FR\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-06T10:50:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2018\/06\/sono-motors-800x450-1-768x432.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\\\/\",\"name\":\"Sono Motors choisit Expleo pour son concept d\u2019\u00e9clairage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/sono-motors-800x450-1-768x432.jpeg\",\"datePublished\":\"2018-06-13T03:29:00+00:00\",\"dateModified\":\"2025-02-06T10:50:33+00:00\",\"description\":\"Automotive Solutions Germany (ASG), filiale d\u2019Expleo accompagne Sono Motors pour d\u00e9velopper le syst\u00e8me d\u2019\u00e9clairage ext\u00e9rieur de la Sion.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/sono-motors-800x450-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/sono-motors-800x450-1.jpeg\",\"width\":800,\"height\":450,\"caption\":\"A black electric car with solar panels on its hood is parked near a marina with boats in the background under a partly cloudy sky.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perspectives\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sono Motors choisit Expleo pour d\u00e9velopper un concept d\u2019\u00e9clairage original pour sa voiture \u00e9lectrique solaire Sion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\",\"name\":\"Expleo | FR\",\"description\":\"Expleo\",\"publisher\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#organization\",\"name\":\"Expleo | FR\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"width\":1600,\"height\":774,\"caption\":\"Expleo | FR\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sono Motors choisit Expleo pour son concept d\u2019\u00e9clairage","description":"Automotive Solutions Germany (ASG), filiale d\u2019Expleo accompagne Sono Motors pour d\u00e9velopper le syst\u00e8me d\u2019\u00e9clairage ext\u00e9rieur de la Sion.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\/","og_locale":"fr_FR","og_type":"article","og_title":"Sono Motors choisit Expleo pour d\u00e9velopper un concept d\u2019\u00e9clairage original pour sa voiture \u00e9lectrique solaire Sion","og_description":"Automotive Solutions Germany (ASG), filiale d\u2019Expleo accompagne Sono Motors pour d\u00e9velopper le syst\u00e8me d\u2019\u00e9clairage ext\u00e9rieur de la Sion.","og_url":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\/","og_site_name":"Global FR","article_modified_time":"2025-02-06T10:50:33+00:00","og_image":[{"url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2018\/06\/sono-motors-800x450-1-768x432.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\/","url":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\/","name":"Sono Motors choisit Expleo pour son concept d\u2019\u00e9clairage","isPartOf":{"@id":"https:\/\/expleo.com\/global\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\/#primaryimage"},"image":{"@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\/#primaryimage"},"thumbnailUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2018\/06\/sono-motors-800x450-1-768x432.jpeg","datePublished":"2018-06-13T03:29:00+00:00","dateModified":"2025-02-06T10:50:33+00:00","description":"Automotive Solutions Germany (ASG), filiale d\u2019Expleo accompagne Sono Motors pour d\u00e9velopper le syst\u00e8me d\u2019\u00e9clairage ext\u00e9rieur de la Sion.","breadcrumb":{"@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\/#primaryimage","url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2018\/06\/sono-motors-800x450-1.jpeg","contentUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2018\/06\/sono-motors-800x450-1.jpeg","width":800,"height":450,"caption":"A black electric car with solar panels on its hood is parked near a marina with boats in the background under a partly cloudy sky."},{"@type":"BreadcrumbList","@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expleo.com\/global\/fr\/"},{"@type":"ListItem","position":2,"name":"Perspectives","item":"https:\/\/expleo.com\/global\/fr\/perspectives\/"},{"@type":"ListItem","position":3,"name":"Sono Motors choisit Expleo pour d\u00e9velopper un concept d\u2019\u00e9clairage original pour sa voiture \u00e9lectrique solaire Sion"}]},{"@type":"WebSite","@id":"https:\/\/expleo.com\/global\/fr\/#website","url":"https:\/\/expleo.com\/global\/fr\/","name":"Expleo | FR","description":"Expleo","publisher":{"@id":"https:\/\/expleo.com\/global\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expleo.com\/global\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/expleo.com\/global\/fr\/#organization","name":"Expleo | FR","url":"https:\/\/expleo.com\/global\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/expleo.com\/global\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","contentUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","width":1600,"height":774,"caption":"Expleo | FR"},"image":{"@id":"https:\/\/expleo.com\/global\/fr\/#\/schema\/logo\/image\/"}}]}},"hreflang":{"rendered":"<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/perspectives\/news\/sono-motors-chooses-expleo-as-partner-for-the-development-of-a-unique-lighting-concept-for-its-sion-electrical-solar-car\/\" hreflang=\"x-default\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/perspectives\/news\/sono-motors-chooses-expleo-as-partner-for-the-development-of-a-unique-lighting-concept-for-its-sion-electrical-solar-car\/\" hreflang=\"en\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\/\" hreflang=\"fr\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/de\/perspectives\/neuigkeiten\/zuschlag-fur-lichtsystem-des-sion-geht-an-expleo-tochter-asg\/\" hreflang=\"de\"\/>\n","structure":[{"blogId":4,"blogIsHidden":false,"postId":760,"url":"https:\/\/expleo.com\/global\/en\/perspectives\/news\/sono-motors-chooses-expleo-as-partner-for-the-development-of-a-unique-lighting-concept-for-its-sion-electrical-solar-car\/","language":"en","default":true},{"blogId":5,"blogIsHidden":false,"postId":637,"url":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/sono-motors-choisit-expleo-pour-developper-un-concept-declairage-original-pour-sa-voiture-electrique-solaire-sion\/","language":"fr","default":false},{"blogId":6,"blogIsHidden":false,"postId":636,"url":"https:\/\/expleo.com\/global\/de\/perspectives\/neuigkeiten\/zuschlag-fur-lichtsystem-des-sion-geht-an-expleo-tochter-asg\/","language":"de","default":false}]},"_links":{"self":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights\/637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/types\/insights"}],"author":[{"embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/users\/9"}],"version-history":[{"count":0,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights\/637\/revisions"}],"wp:attachment":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/media?parent=637"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/topic?post=637"},{"taxonomy":"insights-single-templates","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights-single-templates?post=637"},{"taxonomy":"industry-taxonomy","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/industry-taxonomy?post=637"},{"taxonomy":"content-type","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/content-type?post=637"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/country?post=637"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/service?post=637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}