{"id":698,"date":"2019-09-06T14:47:00","date_gmt":"2019-09-06T14:47:00","guid":{"rendered":"https:\/\/expleo.com\/?post_type=insight&#038;p=5858"},"modified":"2024-03-21T06:24:42","modified_gmt":"2024-03-21T06:24:42","slug":"expleo-nouveau-partenaire-de-sncf-mobilites","status":"publish","type":"insights","link":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nouveau-partenaire-de-sncf-mobilites\/","title":{"rendered":"Expleo, nouveau partenaire de SNCF Mobilit\u00e9s"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"698\" class=\"elementor elementor-698\" data-elementor-post-type=\"insights\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4fdf58b gg-article-content gg-standard-article-template gg-simple-text gg-container-small-ptb-72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fdf58b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0522d99 gg-tablet-view\" data-id=\"0522d99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cae92ff gg-font-v9 gg-class-for-iphone8    elementor-widget elementor-widget-text-editor\" data-id=\"cae92ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong data-rich-text-format-boundary=\"true\">Paris, 6 septembre 2019.\u00a0<\/strong>Expleo a remport\u00e9 un contrat de 4 ans avec le Groupe SNCF.<\/p><p>Le groupe Expleo est d\u00e9sormais r\u00e9f\u00e9renc\u00e9 notamment aupr\u00e8s de SNCF Mobilit\u00e9s pour la r\u00e9alisation de missions de type \u00e9tudes et conseils techniques dans les domaines \u00ab Cabinets g\u00e9n\u00e9ralistes et multi-domaines \u00bb et \u00ab Informatique et \u00e9lectronique embarqu\u00e9e \u00bb. Ce double r\u00e9f\u00e9rencement permet \u00e0 Expleo de r\u00e9pondre aux consultations des p\u00f4les d\u2019ing\u00e9nierie, directions du mat\u00e9riel, technicentres industriels et technicentres de maintenance de SNCF Mobilit\u00e9s, et ce, sur l\u2019ensemble des activit\u00e9s et m\u00e9tiers relatifs au mat\u00e9riel roulant : m\u00e9canique, conception, calcul, soutien logistique int\u00e9gr\u00e9, s\u00fbret\u00e9 de fonctionnement, management de la qualit\u00e9, \u00e9tudes de conception et modifications de la carte \u00e9lectronique, validation des bancs de tests, gestion d\u2019obsolescence ou encore \u00e9tudes logicielles.<\/p><p>Expleo \u00e9tait d\u00e9j\u00e0 partenaire depuis 2018 de SNCF R\u00e9seaux, \u00c9pic* en charge de la gestion, de l\u2019exploitation et du d\u00e9veloppement du r\u00e9seau ferr\u00e9.<\/p><p>Le\u00a0<a href=\"https:\/\/expleo.com\/global\/fr\/secteurs\/transport\/\">ferroviaire<\/a>\u00a0est l\u2019un des principaux secteurs d\u2019activit\u00e9 d\u2019Expleo. Fort de sa connaissance m\u00e9tier et de son expertise digitale, le groupe accompagne les grands acteurs industriels, constructeurs et op\u00e9rateurs, dans la conception et le d\u00e9veloppement de nouvelles solutions de mobilit\u00e9. Il s\u2019appuie sur un r\u00e9seau de p\u00f4les d\u2019expertise et d\u2019innovation ferroviaires r\u00e9partis sur l\u2019ensemble du territoire fran\u00e7ais.<\/p><p><strong>Philippe Arragain, Head of Transportation chez Expleo, d\u00e9clare :<br \/><\/strong><em>\u00ab Nous sommes tr\u00e8s heureux de renforcer nos liens avec le Groupe SNCF. Ce double r\u00e9f\u00e9rencement est l\u2019occasion pour nous de mettre notre savoir-faire m\u00e9tier au service de la r\u00e9alisation des grands projets port\u00e9s par SNCF Mobilit\u00e9s et de la dynamique de transformation du secteur ferroviaire. \u00bb\u00a0<\/em><\/p><p><strong>Jonathan Bourcet, Acheteur Expert Lead PI chez SNCF, pr\u00e9cise :<br \/><\/strong><em>\u00ab Face aux grands enjeux en mati\u00e8re de mobilit\u00e9 et aux nouvelles attentes de nos clients, il est essentiel pour notre Groupe de pouvoir compter sur des partenaires partageant notre ambition technologique. Nous nous r\u00e9jouissons donc des nouvelles perspectives de collaboration annonc\u00e9es par la signature de ce contrat entre la SNCF et le Groupe Expleo. \u00bb<\/em><\/p><p>*\u00c9tablissement Public \u00e0 caract\u00e8re Industriel et Commercial.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le groupe Expleo est d\u00e9sormais r\u00e9f\u00e9renc\u00e9 notamment aupr\u00e8s de SNCF Mobilit\u00e9s pour la r\u00e9alisation de missions de type \u00e9tudes et conseils techniques dans les domaines.<\/p>\n","protected":false},"author":9,"featured_media":1785,"parent":0,"template":"","meta":{"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","footnotes":""},"topic":[121],"insights-single-templates":[492],"industry-taxonomy":[40],"content-type":[20],"country":[91],"service":[],"class_list":["post-698","insights","type-insights","status-publish","has-post-thumbnail","hentry","topic-innovation-conception","insights-single-templates-old-template","industry-taxonomy-transport","content-type-actualite","country-france"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Expleo, nouveau partenaire de SNCF Mobilit\u00e9s<\/title>\n<meta name=\"description\" content=\"Expleo est d\u00e9sormais r\u00e9f\u00e9renc\u00e9 notamment aupr\u00e8s de SNCF Mobilit\u00e9s pour la r\u00e9alisation de missions de type \u00e9tudes et conseils techniques.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nouveau-partenaire-de-sncf-mobilites\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expleo, nouveau partenaire de SNCF Mobilit\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Expleo est d\u00e9sormais r\u00e9f\u00e9renc\u00e9 notamment aupr\u00e8s de SNCF Mobilit\u00e9s pour la r\u00e9alisation de missions de type \u00e9tudes et conseils techniques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nouveau-partenaire-de-sncf-mobilites\/\" \/>\n<meta property=\"og:site_name\" content=\"Global FR\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-21T06:24:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/09\/train-02-480x270-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/expleo-nouveau-partenaire-de-sncf-mobilites\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/expleo-nouveau-partenaire-de-sncf-mobilites\\\/\",\"name\":\"Expleo, nouveau partenaire de SNCF Mobilit\u00e9s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/expleo-nouveau-partenaire-de-sncf-mobilites\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/expleo-nouveau-partenaire-de-sncf-mobilites\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/train-02-480x270-1.jpg\",\"datePublished\":\"2019-09-06T14:47:00+00:00\",\"dateModified\":\"2024-03-21T06:24:42+00:00\",\"description\":\"Expleo est d\u00e9sormais r\u00e9f\u00e9renc\u00e9 notamment aupr\u00e8s de SNCF Mobilit\u00e9s pour la r\u00e9alisation de missions de type \u00e9tudes et conseils techniques.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/expleo-nouveau-partenaire-de-sncf-mobilites\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/expleo-nouveau-partenaire-de-sncf-mobilites\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/expleo-nouveau-partenaire-de-sncf-mobilites\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/train-02-480x270-1.jpg\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/train-02-480x270-1.jpg\",\"width\":480,\"height\":270,\"caption\":\"Train at the station\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/expleo-nouveau-partenaire-de-sncf-mobilites\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perspectives\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Expleo, nouveau partenaire de SNCF Mobilit\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\",\"name\":\"Expleo | FR\",\"description\":\"Expleo\",\"publisher\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#organization\",\"name\":\"Expleo | FR\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"width\":1600,\"height\":774,\"caption\":\"Expleo | FR\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Expleo, nouveau partenaire de SNCF Mobilit\u00e9s","description":"Expleo est d\u00e9sormais r\u00e9f\u00e9renc\u00e9 notamment aupr\u00e8s de SNCF Mobilit\u00e9s pour la r\u00e9alisation de missions de type \u00e9tudes et conseils techniques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nouveau-partenaire-de-sncf-mobilites\/","og_locale":"fr_FR","og_type":"article","og_title":"Expleo, nouveau partenaire de SNCF Mobilit\u00e9s","og_description":"Expleo est d\u00e9sormais r\u00e9f\u00e9renc\u00e9 notamment aupr\u00e8s de SNCF Mobilit\u00e9s pour la r\u00e9alisation de missions de type \u00e9tudes et conseils techniques.","og_url":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nouveau-partenaire-de-sncf-mobilites\/","og_site_name":"Global FR","article_modified_time":"2024-03-21T06:24:42+00:00","og_image":[{"width":480,"height":270,"url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/09\/train-02-480x270-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nouveau-partenaire-de-sncf-mobilites\/","url":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nouveau-partenaire-de-sncf-mobilites\/","name":"Expleo, nouveau partenaire de SNCF Mobilit\u00e9s","isPartOf":{"@id":"https:\/\/expleo.com\/global\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nouveau-partenaire-de-sncf-mobilites\/#primaryimage"},"image":{"@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nouveau-partenaire-de-sncf-mobilites\/#primaryimage"},"thumbnailUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/09\/train-02-480x270-1.jpg","datePublished":"2019-09-06T14:47:00+00:00","dateModified":"2024-03-21T06:24:42+00:00","description":"Expleo est d\u00e9sormais r\u00e9f\u00e9renc\u00e9 notamment aupr\u00e8s de SNCF Mobilit\u00e9s pour la r\u00e9alisation de missions de type \u00e9tudes et conseils techniques.","breadcrumb":{"@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nouveau-partenaire-de-sncf-mobilites\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nouveau-partenaire-de-sncf-mobilites\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nouveau-partenaire-de-sncf-mobilites\/#primaryimage","url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/09\/train-02-480x270-1.jpg","contentUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/09\/train-02-480x270-1.jpg","width":480,"height":270,"caption":"Train at the station"},{"@type":"BreadcrumbList","@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nouveau-partenaire-de-sncf-mobilites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expleo.com\/global\/fr\/"},{"@type":"ListItem","position":2,"name":"Perspectives","item":"https:\/\/expleo.com\/global\/fr\/perspectives\/"},{"@type":"ListItem","position":3,"name":"Expleo, nouveau partenaire de SNCF Mobilit\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/expleo.com\/global\/fr\/#website","url":"https:\/\/expleo.com\/global\/fr\/","name":"Expleo | FR","description":"Expleo","publisher":{"@id":"https:\/\/expleo.com\/global\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expleo.com\/global\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/expleo.com\/global\/fr\/#organization","name":"Expleo | FR","url":"https:\/\/expleo.com\/global\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/expleo.com\/global\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","contentUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","width":1600,"height":774,"caption":"Expleo | FR"},"image":{"@id":"https:\/\/expleo.com\/global\/fr\/#\/schema\/logo\/image\/"}}]}},"hreflang":{"rendered":"<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/perspectives\/news\/expleo-a-new-partner-of-sncf-mobilites\/\" hreflang=\"x-default\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/perspectives\/news\/expleo-a-new-partner-of-sncf-mobilites\/\" hreflang=\"en\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nouveau-partenaire-de-sncf-mobilites\/\" hreflang=\"fr\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/de\/perspectives\/neuigkeiten\/expleo-ist-neuer-partner-von-sncf-mobilites\/\" hreflang=\"de\"\/>\n","structure":[{"blogId":4,"blogIsHidden":false,"postId":796,"url":"https:\/\/expleo.com\/global\/en\/perspectives\/news\/expleo-a-new-partner-of-sncf-mobilites\/","language":"en","default":true},{"blogId":5,"blogIsHidden":false,"postId":698,"url":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nouveau-partenaire-de-sncf-mobilites\/","language":"fr","default":false},{"blogId":6,"blogIsHidden":false,"postId":683,"url":"https:\/\/expleo.com\/global\/de\/perspectives\/neuigkeiten\/expleo-ist-neuer-partner-von-sncf-mobilites\/","language":"de","default":false}]},"_links":{"self":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights\/698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/types\/insights"}],"author":[{"embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/users\/9"}],"version-history":[{"count":0,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights\/698\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/media\/1785"}],"wp:attachment":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/media?parent=698"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/topic?post=698"},{"taxonomy":"insights-single-templates","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights-single-templates?post=698"},{"taxonomy":"industry-taxonomy","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/industry-taxonomy?post=698"},{"taxonomy":"content-type","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/content-type?post=698"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/country?post=698"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/service?post=698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}