{"id":823,"date":"2019-02-06T11:08:00","date_gmt":"2019-02-06T11:08:00","guid":{"rendered":"https:\/\/expleo.com\/insights\/uncategorized\/assystem-technologies-becomes-expleo-a-new-breed-of-technology-partner-2\/"},"modified":"2024-03-18T11:43:15","modified_gmt":"2024-03-18T11:43:15","slug":"assystem-technologies-devient-expleo","status":"publish","type":"insights","link":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/assystem-technologies-devient-expleo\/","title":{"rendered":"Assystem Technologies devient Expleo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"823\" class=\"elementor elementor-823\" data-elementor-post-type=\"insights\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4fdf58b gg-article-content gg-standard-article-template gg-simple-text gg-container-small-ptb-72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fdf58b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0522d99 gg-tablet-view\" data-id=\"0522d99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cae92ff gg-font-v9 gg-class-for-iphone8    elementor-widget elementor-widget-text-editor\" data-id=\"cae92ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Paris, 6 f\u00e9vrier 2019. Le groupe Assystem Technologies et ses filiales annoncent le lancement de leur nouvelle marque. 18 mois apr\u00e8s avoir repris les op\u00e9rations de la division\u00a0Global Product Solutions\u00a0d\u2019Assystem SA et suite \u00e0 une s\u00e9rie d\u2019acquisitions r\u00e9alis\u00e9es en 2018, dont celle de SQS, acteur de r\u00e9f\u00e9rence de la transformation digitale et de l\u2019assurance qualit\u00e9, Assystem Technologies devient Expleo.<\/strong><\/p><p>Dans un contexte d\u2019acc\u00e9l\u00e9ration technologique, Expleo accompagne ses clients, sur l\u2019ensemble de la cha\u00eene de valeur\u00a0: du conseil et de la\u00a0<em>business agility<\/em>\u00a0\u00e0 la conception, la production et les services post d\u00e9veloppement, jusqu\u2019au management de la qualit\u00e9. Ce portefeuille de services unique, associ\u00e9 \u00e0 une forte expertise sectorielle, refl\u00e8te l\u2019\u00e9volution des besoins du march\u00e9 dans lequel l\u2019ing\u00e9nierie et le software sont de plus en plus imbriqu\u00e9s.<\/p><p><strong>Gagner la course \u00e0 la technologie<\/strong><\/p><p>Les nouvelles technologies transforment les mod\u00e8les \u00e9conomiques, dans tous les secteurs et partout dans le monde. Sources d\u2019incertitudes comme d\u2019opportunit\u00e9s, elles sont plus que jamais au c\u0153ur de la strat\u00e9gie de toutes les entreprises.<\/p><p><strong>Olivier Aldrin, CEO d\u2019Expleo, pr\u00e9cise:<\/strong>\u00a0<em>\u201cAujourd\u2019hui, les entreprises sont toutes engag\u00e9es dans une course \u00e0 la technologie. Elles doivent transformer leur mod\u00e8le op\u00e9rationnel en s\u00e9curisant \u00e0 la fois l\u2019acc\u00e8s aux technologies de pointe et aux savoir-faire industriels.Pour aider nos clients \u00e0 l\u2019emporter, nous leur proposons une offre unique de services int\u00e9gr\u00e9s d\u2019ing\u00e9nierie, qualit\u00e9 et conseil strat\u00e9gique pour la transformation digitale. Ce positionnement audacieux est celui d\u2019un partenaire technologique d\u2019un nouveau genre. C\u2019est celui d\u2019Expleo. Notre nouvelle identit\u00e9 refl\u00e8te notre ambition d\u2019\u00eatre le partenaire de confiance dont nos clients ont besoin pour d\u00e9velopper rapidement et avec succ\u00e8s des innovations \u00e0 grande \u00e9chelle. \u201d<\/em><\/p><p><strong>Des perspectives de croissance ambitieuses<\/strong><\/p><p>Expleo compte 15 000 collaborateurs dans plus de 25 pays. Associant flexibilit\u00e9 et comp\u00e9titivit\u00e9, son organisation op\u00e9rationnelle conjugue ancrage local et acc\u00e8s \u00e0 des centres d\u2019excellence internationaux\u00a0bestshore.<\/p><p>L\u2019ambition d\u2019Expleo est de poursuivre sa croissance de mani\u00e8re organique et par acquisitions. Le Groupe pr\u00e9voit de renforcer sa pr\u00e9sence g\u00e9ographique, notamment en Allemagne, en Am\u00e9rique du Nord et en Inde. En Inde, Expleo vise \u00e0 doubler rapidement de taille pour atteindre plus de 5\u00a0000 collaborateurs.<\/p><p><strong>Une nouvelle marque fond\u00e9e sur un \u00e9quilibre entre audace et fiabilit\u00e9<\/strong><\/p><p>Alors que le Groupe ouvre un nouveau chapitre de son histoire, le nom Expleo sugg\u00e8re l\u2019exploration de nouvelles opportunit\u00e9s et de nouveaux horizons. Il illustre une vision \u00e0 la fois audacieuse et confiante de l\u2019avenir, ainsi qu\u2019une volont\u00e9 d\u2019innover. En latin, Expleo signifie litt\u00e9ralement \u00ab\u00a0compl\u00e9ter\u00a0\u00bb et \u00ab\u00a0satisfaire\u00a0\u00bb, faisant aussi bien r\u00e9f\u00e9rence au travail bien fait qu\u2019\u00e0 une promesse tenue.<\/p><p>Les entreprises ont aujourd\u2019hui besoin d\u2019expertise et de cr\u00e9ativit\u00e9 pour prendre, en confiance, des risques mesur\u00e9s. Elles doivent s\u2019entourer de partenaires fiables et responsables. Les collaborateurs d\u2019Expleo rel\u00e8vent ce d\u00e9fi en combinant intuition et rigueur, en r\u00e9conciliant ing\u00e9niosit\u00e9 et vigilance. Un \u00e9quilibre essentiel refl\u00e9t\u00e9 par le nouveau nom du Groupe, mais aussi par son slogan \u00ab\u00a0<em>Think bold, act reliable<\/em>\u00a0\u00bb.<\/p><p>Le motif graphique du nouveau logo, baptis\u00e9 \u00ab\u00a0<em>the Lens<\/em>\u00a0\u00bb (la lentille), symbolise la contribution et la vision des collaborateurs du groupe, int\u00e9gr\u00e9s aux \u00e9quipes de ses clients.<\/p><p><a href=\"https:\/\/expleo.com\/global\/en\/wp-content\/uploads\/2021\/10\/expleo_presskit_en.pdf\" target=\"_blank\" rel=\"noopener\">T\u00e9l\u00e9chargez le dossier presse ici<\/a><\/p><p><strong>Contacts\u00a0media<\/strong><\/p><p><strong>Expleo<\/strong><br \/>Cl\u00e9mence Choutet<br \/>press@expleogroup.com<br \/>+33 (0) 6 71 15 99 61<\/p><p><strong>Brunswick Group<\/strong><br \/>Julien Trosdorf<br \/>jtrosdorf@brunswickgroup.com<br \/>+33 (0) 1 53 96 83 83<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le groupe Assystem Technologies et ses filiales annoncent le lancement de leur nouvelle marque. 18 mois apr\u00e8s avoir repris les op\u00e9rations de la division Global Product Solutions d\u2019Assystem SA et suite \u00e0 une s\u00e9rie d\u2019acquisitions r\u00e9alis\u00e9es en 2018.<\/p>\n","protected":false},"author":67,"featured_media":15032,"parent":0,"template":"","meta":{"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","footnotes":""},"topic":[119],"insights-single-templates":[492],"industry-taxonomy":[373],"content-type":[20],"country":[116],"service":[],"class_list":["post-823","insights","type-insights","status-publish","has-post-thumbnail","hentry","topic-people-and-leadership","insights-single-templates-old-template","industry-taxonomy-all","content-type-actualite","country-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Expleo | Assystem Technologies devient Expleo<\/title>\n<meta name=\"description\" content=\"Le groupe Assystem Technologies et ses filiales annoncent le lancement de leur nouvelle marque. 18 mois apr\u00e8s avoir repris les\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/assystem-technologies-devient-expleo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assystem Technologies devient Expleo\" \/>\n<meta property=\"og:description\" content=\"Le groupe Assystem Technologies et ses filiales annoncent le lancement de leur nouvelle marque. 18 mois apr\u00e8s avoir repris les\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/assystem-technologies-devient-expleo\/\" \/>\n<meta property=\"og:site_name\" content=\"Global FR\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-18T11:43:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"774\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/assystem-technologies-devient-expleo\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/assystem-technologies-devient-expleo\\\/\",\"name\":\"Expleo | Assystem Technologies devient Expleo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/assystem-technologies-devient-expleo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/assystem-technologies-devient-expleo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"datePublished\":\"2019-02-06T11:08:00+00:00\",\"dateModified\":\"2024-03-18T11:43:15+00:00\",\"description\":\"Le groupe Assystem Technologies et ses filiales annoncent le lancement de leur nouvelle marque. 18 mois apr\u00e8s avoir repris les\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/assystem-technologies-devient-expleo\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/assystem-technologies-devient-expleo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/assystem-technologies-devient-expleo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"width\":1600,\"height\":774,\"caption\":\"Expleo logo and tagline\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/assystem-technologies-devient-expleo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perspectives\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Assystem Technologies devient Expleo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\",\"name\":\"Expleo | FR\",\"description\":\"Expleo\",\"publisher\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#organization\",\"name\":\"Expleo | FR\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"width\":1600,\"height\":774,\"caption\":\"Expleo | FR\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Expleo | Assystem Technologies devient Expleo","description":"Le groupe Assystem Technologies et ses filiales annoncent le lancement de leur nouvelle marque. 18 mois apr\u00e8s avoir repris les","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/assystem-technologies-devient-expleo\/","og_locale":"fr_FR","og_type":"article","og_title":"Assystem Technologies devient Expleo","og_description":"Le groupe Assystem Technologies et ses filiales annoncent le lancement de leur nouvelle marque. 18 mois apr\u00e8s avoir repris les","og_url":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/assystem-technologies-devient-expleo\/","og_site_name":"Global FR","article_modified_time":"2024-03-18T11:43:15+00:00","og_image":[{"width":1600,"height":774,"url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/assystem-technologies-devient-expleo\/","url":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/assystem-technologies-devient-expleo\/","name":"Expleo | Assystem Technologies devient Expleo","isPartOf":{"@id":"https:\/\/expleo.com\/global\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/assystem-technologies-devient-expleo\/#primaryimage"},"image":{"@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/assystem-technologies-devient-expleo\/#primaryimage"},"thumbnailUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","datePublished":"2019-02-06T11:08:00+00:00","dateModified":"2024-03-18T11:43:15+00:00","description":"Le groupe Assystem Technologies et ses filiales annoncent le lancement de leur nouvelle marque. 18 mois apr\u00e8s avoir repris les","breadcrumb":{"@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/assystem-technologies-devient-expleo\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/assystem-technologies-devient-expleo\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/assystem-technologies-devient-expleo\/#primaryimage","url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","contentUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","width":1600,"height":774,"caption":"Expleo logo and tagline"},{"@type":"BreadcrumbList","@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/assystem-technologies-devient-expleo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expleo.com\/global\/fr\/"},{"@type":"ListItem","position":2,"name":"Perspectives","item":"https:\/\/expleo.com\/global\/fr\/perspectives\/"},{"@type":"ListItem","position":3,"name":"Assystem Technologies devient Expleo"}]},{"@type":"WebSite","@id":"https:\/\/expleo.com\/global\/fr\/#website","url":"https:\/\/expleo.com\/global\/fr\/","name":"Expleo | FR","description":"Expleo","publisher":{"@id":"https:\/\/expleo.com\/global\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expleo.com\/global\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/expleo.com\/global\/fr\/#organization","name":"Expleo | FR","url":"https:\/\/expleo.com\/global\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/expleo.com\/global\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","contentUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","width":1600,"height":774,"caption":"Expleo | FR"},"image":{"@id":"https:\/\/expleo.com\/global\/fr\/#\/schema\/logo\/image\/"}}]}},"hreflang":{"rendered":"<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/perspectives\/news\/assystem-technologies-becomes-expleo-a-new-breed-of-technology-partner\/\" hreflang=\"x-default\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/perspectives\/news\/assystem-technologies-becomes-expleo-a-new-breed-of-technology-partner\/\" hreflang=\"en\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/assystem-technologies-devient-expleo\/\" hreflang=\"fr\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/de\/perspectives\/neuigkeiten\/assystem-technologies-wird-expleo-ein-technologiepartner-der-neuen-generation-fur-innovative-unternehmen\/\" hreflang=\"de\"\/>\n","structure":[{"blogId":4,"blogIsHidden":false,"postId":899,"url":"https:\/\/expleo.com\/global\/en\/perspectives\/news\/assystem-technologies-becomes-expleo-a-new-breed-of-technology-partner\/","language":"en","default":true},{"blogId":5,"blogIsHidden":false,"postId":823,"url":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/assystem-technologies-devient-expleo\/","language":"fr","default":false},{"blogId":6,"blogIsHidden":false,"postId":805,"url":"https:\/\/expleo.com\/global\/de\/perspectives\/neuigkeiten\/assystem-technologies-wird-expleo-ein-technologiepartner-der-neuen-generation-fur-innovative-unternehmen\/","language":"de","default":false}]},"_links":{"self":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights\/823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/types\/insights"}],"author":[{"embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/users\/67"}],"version-history":[{"count":0,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights\/823\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/media\/15032"}],"wp:attachment":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/media?parent=823"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/topic?post=823"},{"taxonomy":"insights-single-templates","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights-single-templates?post=823"},{"taxonomy":"industry-taxonomy","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/industry-taxonomy?post=823"},{"taxonomy":"content-type","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/content-type?post=823"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/country?post=823"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/service?post=823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}