{"id":834,"date":"2019-02-15T05:56:00","date_gmt":"2019-02-15T05:56:00","guid":{"rendered":"https:\/\/expleo.com\/insights\/uncategorized\/expleo-named-airbus-airframe-wing-engineering-supplier-of-the-year-2\/"},"modified":"2024-02-02T16:57:21","modified_gmt":"2024-02-02T16:57:21","slug":"expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering","status":"publish","type":"insights","link":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\/","title":{"rendered":"Expleo nomm\u00e9 \u00ab\u00a0Fournisseur de l\u2019ann\u00e9e\u00a0\u00bb par Airbus Airframe Wing Engineering"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"834\" class=\"elementor elementor-834\" data-elementor-post-type=\"insights\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4fdf58b gg-article-content gg-standard-article-template gg-simple-text gg-container-small-ptb-72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fdf58b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0522d99 gg-tablet-view\" data-id=\"0522d99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cae92ff gg-font-v9 gg-class-for-iphone8    elementor-widget elementor-widget-text-editor\" data-id=\"cae92ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Londres,\u00a015 f\u00e9vrier 2019. Expleo, ex-Assystem Technologies, a \u00e9t\u00e9 distingu\u00e9 par Airbus S\u00e9ries Wing Engineering (ESW) pour sa participation \u00e0 la r\u00e9alisation des ailes des appareils A380, A350 et Single Aisle (A320\/A321). Le prix de \u00ab\u00a0Fournisseur de l\u2019ann\u00e9e 2018\u00a0\u00bb d\u00e9cern\u00e9 par ESW Airframe Wing Engineering r\u00e9compense un fournisseur assurant le plus haut niveau de qualit\u00e9, d\u2019agilit\u00e9, de proactivit\u00e9 et de performances pour Airbus ESW parmi tous les grands sous-traitants.<\/strong><\/p>\n<p>Le 6 d\u00e9cembre 2018, Airbus ESW a tenu sa conf\u00e9rence annuelle avec les fournisseurs \u00e0 Bristol, r\u00e9union o\u00f9 la soci\u00e9t\u00e9 a fait conna\u00eetre sa vision et ses attentes pour l\u2019avenir. Elle a aussi r\u00e9compens\u00e9 un fournisseur pour sa participation \u00e0 l\u2019activit\u00e9 d\u2019ESW en lui remettant le prix de \u00ab\u00a0Fournisseur de l\u2019ann\u00e9e\u00a0\u00bb.<\/p>\n<p>Le prix \u00ab\u00a0Fournisseur de l\u2019ann\u00e9e 2018\u00a0\u00bb a \u00e9t\u00e9 remis \u00e0 Jonathan Taylor (Operations Director \u2013 Expleo Engineering UK) et Daniel Thorpe (Key Account Manager Aerospace \u2013 Expleo Engineering UK) par Timothy Pegler (Vice-Pr\u00e9sident Airframe Wing Engineering).<\/p>\n<p>Enchant\u00e9 de se voir remettre ce prix pour la seconde ann\u00e9e d\u2019affil\u00e9e par ESW, Jonathan Taylor a d\u00e9clar\u00e9 : \u00ab\u00a0Cet excellent r\u00e9sultat est \u00e0 mettre au cr\u00e9dit de toutes nos \u00e9quipes qui travaillent pour Airbus\u00a0; merci \u00e0 eux d\u2019avoir rendu cela possible\u00a0!\u00a0\u00bb<\/p>\n<p>Ce prix, qui refl\u00e8te les capacit\u00e9s d\u2019Expleo dans la technologie des ailes, t\u00e9moigne aussi de ses relations avec Airbus Airframe Wing Engineering, au Royaume-Uni et en Europe. Notre r\u00e9ussite repose sur notre engagement constant \u00e0 fournir des solutions \u00e9prouv\u00e9es, rentables et en temps utile, en les associant \u00e0 une d\u00e9marche proactive pour trouver les meilleurs moyens de progresser en permanence.<\/p>\n<p>Les travaux pour Airbus ESW ont concern\u00e9 la conception m\u00e9canique, depuis la cr\u00e9ation jusqu\u2019\u00e0 la certification des structures primaires et secondaires. Ils concernent l\u2019analyse statique et de fatigue, la conception et l\u2019installation des syst\u00e8mes, les projets d\u2019am\u00e9lioration continue, la conception de l\u2019outillage, le soutien en R&amp;D et l\u2019ing\u00e9nierie de fabrication. Les ann\u00e9es pr\u00e9c\u00e9dentes, Expleo avait aussi re\u00e7u les prix de l\u2019Innovation et de la Qualit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Expleo, ex-Assystem Technologies, a \u00e9t\u00e9 distingu\u00e9 par Airbus S\u00e9ries Wing Engineering (ESW) pour sa participation \u00e0 la r\u00e9alisation des ailes des appareils A380, A350 et Single Aisle (A320\/A321).<\/p>\n","protected":false},"author":9,"featured_media":1762,"parent":0,"template":"","meta":{"_oasis_is_in_workflow":0,"_oasis_original":0,"_oasis_task_priority":"","footnotes":""},"topic":[121],"insights-single-templates":[492],"industry-taxonomy":[],"content-type":[20],"country":[105],"service":[189,58],"class_list":["post-834","insights","type-insights","status-publish","has-post-thumbnail","hentry","topic-innovation-conception","insights-single-templates-old-template","content-type-actualite","country-royaume-uni","service-ingenierie-produits-and-procedes","service-conception-de-produit-et-ingenierie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Expleo, \u00ab\u00a0Fournisseur de l\u2019ann\u00e9e\u00a0\u00bb par Airbus<\/title>\n<meta name=\"description\" content=\"Expleo, ex-Assystem Technologies, a \u00e9t\u00e9 distingu\u00e9 par Airbus S\u00e9ries Wing Engineering pour la r\u00e9alisation des ailes des appareils, dont l&#039;A380.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expleo nomm\u00e9 \u00ab\u00a0Fournisseur de l\u2019ann\u00e9e\u00a0\u00bb par Airbus Airframe Wing Engineering\" \/>\n<meta property=\"og:description\" content=\"Expleo, ex-Assystem Technologies, a \u00e9t\u00e9 distingu\u00e9 par Airbus S\u00e9ries Wing Engineering pour la r\u00e9alisation des ailes des appareils, dont l&#039;A380.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\/\" \/>\n<meta property=\"og:site_name\" content=\"Global FR\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-02T16:57:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2020\/12\/turbine-blade-480x270-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\\\/\",\"name\":\"Expleo, \u00ab\u00a0Fournisseur de l\u2019ann\u00e9e\u00a0\u00bb par Airbus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/turbine-blade-480x270-1.jpg\",\"datePublished\":\"2019-02-15T05:56:00+00:00\",\"dateModified\":\"2024-02-02T16:57:21+00:00\",\"description\":\"Expleo, ex-Assystem Technologies, a \u00e9t\u00e9 distingu\u00e9 par Airbus S\u00e9ries Wing Engineering pour la r\u00e9alisation des ailes des appareils, dont l'A380.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/turbine-blade-480x270-1.jpg\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/turbine-blade-480x270-1.jpg\",\"width\":480,\"height\":270,\"caption\":\"Turbine blade, retro vintage filter effect; Shutterstock ID 539461975; Bon de commande: -\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/actualite\\\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perspectives\",\"item\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/perspectives\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Expleo nomm\u00e9 \u00ab\u00a0Fournisseur de l\u2019ann\u00e9e\u00a0\u00bb par Airbus Airframe Wing Engineering\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\",\"name\":\"Expleo | FR\",\"description\":\"Expleo\",\"publisher\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#organization\",\"name\":\"Expleo | FR\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"contentUrl\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/expleo-logo-and-tagline.png\",\"width\":1600,\"height\":774,\"caption\":\"Expleo | FR\"},\"image\":{\"@id\":\"https:\\\/\\\/expleo.com\\\/global\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Expleo, \u00ab\u00a0Fournisseur de l\u2019ann\u00e9e\u00a0\u00bb par Airbus","description":"Expleo, ex-Assystem Technologies, a \u00e9t\u00e9 distingu\u00e9 par Airbus S\u00e9ries Wing Engineering pour la r\u00e9alisation des ailes des appareils, dont l'A380.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\/","og_locale":"fr_FR","og_type":"article","og_title":"Expleo nomm\u00e9 \u00ab\u00a0Fournisseur de l\u2019ann\u00e9e\u00a0\u00bb par Airbus Airframe Wing Engineering","og_description":"Expleo, ex-Assystem Technologies, a \u00e9t\u00e9 distingu\u00e9 par Airbus S\u00e9ries Wing Engineering pour la r\u00e9alisation des ailes des appareils, dont l'A380.","og_url":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\/","og_site_name":"Global FR","article_modified_time":"2024-02-02T16:57:21+00:00","og_image":[{"width":480,"height":270,"url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2020\/12\/turbine-blade-480x270-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\/","url":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\/","name":"Expleo, \u00ab\u00a0Fournisseur de l\u2019ann\u00e9e\u00a0\u00bb par Airbus","isPartOf":{"@id":"https:\/\/expleo.com\/global\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\/#primaryimage"},"image":{"@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\/#primaryimage"},"thumbnailUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2020\/12\/turbine-blade-480x270-1.jpg","datePublished":"2019-02-15T05:56:00+00:00","dateModified":"2024-02-02T16:57:21+00:00","description":"Expleo, ex-Assystem Technologies, a \u00e9t\u00e9 distingu\u00e9 par Airbus S\u00e9ries Wing Engineering pour la r\u00e9alisation des ailes des appareils, dont l'A380.","breadcrumb":{"@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\/#primaryimage","url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2020\/12\/turbine-blade-480x270-1.jpg","contentUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2020\/12\/turbine-blade-480x270-1.jpg","width":480,"height":270,"caption":"Turbine blade, retro vintage filter effect; Shutterstock ID 539461975; Bon de commande: -"},{"@type":"BreadcrumbList","@id":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/expleo.com\/global\/fr\/"},{"@type":"ListItem","position":2,"name":"Perspectives","item":"https:\/\/expleo.com\/global\/fr\/perspectives\/"},{"@type":"ListItem","position":3,"name":"Expleo nomm\u00e9 \u00ab\u00a0Fournisseur de l\u2019ann\u00e9e\u00a0\u00bb par Airbus Airframe Wing Engineering"}]},{"@type":"WebSite","@id":"https:\/\/expleo.com\/global\/fr\/#website","url":"https:\/\/expleo.com\/global\/fr\/","name":"Expleo | FR","description":"Expleo","publisher":{"@id":"https:\/\/expleo.com\/global\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expleo.com\/global\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/expleo.com\/global\/fr\/#organization","name":"Expleo | FR","url":"https:\/\/expleo.com\/global\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/expleo.com\/global\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","contentUrl":"https:\/\/expleo.com\/global\/fr\/wp-content\/uploads\/2019\/02\/expleo-logo-and-tagline.png","width":1600,"height":774,"caption":"Expleo | FR"},"image":{"@id":"https:\/\/expleo.com\/global\/fr\/#\/schema\/logo\/image\/"}}]}},"hreflang":{"rendered":"<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/perspectives\/news\/expleo-named-airbus-airframe-wing-engineering-supplier-of-the-year\/\" hreflang=\"x-default\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/en\/perspectives\/news\/expleo-named-airbus-airframe-wing-engineering-supplier-of-the-year\/\" hreflang=\"en\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\/\" hreflang=\"fr\"\/>\n<link rel=\"alternate\" href=\"https:\/\/expleo.com\/global\/de\/perspectives\/neuigkeiten\/expleo-wird-von-airbus-airframe-wing-engineering-zum-zulieferer-des-jahres-ernannt\/\" hreflang=\"de\"\/>\n","structure":[{"blogId":4,"blogIsHidden":false,"postId":907,"url":"https:\/\/expleo.com\/global\/en\/perspectives\/news\/expleo-named-airbus-airframe-wing-engineering-supplier-of-the-year\/","language":"en","default":true},{"blogId":5,"blogIsHidden":false,"postId":834,"url":"https:\/\/expleo.com\/global\/fr\/perspectives\/actualite\/expleo-nomme-fournisseur-de-lannee-par-airbus-airframe-wing-engineering\/","language":"fr","default":false},{"blogId":6,"blogIsHidden":false,"postId":816,"url":"https:\/\/expleo.com\/global\/de\/perspectives\/neuigkeiten\/expleo-wird-von-airbus-airframe-wing-engineering-zum-zulieferer-des-jahres-ernannt\/","language":"de","default":false}]},"_links":{"self":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights\/834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights"}],"about":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/types\/insights"}],"author":[{"embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/users\/9"}],"version-history":[{"count":0,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights\/834\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/media\/1762"}],"wp:attachment":[{"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/media?parent=834"}],"wp:term":[{"taxonomy":"topic","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/topic?post=834"},{"taxonomy":"insights-single-templates","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/insights-single-templates?post=834"},{"taxonomy":"industry-taxonomy","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/industry-taxonomy?post=834"},{"taxonomy":"content-type","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/content-type?post=834"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/country?post=834"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/expleo.com\/global\/fr\/wp-json\/wp\/v2\/service?post=834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}